{"id":295302,"date":"2011-05-03T05:17:54","date_gmt":"2011-05-03T03:17:54","guid":{"rendered":"https:\/\/www.focolare.org\/juan-pablo-ii-en-el-centro-mariapolis-internacional\/"},"modified":"2024-05-13T20:52:27","modified_gmt":"2024-05-13T18:52:27","slug":"juan-pablo-ii-en-el-centro-mariapolis-internacional","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/es\/juan-pablo-ii-en-el-centro-mariapolis-internacional\/","title":{"rendered":"Juan Pablo II en el Centro Mari\u00e1polis internacional"},"content":{"rendered":"<p>Durante las distintas fases de nuestro encuentro he hecho muchas reflexiones. Intento ahora resumirlo todo en una constataci\u00f3n y en un deseo. La constataci\u00f3n ata\u00f1e al n\u00facleo central de vuestro Movimiento: el amor. Ciertamente el amor es el inicio de muchas instituciones y estructuras de todo el apostolado, de todas las familias religiosas. El amor es rico, lleva en s\u00ed distintas potencialidades y difunde en los corazones humanos los distintos carismas. Con este encuentro he podido acercarme un poco m\u00e1s a lo que forma el carisma propio de vuestro Movimiento o, por decirlo de otro modo, comprender mejor que el amor \u2013que es un don del Esp\u00edritu Santo, por \u00e9l difundido en nuestros corazones, su virtud m\u00e1s grande\u2013 constituye el camino m\u00e1s excelente, la animaci\u00f3n principal de vuestro Movimiento. Es bueno que hay\u00e1is encontrado tal camino, esa vocaci\u00f3n al amor.  Escuchando los testimonios, me he convencido a\u00fan mayormente de algo que desde hace muchos a\u00f1os y cada d\u00eda me doy cuenta: en el mundo de hoy, en la vida de las naciones, de las sociedades, de los distintos \u00e1mbitos, de las personas, el odio y la lucha son muy fuertes. Son program\u00e1ticos. Por eso se requiere el amor. Se puede decir que el amor no tiene programa, mas los crea hermos\u00edsimos y riqu\u00edsimos, como el vuestro. Se requiere la presencia del amor en el mundo para afrontar el gran peligro que acecha a la humanidad, que amenaza al hombre: el de encontrarse sin amor, con el odio, con la lucha, con varias guerras, con varias opresiones, con varias torturas, como hemos o\u00eddo. El amor es m\u00e1s fuerte que todo y \u00e9sta es vuestra fe, la chispa inspiradora de todo lo que se hace bajo el nombre Focolares, de todo lo que sois, de todo lo que hac\u00e9is en el mundo. El amor es m\u00e1s fuerte. Es una revoluci\u00f3n. En este mundo tan trabajado por las revoluciones, cuyos principios constitutivos son el odio y la lucha, se requiere la revoluci\u00f3n del amor; es necesario que tal revoluci\u00f3n demuestre ser m\u00e1s fuerte. Esto es tambi\u00e9n el radicalismo del amor. Ha habido en la historia de la Iglesia muchos radicalismo del amor, casi todos contenidos en el supremo radicalismo de Cristo Jes\u00fas. Hubo el radicalismo de san Francisco, el de San Ignacio de Loyola, el de Carlos de Foucauld y tantos otros hasta nuestros d\u00edas. Tambi\u00e9n hay un radicalismo del amor vuestro, de Chiara, de los focolarinos: un radicalismo que descubre la profundidad del amor y su simplicidad, todas las exigencias del amor en las distintas situaciones, y procura que siempre venza este amor en cualquier circunstancia, en cualquier dificultad; y donde el hombre \u2013humanamente hablando\u2013 podr\u00eda ser superado por el odio, no le permite tanto a este hombre, a este coraz\u00f3n humano, y hace que venza el amor.  Bien, pues \u00e9ste el radicalismo evang\u00e9lico del amor que vosotros procur\u00e1is llevar a la vida de los hombres de hoy, a los ambientes de hoy, por todo el mundo. Y con esta certeza de que el amor debe ser siempre m\u00e1s fuerte, en cualquier circunstancia, ante cualquier dificultad, dais un testimonio de Dios que es amor. Podemos decir que vuestra obra de evangelizaci\u00f3n comienza por el amor para llegar a Dios. Muchas veces se empieza por Dios para llegar, quiz\u00e1s, al amor. Vosotros hab\u00e9is acentuado esta f\u00f3rmula de san Juan: Dios es amor. Esto quiere decir que, cuando se vive el amor, cuando se realiza el amor, cuando se hace que el amor venza en cualquier circunstancia, entonces dejamos que se vea a Dios. Esto no es s\u00f3lo un programa abstracto, es un programa vivido. Est\u00e1 bien que atribuy\u00e1is mucha importancia a los testimonios, porque cada uno de estos testimonios conlleva la confirmaci\u00f3n de este programa. Est\u00e1 bien que el programa se escriba m\u00e1s en los testimonios, en las experiencias vividas, que en el papel o las teor\u00edas.  En todo esto he pensado durante mis visita a vuestro centro internacional, y os agradezco pro la oportunidad que me hab\u00e9is dado de vivir todo esto, de reflexionar, de ver lo que constituye la vida de vuestro gran Movimiento de m\u00e1s de un mill\u00f3n de personas en todo el mundo, y lo que constituye la experiencia de cada uno de vosotros: la revelaci\u00f3n de que Dios es amor, y adem\u00e1s una soluci\u00f3n personal para cada unos de vosotros. Esto hemos percibido profundamente en los testimonios. Si falta esta consciencia y esta experiencia, si falta esta gracia, hay un vac\u00edo. Y ah\u00ed, otra amenaza; aparte de la de la lucha y el odio, la de las varias guerras, la de la autodestrucci\u00f3n nuclear: el peligro del vac\u00edo en el coraz\u00f3n humano. Vosotros quer\u00e9is poner remedio directamente este vac\u00edo con vuestra experiencia personal, una experiencia vivida que luego se transmite a los dem\u00e1s.  Os deseo, pues, que sig\u00e1is por el mismo camino. Ya ten\u00e9is una orientaci\u00f3n bien clara, una caracter\u00edstica profundamente marcada, un carisma en la riqueza del amor, cuya fuente es Dios mismo, el Esp\u00edritu Santo. Hab\u00e9is hallado vuestro campo, vuestra morada. Os deseo Que desarroll\u00e9is cada vez m\u00e1s esta realidad, propia de vuestra vocaci\u00f3n, y que llev\u00e9is al mundo de hoy el amor, que tanta falta le hace, y que por medio del amor, llev\u00e9is a Dios. \u00c9ste es mi deseo.  Os encomiendo de modo especial a la Virgen sant\u00edsima, Madre de Cristo y de la Iglesia, Madre nuestra, de los ap\u00f3stoles, de todas las Mari\u00e1polis del mundo. Os encomiendo a ella, porque ella, m\u00e1s que todos los hombres, ha sabido vivir el amor, el radicalismo del amor, y de la manera m\u00e1s simple, maravillosa y absolutamente original. Vosotros est\u00e1is fascinados por la Virgen, por su santidad, por ese amor que late en su coraz\u00f3n, y quer\u00e9is imitarla. Os deseo que obteng\u00e1is esto cada vez m\u00e1s. Es m\u00e1s, os deseo que a trav\u00e9s de Mar\u00eda os acerqu\u00e9is a Jes\u00fas, el cual nos ha mostrado que Dios es amor, al Esp\u00edritu Santo, que es quien elabora el amor en nuestros corazones, gracias a la cruz y la resurrecci\u00f3n de Jes\u00fas. Os doy las gracias de nuevo por haberme recibido en vuestra casa, en vuestra familia. Quiero hacer extensivo estos deseos a todos los focolarinos del mundo, porque est\u00e1is muy unidos entre vosotros y procur\u00e1is formar una gran familia cristiana, evang\u00e9lica, en todo el mundo. Me encomiendo a esta familia. Y tengo que agradeceros por vuestro apostolado, porque estoy aqu\u00ed en cuanto sucesor de Pedro, preocupado por el apostolado de la Iglesia. Es m\u00e1s, estoy convencido, lo veo, lo experimento, cu\u00e1l es el aspecto del apostolado de la Iglesia contempor\u00e1nea propio de vosotros. Os deseo que se\u00e1is un fermento en la masa de la humanidad\u00a0 y del pueblo de Dios. Os deseo que se\u00e1is un fermento evang\u00e9lico en la Iglesia, que ha reconocido su dimensi\u00f3n con el Concilio Vaticano II en la constituci\u00f3n <em><a href=\"http:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19641121_lumen-gentium_it.html\">Lumen Gentium<\/a><\/em>, en la constituci\u00f3n pastoral <em><a href=\"http:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19651207_gaudium-et-spes_it.html\">Gaudium et Spes<\/a><\/em>. Veo que vosotros ten\u00e9is la intenci\u00f3n de seguir aut\u00e9nticamente esa visi\u00f3n de la Iglesia, esa autodefinici\u00f3n que la Iglesia ha dado de s\u00ed misma en el Concilio Vaticano II. Por eso veo vuestros contactos tan fruct\u00edferos en la dimensi\u00f3n ecum\u00e9nica, o con nuestros hermanos no cristianos, que poseen sus riquezas religiosas, tal y como he podido constatar, por ejemplo, durante una breve visita a Corea y a Tailandia, y luego los contactos con el mundo secularizado, con los no creyentes, con los ateos y los agn\u00f3sticos. Por todas partes est\u00e1 la Iglesia y, como dec\u00eda san Juan de la Cruz, donde no hay amor, lleva amor y encontrar\u00e1s amor. Pienso que esto se puede aplicar muy bien a vuestro apostolado en todos los \u00e1mbitos, no solamente en los de la Iglesia, en su cuerpo cat\u00f3lico, sino tambi\u00e9n en su dimensi\u00f3n ecum\u00e9nica y en los contactos de di\u00e1logo con los no cristianos y con los no creyentes. El amor abre el camino. Espero que, gracias a vosotros, este camino est\u00e9 cada vez m\u00e1s abierto para la Iglesia.  \u00a9 Copyright 1984 &#8211;\u00a0 Libreria Editrice Vaticana<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del Centro Chiara Lubich el video de la visita de Juan Pablo II al Centro Mari\u00e1polis de Rocca di Papa (Roma), el 19 de agosto de 1984. En ese d\u00eda inolvidable el Papa habla del \u2018radicalismo del amor\u2019 de Chiara, de los Focolares.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[46],"tags":[],"class_list":["post-295302","post","type-post","status-publish","format-standard","hentry","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/295302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/comments?post=295302"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/295302\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/media?parent=295302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/categories?post=295302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/tags?post=295302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}