{"id":309040,"date":"2017-10-20T00:10:07","date_gmt":"2017-10-19T22:10:07","guid":{"rendered":"https:\/\/www.focolare.org\/nadie-es-extranjero-para-mi\/"},"modified":"2024-05-15T20:45:25","modified_gmt":"2024-05-15T18:45:25","slug":"nadie-es-extranjero-para-mi","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/es\/nadie-es-extranjero-para-mi\/","title":{"rendered":"Nadie es extranjero para m\u00ed"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-157132\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2017\/10\/GenVerde_Germany_05.jpg\" alt=\"GenVerde_Germany_05\" width=\"368\" height=\"245\" \/><strong>Un mes bajo el signo del di\u00e1logo, del encuentro y del descubrimiento del valor del \u201cotro\u201d.<\/strong>  <strong>En un pa\u00eds con una fuerte connotaci\u00f3n multi\u00e9tnica,<\/strong> El ritmo y la m\u00fasica han tenido un poder coagulante. \u00a0El<strong> 9 de septiembre<\/strong>, en la peque\u00f1a ciudad de <strong><em>Stadthagen<\/em>,<\/strong> en la regi\u00f3n Baja de Sajonia, el <a href=\"http:\/\/www.genverde.it\/\"><strong>Gen Verde<\/strong><\/a> (sus 22 miembros, provenientes de 14 pa\u00edses) particip\u00f3 en los festejos del jubileo de la Reforma,\u00a0llevando una nota de internacionalidad con el espect\u00e1culo <strong><em>On the Other Side<\/em>. <\/strong>Un viaje de una parte a otra del planeta\u00a0a trav\u00e9s del relato de historias personales y de todo un pueblo, para poner en evidencia la riqueza de la diversidad y el potencial de cualquiera que \u00e9ste \u201cdel otro lado\u201d.  <strong>El 15 de septiembre,<\/strong> en <em>Boppard<\/em>, en la <em>Fazenda da Esperan\u00e7a <\/em>local, qu\u00e9 es una comunidad que desaf\u00eda la drogadicci\u00f3n desde la perspectiva de un renacimiento, tuvo lugar el concierto \u201cLA VIDA\u201d <strong><em>LIVE. <\/em><\/strong>Fue una ocasi\u00f3n de encuentro personal entre las componentes del conjunto y las experiencias de los j\u00f3venes. \u00a0Una oportunidad para comprender que cada uno puede hacer un peque\u00f1o pero grand\u00edsimo paso para cambiar algo y para descubrirnos todos hermanos.  <img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-157133\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2017\/10\/GenVerde_Stadthagen.jpg\" alt=\"GenVerde_Stadthagen\" width=\"368\" height=\"245\" \/><strong>En los d\u00edas sucesivos,<\/strong> se realiz\u00f3 el taller <em>Start Now <\/em>que se ha convertido en una caracter\u00edstica art\u00edstica t\u00edpica del Gen Verde. Fueron talleres intensos, de 5 d\u00edas de duraci\u00f3n en cada una de sus tres etapas, trabajando codo a codo con grupos de chicos y de j\u00f3venes.  <strong>Durante el proceso creativo,<\/strong> que se renueva cada vez en una forma diferente e imprevisible, los chicos trabajaron en equipo desarrollando sus propios talentos y potencialidades, siendo co-protagonistas de una fascinante experiencia creativa basada en la escucha rec\u00edproca y en la transparencia. Despu\u00e9s de dos d\u00edas de intenso trabajo, sostenidos por la confianza y el respeto del grupo, los chicos se presentaron junto con el conjunto durante el espect\u00e1culo final, en un <em>crescendo<\/em> de emociones.  <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-157134 alignright\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2017\/10\/GenVerde_Germany_04.jpg\" alt=\"GenVerde_Germany_04\" width=\"368\" height=\"245\" \/><strong>Tres etapas del taller-espect\u00e1culo: <\/strong>en <strong><em>Dortmund<\/em>, <\/strong>el grupo trabaj\u00f3 junto a 170 chicos, en <strong><em>Duderstadt<\/em>, <\/strong>se realiz\u00f3 con los estudiantes de tres escuelas, en las cuales hab\u00eda un numeroso grupo de inmigrantes, y finalmente en <strong><em>Mannheim<\/em>, <\/strong>los participantes eran hombres y mujeres de un enorme campo de refugiados.  En cada ciudad, durante el espect\u00e1culo final, se repiti\u00f3, con caracter\u00edsticas diferentes, el mismo milagro; cambio de vida, atm\u00f3sfera de profunda fraternidad, participaci\u00f3n incluso de qui\u00e9n al inicio estaba al margen. <em>\u201c\u00a1Es incre\u00edble lo que se puede hacer en s\u00f3lo dos d\u00edas!\u201d<\/em> exclam\u00f3, todav\u00eda incr\u00e9dula, una chica. \u00a0Y un joven: <em>\u201cLos errores no nos frenaron, por el contrario, est\u00e1bamos todav\u00eda m\u00e1s animados a seguir adelante\u201d.<\/em>  <strong>Especialmente en la \u00faltima etapa de Mannheim, <\/strong>el Gen Verde se encontr\u00f3 con personas que han atravesado dolores desgarradores, que sufrieron atrocidades, perdi\u00e9ndolo todo. \u00a0<strong>Cuentan los miembros del grupo:<\/strong> \u201c<em>Fuimos a visitarlos all\u00ed donde viven, nos donaron sus historias. Durante la velada, en la canci\u00f3n \u201cQui\u00e9n llora por ti\u201d, muchos encontraron fragmentos de las tragedias vividas\u201d. \u00a0Las palabras<\/em> \u201c<em>No one is a stranger to me<\/em>\u201d (\u201cNinguno es extranjero\u201d) nunca hab\u00edan resonado tan aut\u00e9nticas.  &nbsp;  <strong>Mira el video<\/strong>  https:\/\/vimeo.com\/236654355<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del 9 al 25 de septiembre era en Alemania del conjunto internacional Gen Verde. Un rico programa de conciertos y talleres en las ciudades de Stadthagen, Boppard, Dortmund, Duderstadt e Mannheim.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[46],"tags":[],"class_list":["post-309040","post","type-post","status-publish","format-standard","hentry","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/309040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/comments?post=309040"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/309040\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/media?parent=309040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/categories?post=309040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/tags?post=309040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}