{"id":309090,"date":"2017-11-09T13:54:01","date_gmt":"2017-11-09T12:54:01","guid":{"rendered":"https:\/\/www.focolare.org\/la-caida-del-muro-de-berlin\/"},"modified":"2024-05-15T20:45:33","modified_gmt":"2024-05-15T18:45:33","slug":"la-caida-del-muro-de-berlin","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/es\/la-caida-del-muro-de-berlin\/","title":{"rendered":"La ca\u00edda del Muro de Berl\u00edn"},"content":{"rendered":"<p>El 9 de noviembre de hace 28 a\u00f1os el gobierno alem\u00e1n oriental decretaba la apertura de las fronteras con la\u00a0Rep\u00fablica Federal. Apenas se supo, miles de berlineses del Este se precipitaron a las calles armados de picos para demolir de una buena vez el muro que los divid\u00eda del oeste. La ca\u00edda del muro se interpret\u00f3 universalmente como el signo de una nuova \u00e9poca que comenzaba. Los berlineses del Este fueron acogidos con mucho regocijo de parte de sus hermanos del Oeste, tanto che los bares cercanos al muro comenzaron a ofrecer cerveza gratis a todos<strong>. <\/strong> Poco menos de un a\u00f1o despu\u00e9s, el 3 de octubre de 1990, Alemania se reunificaba definitivamente como la Rep\u00fablica Federal de Alemania. Hoy, algunos restos que quedan del muro se han transformado en el s\u00edmbolo de una \u00e9poca hist\u00f3rica y un memorial que recuerda a las 170 personas que murieron en el intento desesperado de atravesarlo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 9 de noviembre de hace 28 a\u00f1os el gobierno alem\u00e1n oriental decretaba la apertura de las fronteras con la\u00a0Rep\u00fablica Federal. Apenas se supo, miles de berlineses del Este se precipitaron a las calles armados de picos para demolir de una buena vez el muro que los divid\u00eda del oeste. La ca\u00edda del muro se [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[46],"tags":[],"class_list":["post-309090","post","type-post","status-publish","format-standard","hentry","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/309090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/comments?post=309090"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/309090\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/media?parent=309090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/categories?post=309090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/tags?post=309090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}