{"id":309194,"date":"2017-12-16T01:10:21","date_gmt":"2017-12-16T00:10:21","guid":{"rendered":"https:\/\/www.focolare.org\/dios-esta-cerca-de-los-que-sufren\/"},"modified":"2024-05-15T20:45:50","modified_gmt":"2024-05-15T18:45:50","slug":"dios-esta-cerca-de-los-que-sufren","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/es\/dios-esta-cerca-de-los-que-sufren\/","title":{"rendered":"Dios est\u00e1  cerca de los que sufren"},"content":{"rendered":"<p><strong>Hoy la calidez de la Navidad nos ayuda a sentirnos todos m\u00e1s familia<\/strong>, m\u00e1s\u00a0 uno entre nosotros, m\u00e1s hermanos; a compartirlo todo: alegr\u00edas y dolores. Sobre todo, dolores con aquellos que por las circunstancias m\u00e1s variadas transcurren esta Navidad sumidos en el sufrimiento: una enfermedad, una desgracia, una prueba, una circunstancia dolorosa\u2026  [\u2026]<strong> Si miramos con ojos humanos el sufrimiento<\/strong>, sentiremos la tentaci\u00f3n de buscar la causa en nosotros o fuera de nosotros, en la maldad humana, por ejemplo, en la naturaleza o en otras cosas\u2026 Ese accidente es culpa de aqu\u00e9l, esa enfermedad es por mi culpa; esa prueba dolorosa proviene de aquel otro\u2026  Todo esto tambi\u00e9n puede ser verdad, pero si pensamos s\u00f3lo de esta manera, olvidamos lo m\u00e1s importante. Nos olvidamos que detr\u00e1s de la trama de nuestra vida est\u00e1 Dios con su amor, que quiere o permite las cosas por un motivo superior, que es nuestro bien.  [\u2026] \u00bfQu\u00e9 decirles entonces hoy a los que luchan en medio del sufrimiento? \u00bfQu\u00e9 podemos desearles? \u00bfC\u00f3mo comportarnos con ellos?\u00a0 Acerqu\u00e9monos a ellos, ante todo, con sumo respeto: porque aunque todav\u00eda no lo piensen, ellos son visitados por Dios.  <strong>Despu\u00e9s compartamos, en todo lo posible, sus cruces<\/strong>. Asegur\u00e9mosles nuestro constante recuerdo y nuestras oraciones, para que sepan acoger directamente de las manos de Dios todo lo que les angustia y les hace sufrir. Ayud\u00e9mosles, adem\u00e1s, a tener siempre presente el valor del sufrimiento. Y record\u00e9mosles ese maravilloso principio cristiano por el cual un dolor amado como rostro de <a href=\"https:\/\/www.focolare.org\/es\/chiara-lubich\/spiritualita-dellunita\/gesu-abbandonato\/\">Jes\u00fas crucificado y abandonado<\/a> puede transformarse en alegr\u00eda.  [\u2026]<strong> Siendo conscientes de que quien se pone a caminar en el camino de Dios<\/strong> no puede escapar al sufrimiento, deseamos a todos que sepan descubrir cada dolor peque\u00f1o o grande que encuentren con amor, con gran amor, para donarlo al Ni\u00f1o Jes\u00fas [\u2026] como los Reyes Magos ofrecieron sus regalos. Ser\u00e1 el mejor incienso, el mejor oro, la mejor mirra que podremos depositar en el pesebre.  &nbsp;  <a href=\"https:\/\/www.focolare.org\/es\/chiara-lubich\/\">Chiara Lubich,<\/a> 25 de diciembre de 1986<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una conferencia telef\u00f3nica, la fundadora del Movimiento de los Focolares, en la Navidad de 1986, insta a no olvidar a quien est\u00e1 solo, enfermo, atraviesa pruebas espirituales, y a ofrecer con ellos el sufrimiento como un regalo precioso para el Ni\u00f1o que nace en Bel\u00e9n.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[46],"tags":[],"class_list":["post-309194","post","type-post","status-publish","format-standard","hentry","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/309194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/comments?post=309194"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/309194\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/media?parent=309194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/categories?post=309194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/tags?post=309194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}