{"id":310486,"date":"2019-08-22T20:02:22","date_gmt":"2019-08-22T18:02:22","guid":{"rendered":"https:\/\/www.focolare.org\/el-rostro-de-dios-hoy\/"},"modified":"2024-05-15T20:49:28","modified_gmt":"2024-05-15T18:49:28","slug":"el-rostro-de-dios-hoy","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/es\/el-rostro-de-dios-hoy\/","title":{"rendered":"El rostro de Dios hoy"},"content":{"rendered":"<p><em>Desde el 2012 el festival de Salisburgo, es el evento m\u00e1s importante del mundo dedicado a la m\u00fasica cl\u00e1sica. Se inaugura con una obertura espiritual, es decir una serie de conciertos de m\u00fasica sacra y de conferencias dedicadas al di\u00e1logo entre las religiones. Participan muchos grandes de la escena musical y por primera vez, este a\u00f1o estubo presente tambi\u00e9n la Arquidi\u00f3cesis de Salisburgo con una exposici\u00f3n del artista franc\u00e9s Michel Pochet.<\/em>  En la tarde, del s\u00e1bado 20 de julio de 2019, el sal\u00f3n de ingreso del palacio arzobispal de Salisburgo se llen\u00f3 de gente, entre otros estaban presentes la presidente del Festival Helga Rabl-Stadler y el Arzobispo de Salisburgo, Franz Lackner quienes inauguraron la exposici\u00f3n del artista franc\u00e9s Michel Pochet, titulada \u00abLacreme\u00bb (\u00abL\u00e1grimas\u00bb) . \u00abEs la primera vez que la Iglesia cat\u00f3lica de Salisburgo participa en la as\u00ed llamada <em>ouverture spirituelle<\/em> del festival de m\u00fasica\u00bb -explic\u00f3 Mons. Matth\u00e4us Appesbacher, vicario del Obispo, relatando la g\u00e9nesis de esta exposici\u00f3n. Cuando \u00e9l se enter\u00f3 de que el artista hab\u00eda tenido la posibilidad de regalarle al Papa Francisco un lienzo que representaba el rostro lloroso de Dios-misericordia decidi\u00f3 invitarlo a la <em>ouverture spirituelle<\/em> de este a\u00f1o, cuyo tema central eran precisamente las l\u00e1grimas.  \u201cLa belleza \u2013 subray\u00f3 Michel Pochet en su breve intervenci\u00f3n- es una necesidad primaria del ser humano\u00bb. Y para subrayar la necesidad de liberar a los artistas del complejo de su inutilidad social relat\u00f3 lo ocurrido a un chico de Amazonas quien con la m\u00fasica de su flauta trataba de sostener a sus familiares que padec\u00edan hambre.  Las obras elegidas para esta exposici\u00f3n, que se concluyeron el 30 de julio pasado, estimulan el di\u00e1logo. La exposici\u00f3n se encuentra en el majestuoso marco de la ciudad de Salisburgo, donde resalta por doquier el pacto que en tiempos pasados, se estableci\u00f3 entre la Iglesia y el poder. Aqu\u00ed el encuentro entre Iglesia y arte ha asumido un car\u00e1cter fuertemente celebrativo, en cambio las obras de Pochet son decididamente anti-triunfalistas: en su materia, forma y contenidos.  Sus lienzos lo demuestran, por ejemplo, uno en el que \u00abcuenta\u00bb la presencia de Dios en Auschwitz, en el que utiliz\u00f3 trazos ligeros sobre una tela blanca reducida casi a trizas. Pochet dibuja el indecible dolor de la monta\u00f1a de cad\u00e1veres observados por el rostro-coraz\u00f3n de Dios que llora. Un detalle sorprendente, que casi irrita, es que cada cad\u00e1ver tiene un cartelito que lo identifica aunque esto no exist\u00eda en los campos de concentraci\u00f3n. Sin embargo son nombres que conocemos a trav\u00e9s de las novelas televisivas, y aunque sea un procedimiento burocr\u00e1tico, de esta forma se puede arrancar a los muertos del anonimato de las fosas. En el lienzo ellos son un t\u00edmido recuerdo de la memoria de Dios, y aunque se hizo el intento de borrar innumerables nombres de la faz de la tierra, \u00c9l no los olvida. Junto a esta escena, como contrapeso, aparece un gran rostro de Mar\u00eda con rasgos firmes, que tiene un aspecto casi viril; ese lienzo est\u00e1 hecho con colores tiernos y est\u00e1 lleno de poes\u00eda, las l\u00e1grimas de Mar\u00eda son como perlas del roc\u00edo y reflejan la aurora de una nueva creaci\u00f3n.  La exposici\u00f3n est\u00e1 montada en el sal\u00f3n del ingreso y en una sala adyacente. Incluye un ciclo en blanco y negro, que es una &#8216;Via Crucis&#8217; e incluye escenas de la pasi\u00f3n de Jes\u00fas y escenas del dolor de nuestros tiempos. Prosigue con una serie de meditaciones sobre otros \u00abrostros de Dios\u00bb con los que \u00c9l se acerca a su pueblo a trav\u00e9s de sus arc\u00e1ngeles. La exposici\u00f3n puede ser definida como \u00abarte sacro\u00bb, si bien se distingue notablemente de otras representaciones a las que se le atribuye este nombre. No ilustra escenas tomadas de la sagrada escritura -como se hac\u00eda en el barroco o en el rococ\u00f3- sin embargo trasmite conceptos teol\u00f3gicos, pero tiene la audacia de aportar una reflexi\u00f3n personal. La concentraci\u00f3n en el rostro hace pensar en las palabras del fil\u00f3sofo Giuseppe M. Zangh\u00ed, seg\u00fan el cual \u00ablo Sagrado emergente\u00bb del siglo XXI es \u00abUno sin rostro\u00bb, un \u00abPoder sin rostro\u00bb. 1) <\/p>\n<p style=\"text-align: right;\"><em>Peter Seifert, historiador de arte<\/em><\/p>\n<p> &nbsp;  &nbsp;  1) Giuseppe Maria Zangh\u00ed, <em>Notte della cultura europea<\/em>, Roma 2007, pp. 46-47<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el 2012 el festival de Salisburgo, es el evento m\u00e1s importante del mundo dedicado a la m\u00fasica cl\u00e1sica. Se inaugura con una obertura espiritual, es decir una serie de conciertos de m\u00fasica sacra y de conferencias dedicadas al di\u00e1logo entre las religiones. Participan muchos grandes de la escena musical y por primera vez, este a\u00f1o estubo presente tambi\u00e9n la Arquidi\u00f3cesis de Salisburgo con una exposici\u00f3n del artista franc\u00e9s Michel Pochet.<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[46],"tags":[],"class_list":["post-310486","post","type-post","status-publish","format-standard","hentry","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/310486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/comments?post=310486"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/310486\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/media?parent=310486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/categories?post=310486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/tags?post=310486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}