{"id":311150,"date":"2021-01-21T10:00:51","date_gmt":"2021-01-21T09:00:51","guid":{"rendered":"https:\/\/www.focolare.org\/comienza-la-asamblea-general-de-los-focolares\/"},"modified":"2024-05-15T20:51:20","modified_gmt":"2024-05-15T18:51:20","slug":"comienza-la-asamblea-general-de-los-focolares","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/es\/comienza-la-asamblea-general-de-los-focolares\/","title":{"rendered":"Comienza la Asamblea general de los Focolares"},"content":{"rendered":"<p><em>Del 24 al 7 de febrero se desarrollar\u00e1 en forma online la Asamblea general del Movimiento de los Focolares. Se renovar\u00e1n los cargos de la Presidente, el Copresidente, los \u00f3rganos directivos y se definir\u00e1n las l\u00edneas de orientaci\u00f3n y acci\u00f3n para los pr\u00f3ximos seis a\u00f1os.<\/em>  Precedida por un camino formativo e informativo del que participaron las comunidades de los Focolares en el mundo, <strong>el pr\u00f3ximo domingo, 24 de enero de 2021 comenzar\u00e1 la asamblea general de los Focolares<\/strong>, despu\u00e9s de doce a\u00f1os de la muerte de la fundadora<a href=\"https:\/\/www.focolare.org\/es\/chi-siamo\/\" target=\"_blank\" rel=\"noopener\"> Chiara Lubich<\/a>. La Asamblea, que deb\u00eda realizarse a principios de septiembre de 2020, fue reprogramada debido a la pandemia. El Dicasterio para los Laicos, la Familia y la Vida aprob\u00f3 el cambio de fecha y el completo desarrollo en modalidad telem\u00e1tica.  <strong>Camino participativo<\/strong> Participar\u00e1n <strong>362 personas de todo el mundo<\/strong>, en representaci\u00f3n de las distintas culturas, generaciones, vocaciones, pertenencias eclesiales y fe religiosas presentes en el Movimiento de los Focolares. Para alentar la mayor participaci\u00f3n posible, la <a href=\"https:\/\/www.focolare.org\/es\/la-presidente\/\" target=\"_blank\" rel=\"noopener\">actual Presidente Mar\u00eda Voce<\/a> constituy\u00f3 en febrero de 2019 una comisi\u00f3n preparatoria que tuvo la tarea de recibir propuestas de temas para tratar en la asamblea, individualizar nominaciones de los candidatos para las elecciones y preparar el programa.  <strong>Elecci\u00f3n de la Presidente, Copresidente, consejeros<\/strong> Con un sistema de voto telem\u00e1tico, <strong>el 31 de enero se proceder\u00e1 a la elecci\u00f3n de la Presidente<\/strong><a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>, mientras que el 1\u00b0 de febrero ser\u00e1 elegido el Copresidente y el 4 de febrero ser\u00e1 el turno de los consejeros que colaborar\u00e1n con la Presidente en las distintas funciones de gobierno del Movimiento. Ser\u00e1 ella misma quien luego distribuir\u00e1 los cargos.  Otras tareas de la Asamblea general son las deliberaciones sobre tem\u00e1ticas propuestas por el Centro del Movimiento, presentadas por iniciativa de la Presidente, del Consejo general, de una secci\u00f3n, ramificaci\u00f3n o movimiento. Cada participante de la Asamblea puede proponer que sean tomados en consideraci\u00f3n otros temas.  <strong>\u00bfDe qu\u00e9 se hablar\u00e1?<\/strong> <strong>Las m\u00e1s de 3.000 propuestas<\/strong> llegadas de todo el mundo sobre las tem\u00e1ticas para tratar en la Asamblea y los lineamientos que el Movimiento deber\u00eda seguir en los pr\u00f3ximos\u00a0 seis a\u00f1os, representan cabalmente la vivacidad del pueblo de los Focolares, pero tambi\u00e9n la conciencia del <a href=\"http:\/\/www.vatican.va\/content\/francesco\/es\/speeches\/2018\/may\/documents\/papa-francesco_20180510_visita-loppiano-focolari.html\" target=\"_blank\" rel=\"noopener\">\u201ccambio de \u00e9poca\u201d<\/a> que se experimenta, como dijo el papa Francisco en el 2018, cuando visit\u00f3 la comunidad de los Focolares en Loppiano (Italia).  Las numerosas instancias fueron ordenadas en <strong>cuatro grandes ejes tem\u00e1ticos<\/strong>: la actualizaci\u00f3n del carisma transmitido por la fundadora; la cultura que surge del carisma de la unidad; la respuesta a la crisis ambiental y a la pandemia; el trabajar junto a las nuevas generaciones.  Como afirm\u00f3 recientemente en una <a href=\"https:\/\/www.focolare.org\/es\/news\/2021\/01\/20\/focolares-y-abusos-un-antes-y-un-despues\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #000000;\">entrevista<\/span><\/a> el actual Copresidente de los Focolares, <a href=\"https:\/\/www.focolare.org\/download\/scheda-jesus-moran-co-presidente\/\" target=\"_blank\" rel=\"noopener\">Jes\u00fas Mor\u00e1n<\/a>, un<strong> espacio de di\u00e1logo y debate versar\u00e1 sobre el tema de los abusos<\/strong> tanto en la relaci\u00f3n del sexenio de la Presidente que abrir\u00e1 la asamblea, como en una intervenci\u00f3n <em>ad hoc<\/em> del Copresidente.  Aun en la diversidad de opiniones, surge la <strong>necesidad general de individualizar nuevos y actuales caminos de fraternidad<\/strong>, capaces de responder a los desaf\u00edos y a los interrogantes de la humanidad tanto a nivel global como local.  Noticias sobre los trabajos de la Asamblea estar\u00e1n disponibles diariamente en la <a href=\"https:\/\/www.focolare.org\/es\/assemblea-generale\/\" target=\"_blank\" rel=\"noopener\">p\u00e1gina Web de los Focolares<\/a> y en sucesivos comunicados de prensa.  <em>Stefania Tanesini &#8211; \u00a0+39 3385658244<\/em>  &nbsp;  <span style=\"font-size: 14px;\"><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a>Como dicen los Estatutos, el Movimiento ser\u00e1 siempre presidido por una mujer a fin de subrayar el perfil mariano y su connotaci\u00f3n prevalentemente laical y as\u00ed \u201cmantener el designio que Dios tuvo al haber confiado el inicio a una mujer\u201d. Como se lee en los Estatutos, \u201cla suya ser\u00e1 sobre todo una presidencia de la caridad, porque deber\u00e1 ser la primera en amar, es decir servir a sus hermanos, recordando las palabras de Jes\u00fas: \u2018(\u2026) quien quiera ser el primero que se haga el servidor de todos\u2019 (Mc 10,44)\u201d.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del 24 al 7 de febrero se desarrollar\u00e1 en forma online la Asamblea general del Movimiento de los Focolares. Se renovar\u00e1n los cargos de la Presidente, el Copresidente, los \u00f3rganos directivos y se definir\u00e1n las l\u00edneas de orientaci\u00f3n y acci\u00f3n para los pr\u00f3ximos seis a\u00f1os.<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[46],"tags":[],"class_list":["post-311150","post","type-post","status-publish","format-standard","hentry","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/311150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/comments?post=311150"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/311150\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/media?parent=311150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/categories?post=311150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/tags?post=311150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}