{"id":311286,"date":"2021-04-14T01:40:15","date_gmt":"2021-04-13T23:40:15","guid":{"rendered":"https:\/\/www.focolare.org\/igino-giordani-un-heroe-desarmado\/"},"modified":"2024-05-15T20:51:42","modified_gmt":"2024-05-15T18:51:42","slug":"igino-giordani-un-heroe-desarmado","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/es\/igino-giordani-un-heroe-desarmado\/","title":{"rendered":"Igino Giordani, un h\u00e9roe desarmado"},"content":{"rendered":"<p><em>El domingo 18 de abril, en live streaming, ser\u00e1 recordado a trav\u00e9s de algunos testimonios Igino Giordani, quien fuera un pol\u00edtico inspirador del compromiso social y de los principios y decisiones de tantos, escritor y periodista, co-fundador del Movimiento de los Focolares. Se presentar\u00e1 su \u00faltimo libro biogr\u00e1fico y se inaugurar\u00e1 una escultura dedicada a \u00e9l.<\/em>  Hombre de di\u00e1logo y de fe profunda, promotor de la fraternidad universal, constructor de paz, pol\u00edtico, periodista: <a href=\"https:\/\/www.focolare.org\/es\/download\/scheda-igino-giordani-2\/\" target=\"_blank\" rel=\"noopener\">Igino Giordani<\/a> (1894-1980) es esto y mucho m\u00e1s. El 18 de abril de 2021 ser\u00e1 el 41\u00b0 aniversario de su partida y para esta conmemoraci\u00f3n el <a href=\"https:\/\/www.facebook.com\/IginoGiordaniFoco\/\">Centro Igino Giordani<\/a> ha organizado un evento para recordar su figura. Una figura que a trav\u00e9s del tiempo sigue suscitando el inter\u00e9s de personas de distintas edades, proveniencias geogr\u00e1ficas, pol\u00edticas, culturales y sigue suscitando el compromiso de construir una sociedad mejor.  El evento ser\u00e1 transmitido v\u00eda streaming ( <a href=\"https:\/\/live.focolare.org\/\" target=\"_blank\" rel=\"noopener\">https:\/\/live.focolare.org\/<\/a> ) desde el Centro Internacional del Movimiento de los Focolares (Rocca di Papa, Italia), el domingo 18 de abril de 2021 a las 15.30 (hora italiana) con la posibilidad de seguirlo en italiano, ingl\u00e9s, franc\u00e9s, espa\u00f1ol y portugu\u00e9s.  <img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-241513 alignright\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2021\/04\/Libro-Giordani-cover-224x340.jpeg\" alt=\"\" width=\"224\" height=\"340\" \/>Giordani fue un periodista y escritor, y tuvo un papel muy importante en la pol\u00edtica italiana de la segunda postguerra. De hecho dio un v\u00e1lido aporte para sentar las bases de la naciente Rep\u00fablica Italiana en un pe\u0155iodo que no fue f\u00e1cil para este pa\u00eds, que estaba volviendo de las guerras mundiales, y tambi\u00e9n fue miembro de la Asamblea Constituyente. Dio un testimonio de la pol\u00edtica vivida como servicio a la paz y a favor de una sociedad m\u00e1s justa. Desde esta \u00f3ptica se presentar\u00e1n algunos testimonios de quien ha traducido la sabidur\u00eda de Giordani en el dise\u00f1o de leyes o iniciativas pol\u00edticas a favor del di\u00e1logo y de quienes han comprendido qu\u00e9 decisiones es necesario tomar para contrarrestar\u00a0 pol\u00edticas que amenazan la paz de los pueblos.  Durante el evento se presentar\u00e1 su \u00faltima biograf\u00eda a cargo de <strong>Alberto Lo Presti<\/strong> (ed. Citt\u00e0 Nuova Italia), con el t\u00edtulo <em>\u201cIgino Giordani. Un eroe disarmato\u201d (<\/em><em>\u201cIgino Giordani. Un h\u00e9roe desarmado\u201d)<\/em>, cuyo prefacio fue escrito por el <strong>Presidente de la Rep\u00fablica italiana Sergio Mattarella<\/strong>. Una biograf\u00eda que ayuda a descubrir el sentido de un aut\u00e9ntico compromiso pol\u00edtico y social. Apasionante como una novela. \u201cSu fe impetuosa, -escribe Matarella, hablando de Giordani- su coherencia evang\u00e9lica, el fervor con el que luchaba por la igualdad social, la libertad, la paz, han sacudido muchas conciencias y promovido acciones y pensamiento, tanto en los tiempos grises del fascismo como en los a\u00f1os de la reconstrucci\u00f3n democr\u00e1tica\u201d. \u201cSe volvi\u00f3 un constructor de paz en el di\u00e1logo entre las personas, entre las confesiones religiosas,\u00a0 entre los pueblos y los Estados. &#8211; prosigue Matarella &#8211; Pensaba en Europa como un continente de paz, despu\u00e9s de haber sido escenario de guerras asoladoras. Quer\u00eda que su pa\u00eds llegara a ser un puente. Y \u00e9l mismo trataba de ser puente para acercar, conectar, recomponer\u201d.  Tambi\u00e9n ser\u00e1 inaugurada una escultura dedicada a \u00e9l, obra del artista <strong>Peter Kostner<\/strong>. La obra, que ser\u00e1 colocada en el jard\u00edn del Centro Internacional de los Focolares, representa a Giordani sentado en una banquita. De hecho en los \u00faltimos a\u00f1os de su vida acostumbraba sentarse precisamente en una banquita de ese parque. Durante los encuentros internacionales que se desarrollaban en el Centro muchos, j\u00f3venes\u00a0 adultos, se acercaban para saludarlo y hablar con \u00e9l. Y la banquita se hab\u00eda convertido en un lugar de encuentro y de di\u00e1logo. A lo largo del evento algunos testimonios recordar\u00e1n esos coloquios en los cuales Giordani escuchaba con humildad y paciencia ofreciendo consejos que proven\u00edan de su fecunda experiencia de vida, enriquecidos por el carisma de la unidad. <\/p>\n<p style=\"text-align: right;\"><em>Lorenzo Russo<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El domingo 18 de abril, en live streaming, ser\u00e1 recordado a trav\u00e9s de algunos testimonios Igino Giordani, quien fuera un pol\u00edtico inspirador del compromiso social y de los principios y decisiones de tantos, escritor y periodista, co-fundador del Movimiento de los Focolares. Se presentar\u00e1 su \u00faltimo libro biogr\u00e1fico y se inaugurar\u00e1 una escultura dedicada a \u00e9l.<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[46],"tags":[],"class_list":["post-311286","post","type-post","status-publish","format-standard","hentry","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/311286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/comments?post=311286"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/311286\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/media?parent=311286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/categories?post=311286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/tags?post=311286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}