{"id":311760,"date":"2022-05-16T01:00:15","date_gmt":"2022-05-15T23:00:15","guid":{"rendered":"https:\/\/www.focolare.org\/chiara-lubich-quien-ama-hace-el-bien\/"},"modified":"2024-05-15T20:53:00","modified_gmt":"2024-05-15T18:53:00","slug":"chiara-lubich-quien-ama-hace-el-bien","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/es\/chiara-lubich-quien-ama-hace-el-bien\/","title":{"rendered":"Chiara Lubich: Quien ama hace el bien"},"content":{"rendered":"<p><em>El mandamiento nuevo de Jes\u00fas, el amor al hermano es lo que nos propone la Palabra de Vida en este mes de mayo de 2022. Es un camino en el que se puede progresar cada d\u00eda y en el que se encuentra la plenitud del mensaje de Jes\u00fas. <\/em>  <em>\u201cToda la ley alcanza su plenitud en este solo precepto: amar\u00e1s a tu pr\u00f3jimo como a ti mismo\u201d <\/em>(<em>Gal<\/em> 5,14).  Esta es una palabra de Pablo el Ap\u00f3stol: breve, estupenda, lapidaria y clarificadora.  Nos dice lo que debe haber como base del comportamiento cristiano, lo que debe inspirarlo siempre: el amor al pr\u00f3jimo.  El Ap\u00f3stol ve en la realizaci\u00f3n de este mandamiento el pleno cumplimiento de la ley. Y esta dice: no cometer\u00e1s adulterio, no matar\u00e1s, no robar\u00e1s, no desear\u00e1s\u2026 y ya sabemos que quien ama no hace todo esto: quien ama no mata, no roba\u2026\u2026  Pero quien ama no solo evita el mal. Quien ama se abre a los dem\u00e1s, quiere el bien, lo hace, se entrega: llega a dar la vida por la persona amada.  Por eso Pablo escribe que en el amor al pr\u00f3jimo no solo se observa la ley, sino que se alcanza \u00abla plenitud\u00bb de la ley.  (\u2026)  Si toda la ley consiste en el amor al pr\u00f3jimo, es necesario ver los dem\u00e1s mandamientos como medios para iluminarnos y guiarnos y as\u00ed saber encontrar en las intrincadas situaciones de la vida el camino para amar a los dem\u00e1s; hay que saber leer en los otros mandamientos la intenci\u00f3n de Dios, su voluntad.  \u00c9l quiere que seamos obedientes, castos, mansos, mortificados, misericordiosos, pobres\u2026 para realizar mejor el mandamiento de la caridad. <\/p>\n<p style=\"text-align: right;\"><em>Chiara Lubich<\/em><\/p>\n<p> (Chiara Lubich, en Palabras de Vida\/1, Ciudad Nueva, Madrid, 2020, p. 275-276)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mandamiento nuevo de Jes\u00fas, el amor al hermano es lo que nos propone la Palabra de Vida en este mes de mayo de 2022. Es un camino en el que se puede progresar cada d\u00eda y en el que se encuentra la plenitud del mensaje de Jes\u00fas.<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[46],"tags":[],"class_list":["post-311760","post","type-post","status-publish","format-standard","hentry","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/311760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/comments?post=311760"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/311760\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/media?parent=311760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/categories?post=311760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/tags?post=311760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}