{"id":324278,"date":"2015-07-23T04:00:15","date_gmt":"2015-07-23T02:00:15","guid":{"rendered":"https:\/\/www.focolare.org\/pais-vasco-un-laboratorio-para-aprender-la-paz\/"},"modified":"2024-05-16T14:50:20","modified_gmt":"2024-05-16T12:50:20","slug":"pais-vasco-un-laboratorio-para-aprender-la-paz","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/es\/pais-vasco-un-laboratorio-para-aprender-la-paz\/","title":{"rendered":"Pa\u00eds Vasco: un laboratorio para aprender la paz"},"content":{"rendered":"<p><a href=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2015\/07\/relatori.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-126854 alignleft\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2015\/07\/relatori.jpg\" alt=\"relatori\" width=\"350\" height=\"197\" hspace=\"5\" \/><\/a>La idea surge para dar respuesta a la situaci\u00f3n de violencia que vive el Pa\u00eds como consecuencia del uso de la lucha armada de ETA. Una Idea para sanar heridas, a\u00fan abiertas, y para intentar asegurar un futuro de paz.  <em>\u201cEsto es una utop\u00eda, pero tal vez sea la \u00fanica soluci\u00f3n para nuestro pueblo.\u201d <\/em>Es el afligido lema de esperanza de algunos miembros del Grupo de Gipuzkoa cuando hace ahora una decena de a\u00f1os, algunos exponentes del <a href=\"http:\/\/mppu.es\/es\/\" target=\"_blank\" rel=\"noopener\">Movimiento Pol\u00edtico por la Unidad<\/a> (MPpU) venidos de Italia, les hablaron de la <strong>fraternidad como categor\u00eda pol\u00edtica. <\/strong> Una prospectiva que, por el clima que se viv\u00eda en el Pa\u00eds Vasco debido a la lucha armada de ETA, result\u00f3 casi como un shock para el grupo. Con el fin de conseguir la independencia para el pueblo vasco, los grupos armados de ETA siembran continuamente un clima de violencia y terror, creando un ambiente de alt\u00edsima tensi\u00f3n.  En aquella \u00e9poca, comienzos de 2005, un grupo de pol\u00edticos, pertenecientes no s\u00f3lo a partidos diferentes sino tambi\u00e9n a ideolog\u00edas diferentes, se unen para iniciar conjuntamente un camino para ir en busca de una regeneraci\u00f3n pol\u00edtica, <strong>basada en la acogida reciproca del otro, sin exclusiones<\/strong>. Se abre as\u00ed un espacio de debate, de aceptaci\u00f3n del otro, que involucra a pol\u00edticos de diversas sensibilidades, funcionarios, sindicalistas, ciudadanos\u2026, sedientos de una convivencia normalizada, de una paz verdadera.  Se mantienen reuniones bimensuales, eligiendo cada vez una sede diferente, alternando entre los diversos partidos.  Entre los participantes hay quien est\u00e1 amenazado por pertenecer a un determinado partido y acude a las reuniones con escolta; hay quien teme no ser entendido en su propio partido y teme, incluso, ser expulsado del <a href=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2015\/07\/platea.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-126858\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2015\/07\/platea.jpg\" alt=\"platea\" width=\"350\" height=\"261\" hspace=\"5\" \/><\/a>mismo, pero todos, con el apoyo mutuo y superando la desconfianza, quieren dar testimonio de que la fraternidad es posible, empezando por la fraternidad entre ellos mismos.  Con el paso del tiempo se ve necesario el intercambiar experiencias con pol\u00edticos de otros territorios, de otras comunidades. Y as\u00ed algunos miembros del grupo acuden a Madrid, a participar en una serie de reuniones donde se conocen otras experiencias. Estos miembros invitan a los otros participantes a mantener una reuni\u00f3n en Euskadi con el grupo de Gipuzkoa. Es un encuentro hist\u00f3rico: cuatro horas de dialogo (despu\u00e9s de haber comido juntos) para conocerse, escucharse, pedirse perd\u00f3n.  Como consecuencia de esa reuni\u00f3n surge la necesidad de <strong>elaborar un documento <\/strong>que sirva de alternativa a la crisis. Elaborado dicho documento, cada miembro que particip\u00f3 en su elaboraci\u00f3n se comprometi\u00f3 a llevarlo a su partido, para su estudio.  Muchos sienten la necesidad de compartir el contenido del documento, y nace la idea de convocar seminarios y mesas redondas en otras comunidades aut\u00f3nomas donde presentar la experiencia de la fraternidad as\u00ed como la experiencia de la convivencia pac\u00edfica basada precisamente en la fraternidad.  Con el cese de la actividad armada de ETA (2011), se inicia un proceso nuevo, esperanzador aunque no sencillo. Todav\u00eda son muchas las personas, las familias y los grupos que a pesar de compartir la misma identidad, est\u00e1n divididos, con enfrentamientos continuos y serias dificultades para dialogar. El laboratorio pol\u00edtico que se hab\u00eda generado en los tiempos duros \u2013 familiarmente llamado \u201c<strong>laboratorio para aprender la paz<\/strong>\u201d- prosigue su camino de reconciliaci\u00f3n y b\u00fasqueda de la paz, afrontando los distintos puntos de vista sobre hechos hist\u00f3ricos, sanando heridas abiertas. En ese contexto, el grupo elabora un documento que lo denomina \u201c<strong>Por el camino de la reconciliaci\u00f3n de la sociedad vasca<\/strong>\u201d (enero de 2013). Este es un documento que describe las bases por las cuales tiene que caminar el grupo de aqu\u00ed en adelante. Coloquialmente se lo denomina \u201cel suelo en el que pisamos\u201d.  <a href=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2015\/07\/gruppo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-126859 alignleft\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2015\/07\/gruppo.jpg\" alt=\"gruppo\" width=\"350\" height=\"164\" hspace=\"5\" \/><\/a>Cada vez que el di\u00e1logo parece bloquearse, se intenta reimpulsarlo ayud\u00e1ndose a creer que cada hombre es un hermano y que se puede construir todo con todos.  Eso no significa no reconocer los delitos y el gran n\u00famero de personas que han pagado con la vida. Todo lo contrario, aceptando lo pasado y reconociendo lo injusto e inexplicable de la violencia sufrida, se trata de mirar la historia como un lento y fatigoso camino hacia la reconciliaci\u00f3n, hacia la paz, en el cual cada uno puede y debe dar su aportaci\u00f3n.  El 13 de Marzo, justamente en la vigilia del aniversario de <a href=\"https:\/\/www.focolare.org\/es\/chiara-lubich\/chi-e-chiara\/\">Chiara Lubich<\/a>, en el que se profundizaba en todo el mundo <a href=\"https:\/\/vimeo.com\/122094306\" target=\"_blank\" rel=\"noopener\">su visi\u00f3n de la pol\u00edtica<\/a>, este grupo se reuni\u00f3 en la casa de \u201c<a href=\"http:\/\/mppu.es\/2015\/03\/03\/juntas-generales-de-gipuzkoa\/\" target=\"_blank\" rel=\"noopener\">las Juntas Generales de Gipuzkoa<\/a>\u201d (parlamento provincial) en San Sebasti\u00e1n, e invitaron a expertos, intelectuales y personalidades pol\u00edticas, para debatir sobre la \u201cRelaci\u00f3n entre el bien com\u00fan y los bienes comunes en la globalizaci\u00f3n\u201d. El documento base, enviado a todos con antelaci\u00f3n y muy bien aceptado, hab\u00eda sido elaborado por el \u201claboratorio para aprender la paz\u201d. En un clima de acogida rec\u00edproca, surgieron aportaciones muy v\u00e1lidos que, con posterioridad se integraron en el mismo documento, que se divulgar\u00e1 despu\u00e9s para promover a todos los niveles el valor de la fraternidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La idea nace en Gipuzkoa, provincia vasca perteneciente a Euskadi, Comunidad Aut\u00f3noma vasca. Comunidad con una cultura, unas tradiciones y una lengua, propias, herencia de una historia milenaria.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[904],"tags":[],"class_list":["post-324278","post","type-post","status-publish","format-standard","hentry","category-focolare-worldwide-2-2"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/324278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/comments?post=324278"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/324278\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/media?parent=324278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/categories?post=324278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/tags?post=324278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}