{"id":324356,"date":"2015-09-02T04:00:27","date_gmt":"2015-09-02T02:00:27","guid":{"rendered":"https:\/\/www.focolare.org\/usa-dialogo-y-preguntas-dificiles\/"},"modified":"2024-05-16T14:50:35","modified_gmt":"2024-05-16T12:50:35","slug":"usa-dialogo-y-preguntas-dificiles","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/es\/usa-dialogo-y-preguntas-dificiles\/","title":{"rendered":"USA: Di\u00e1logo y preguntas dif\u00edciles"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-127937 alignleft\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2015\/09\/20150901-02.jpg\" alt=\"20150901-02\" width=\"328\" height=\"219\" \/><strong>En 1998, <\/strong><a href=\"https:\/\/www.focolare.org\/es\/chiara-lubich\/chi-e-chiara\/\">Chiara Lubich<\/a> <strong>inaugur\u00f3 el \u201cCentro para la Educaci\u00f3n al Di\u00e1logo\u201d, con sede en la <\/strong><a href=\"https:\/\/www.focolare.org\/mariapolisluminosa\/\">Mari\u00e1polis Luminosa<\/a>, ciudadela de los Focolares cercana a Nueva York. En esa ocasi\u00f3n escribi\u00f3: \u00abQue todos los participantes en sus actividades se sientan igualmente constructores de esta nueva realidad colaborando con amor, paciencia, comprensi\u00f3n mutua y solidaridad a crear una isla de paz y un signo de unidad para el mundo de hoy\u2026 que sea sobre todo una escuela donde se aprenda a vivir este amor que es el \u00fanico que puede hacer de los hombres y las mujeres de esta tierra una \u00fanica familia\u00bb.  Este augurio de Chiara estaba muy presente en el encuentro que tuvo lugar el 15 y 16 de agosto pasados, en la ciudadela estadounidense, titulado \u201cEl di\u00e1logo y las preguntas dif\u00edciles\u201d. Un desaf\u00edo acogido por alrededor de un centenar de participantes \u00abcentrado \u2013como escriben los organizadores- en c\u00f3mo podemos dialogar y comunicar cuando se afrontan tem\u00e1ticas importantes y cuando hay personas con profundas diferencias de pensamiento\u00bb.  <img loading=\"lazy\" decoding=\"async\" class=\" wp-image-127938 alignright\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2015\/09\/20180901-01.jpg\" alt=\"20180901-01\" width=\"328\" height=\"220\" \/>El programa se desarroll\u00f3 con el aporte de cuatro expertos en Teolog\u00eda Moral y Teor\u00edas Pol\u00edticas, provenientes de las universidades de Fordham (Nueva York), Providence College (Rhode Island) y Georgetown (Washington). \u00abEmpezamos \u2013cuentan- con pensamientos de Chiara Lubich sobre el di\u00e1logo, donde emerge lo espec\u00edfico de la espiritualidad de la unidad que, si se vive, ayuda a transformar las relaciones entre las personas\u00bb.  Charlie Camosy (Fordham) y Amy Uelmen (Georgetown), analizaron \u00ablos motivos por los que la sociedad en los Estados Unidos est\u00e1 tan polarizada sobre posiciones opuestas y c\u00f3mo se podr\u00edan romper estos muros entre las personas, sabiendo escuchar y teniendo una actitud de apertura al otro\u00bb. Dana Dillon (Providence College) afront\u00f3 la delicada relaci\u00f3n entre \u201camor y verdad\u201d, a partir de uno de los puntos centrales de la espiritualidad de la unidad: Jes\u00fas abandonado. La te\u00f3loga lo present\u00f3 como el aut\u00e9ntico modelo del di\u00e1logo en cuanto \u00ab\u00c9l \u2013 en el momento en que se sinti\u00f3 abandonado por el Padre \u2013 entr\u00f3 en la desunidad, unificando la m\u00e1s grande divisi\u00f3n posible, la que hab\u00eda entre el cielo y la tierra\u00bb.  <img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-127939\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2015\/09\/20180901-03.jpg\" alt=\"20180901-03\" width=\"328\" height=\"218\" \/><strong>En la tarde tuvo lugar un momento interactivo<\/strong>: Claude Blanc, l\u00edder coach (un orientador que promueve el trabajo en equipo), gui\u00f3 a los presentes en la realizaci\u00f3n de algunos ejercicios \u00abpara aprender a escuchar profundamente y sin esperar nada de \u00e9l\u00bb. Bill Gould (Fordham), para completar el argumento desarroll\u00f3 una reflexi\u00f3n sobre las \u201cDistintas formas de comunicar\u201d (imponer, discutir, tratar de convencer al otro, o bien orientarse hacia el bien com\u00fan).  <strong>En la mesa redonda del domingo<\/strong>, en las preguntas a los profesores, se pon\u00eda en evidencia la necesidad por parte de los presentes de estar preparados para afrontar tem\u00e1ticas \u00e1lgidas como la procreaci\u00f3n in vitro, los matrimonios homosexuales, y otros desaf\u00edos que se presentan en la vida de todos los d\u00edas.  \u00abEl taller sobre la escucha me ayud\u00f3 a entender lo fecundo que puede ser el saberse escuchar en las relaciones cotidianas\u00bb; \u00abRegres\u00e9 enriquecido por esta experiencia\u00bb. Son dos de las impresiones entre las muchas que dejaron los participantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la Mari\u00e1polis Luminosa, Nueva York, el Centro para la Educaci\u00f3n al Di\u00e1logo, organiza un fin de semana centrado en la formaci\u00f3n al di\u00e1logo, especialmente en situaciones de gran diversidad.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[904,905],"tags":[],"class_list":["post-324356","post","type-post","status-publish","format-standard","hentry","category-focolare-worldwide-2-2","category-senza-categoria-2-2"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/324356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/comments?post=324356"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/324356\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/media?parent=324356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/categories?post=324356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/tags?post=324356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}