{"id":325856,"date":"2017-03-28T03:10:38","date_gmt":"2017-03-28T01:10:38","guid":{"rendered":"https:\/\/www.focolare.org\/palabra-de-vida-abril-2017\/"},"modified":"2024-05-16T14:55:23","modified_gmt":"2024-05-16T12:55:23","slug":"palabra-de-vida-abril-2017","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/es\/palabra-de-vida-abril-2017\/","title":{"rendered":"Palabra de vida &#8211; Abril 2017"},"content":{"rendered":"<p>Es la invitaci\u00f3n, dirigida a un desconocido en el camino desde Jerusal\u00e9n al pueblo de Ema\u00fas, por dos compa\u00f1eros de viaje que \u00abconversaban y discut\u00edan\u00bb sobre lo que hab\u00eda sucedido en la ciudad en los d\u00edas anteriores.  Parec\u00eda ser el \u00fanico que no sab\u00eda nada, y por eso los dos, que aceptan su compa\u00f1\u00eda, le hablan de \u00abun profeta poderoso en obras y palabras delante de Dios y de todo el pueblo\u00bb en el cual hab\u00edan depositado su confianza. Hab\u00eda sido entregado por los jefes de sus sacerdotes y por las autoridades jud\u00edas a los romanos, y luego condenado a muerte y crucificado (cf. <em>Lc <\/em>24, 19ss.). Una tragedia enorme cuyo sentido no eran capaces de entender.  A lo largo del camino, el desconocido los ayuda a captar el significado de aquellos acontecimientos a partir de la Escritura y enciende de nuevo la esperanza en sus corazones. Al llegar a Ema\u00fas, lo retienen para cenar: \u00abQu\u00e9date con nosotros, porque atardece\u00bb. Mientras est\u00e1n a la mesa juntos, el desconocido bendice el pan y lo comparte con ellos. Un gesto que permite reconocerlo: \u00a1el Crucificado estaba muerto y ahora ha resucitado! E inmediatamente los dos cambian de planes: vuelven a Jerusal\u00e9n a buscar a los dem\u00e1s disc\u00edpulos y darles la gran noticia.  Tambi\u00e9n nosotros podemos sentirnos desilusionados, indignados, desanimados por una sensaci\u00f3n tr\u00e1gica de impotencia ante las injusticias\u00a0 que golpean a personas inocentes e inermes. En nuestra vida no faltan el dolor, la incertidumbre, la oscuridad\u2026 \u00a1Y c\u00f3mo nos gustar\u00eda transformarlos en paz, esperanza y luz para nosotros y para los dem\u00e1s!  \u00bfQueremos encontrar a Alguien que nos entienda hasta el fondo y nos ilumine el camino de la vida?  Jes\u00fas, el Hombre-Dios, para estar seguro de llegar a cada uno de nosotros en lo profundo de su situaci\u00f3n, acept\u00f3 libremente pasar, como nosotros, por el t\u00fanel del dolor. Del dolor f\u00edsico, pero tambi\u00e9n del interior, desde la traici\u00f3n de sus amigos hasta sentirse abandonado (cf. <em>Mt <\/em>27, 46; <em>Mc <\/em>15, 34) por ese Dios al que siempre hab\u00eda llamado Padre. Gracias a esa confianza inquebrantable en el amor de Dios, super\u00f3 ese inmenso dolor y se volvi\u00f3 a entregar a \u00c9l (cf, <em>Lc <\/em>23, 46). Y de \u00c9l recibi\u00f3 nueva vida.  Tambi\u00e9n a nosotros nos ha llevado por este mismo camino y quiere acompa\u00f1arnos:  \u00ab\u2026\u00c9l est\u00e1 presente en todo lo que sabe a dolor\u2026 Procuremos reconocer a Jes\u00fas en todas las angustias y penurias de la vida, en cualquier oscuridad, en las tragedias personales y de los dem\u00e1s, en los sufrimientos de la humanidad que nos rodea. Son \u00c9l porque \u00c9l las ha hecho suyas\u2026 Bastar\u00e1 con hacer algo concreto por aliviar <em>sus <\/em>sufrimientos en los pobres\u2026 para encontrar una nueva plenitud de vida\u00bb<a href=\"#_bookmark0\">1<\/a>.  Cuenta una ni\u00f1a de siete a\u00f1os: \u00abMe doli\u00f3 mucho cuando a mi padre lo metieron en prisi\u00f3n. Am\u00e9 a Jes\u00fas en \u00e9l y por eso no llor\u00e9 delante de \u00e9l cuando fuimos a visitarlo\u00bb.  Y una joven esposa: \u00abAcompa\u00f1\u00e9 a Roberto, mi marido, en sus \u00faltimos meses de vida tras un diagn\u00f3stico sin esperanza. No me alej\u00e9 de \u00e9l ni un segundo. Lo ve\u00eda a \u00e9l y ve\u00eda a Jes\u00fas\u2026 Roberto estaba en la cruz, realmente en la cruz\u00bb. El amor rec\u00edproco de ellos se convirti\u00f3 en luz para sus amigos, los cuales se vieron envueltos en una carrera de solidaridad que no se ha interrumpido desde entonces, sino que se ha extendido a otros y se ha plasmado en una asociaci\u00f3n de promoci\u00f3n social, \u00abAbrazo planetario\u00bb. \u00abLa experiencia vivida con Roberto \u2013 dice un amigo suyo\u2013 nos ha llevado a recorrer un aut\u00e9ntico camino hacia Dios. Muchas veces nos preguntamos qu\u00e9 sentido tienen el sufrimiento, la enfermedad y la muerte. Creo que todos los que han recibido el regalo de recorrer este trecho de camino junto a Roberto tienen ahora muy claro cu\u00e1l es la respuesta\u00bb.  En este mes todos los cristianos celebrar\u00e1n el misterio de la muerte y resurrecci\u00f3n de Jes\u00fas. Es una ocasi\u00f3n para avivar nuestra fe en el amor de Dios, que nos permite transformar el dolor en amor; cualquier desgarro, separaci\u00f3n, fracaso y hasta la muerte, pueden convertirse tambi\u00e9n para nosotros en fuente de luz y de paz. Seguros de la cercan\u00eda de Dios a cada uno de nosotros en cualquier situaci\u00f3n, repitamos con confianza la oraci\u00f3n de los\u00a0 disc\u00edpulos\u00a0 de Ema\u00fas:  \u00abQu\u00e9date con nosotros, porque atardece\u00bb.  <em>Letizia Magri<\/em>  1 Cf. C. LUBICH, Palabra de vida, abril 1999: <em>Ciudad Nueva <\/em>1999\/4, p. 27.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abQu\u00e9date con nosotros, porque atardece\u00bb (Lc 24, 29).<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[95,46],"tags":[],"class_list":["post-325856","post","type-post","status-publish","format-standard","hentry","category-palabra-de-vida","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/325856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/comments?post=325856"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/325856\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/media?parent=325856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/categories?post=325856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/tags?post=325856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}