{"id":348372,"date":"2012-04-05T12:42:43","date_gmt":"2012-04-05T10:42:43","guid":{"rendered":"https:\/\/www.focolare.org\/colombia-faletti-en-el-centro-social-unidad\/"},"modified":"2024-06-06T12:29:27","modified_gmt":"2024-06-06T10:29:27","slug":"colombia-faletti-en-el-centro-social-unidad","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/es\/colombia-faletti-en-el-centro-social-unidad\/","title":{"rendered":"Colombia: Faletti en el Centro social Unidad"},"content":{"rendered":"<p><a href=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2012\/04\/20120406-01.jpg\"><img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-articolo_1 wp-image-60546\" style=\"margin-right: 10px\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2012\/04\/20120406-01-250x187.jpg\" alt=\"\" width=\"250\" height=\"187\" \/><\/a>Joana es una adolescente de largo cabello negro. Canta una canci\u00f3n t\u00edpica \u2013Esta es Colombia, viajero-, que evoca la belleza del Pa\u00eds. Giancarlo <strong>Faletti reci\u00e9n llegado de M\u00e9xico<\/strong> se encuentra ahora en esta tierra con costa sobre los dos oc\u00e9anos. <strong>Visita una significativa iniciativa<\/strong> que le da la bienvenida. Una decena de ni\u00f1os y ni\u00f1as con vestimenta de papel coloreado danza con paso seguro, en la salita repleta de lugare\u00f1os que llegaron para saludar al copresidente de los Focolares.<\/p>\n<p><strong>Los Chircales es un barrio de la periferia sur de Bogot\u00e1.<\/strong> Es una extensi\u00f3n de casitas rojas desordenadas, de color ladrillo que dan el nombre al lugar. Todo alrededor se percibe como un panorama dif\u00edcil, con calles rotas, las paredes en ruina. <strong>Es en este contexto que tiene su sede el Centro social Unidad.<\/strong><\/p>\n<p><strong>Todo comenz\u00f3 en 1977. Un grupito de j\u00f3venes de la ciudad tom\u00f3 en sus manos el audaz desaf\u00edo lanzado en ese a\u00f1o por Chiara Lubich: Morir por la propia gente<\/strong>. Llegaron aqu\u00ed, al territorio de la parroquia del padre Luis y comenzaron a jugar con los ni\u00f1os. Encontraron la humanidad herida pero profunda de dos chircaleros, Gabrielina y Macedonio, que mezclaban la arcilla para producir ladrillos, esos ladrillos que sirvieron para edificar la gran metr\u00f3polis de Bogot\u00e1<\/p>\n<p><strong>Gracias a la generosa disposici\u00f3n de estos j\u00f3venes, nacieron una cantidad de emprendimientos sociales para este barrio olvidado<\/strong> por todos, pero no olvidado por la Providencia. Instalaron un consultorio m\u00e9dico y otro de dentista, una boutique muy bonita que arregla y vende vestidos a precios accesibles, ofrecieron apoyo escolar a los ni\u00f1os del barrio. La misma municipalidad de Bogot\u00e1 se dio cuenta de la voluntad de estos j\u00f3venes que quer\u00edan rescatar el barrio y se ocup\u00f3 de proveer el abastecimiento de agua corriente, del saneamiento, de las alcantarillas, del servicio el\u00e9ctrico.<\/p>\n<p><strong>Gabrielina y Macedonio dan testimonio de una esperanza transformada en realidad.<\/strong> Hoy el analfabetismo y el alcoholismo han desaparecido de la mayor\u00eda de los habitantes. Ellos son un ejemplo y se han convertido, por la dignidad rescatada, en puntos de referencia y l\u00edderes escuchados.<\/p>\n<p><strong>El Centro social Unidad se jacta de ser una sede m\u00e1s que digna, en la cual se desarrollan programas educativos para las diversas edades<\/strong> con una sala equipada con computadoras. 75 estudiantes se benefician del sost\u00e9n a distancia coordinado por la Asociaci\u00f3n Familias Nuevas. Se realizan con regularidad cursos de recuperaci\u00f3n para 70 escolares flojos en el estudio y las actividades recreativas ocupan a otros 120 j\u00f3venes.<\/p>\n<p><strong>Hace unos a\u00f1os una docente conoci\u00f3 la iniciativa y quiso aportar profesionalmente ayuda a las madres<\/strong>. Se desarroll\u00f3 aqu\u00ed un rol fundamental, apareci\u00f3 una figura poco usual: la mam\u00e1 comunitaria. Actualmente son 15 y cada una cuida 14 ni\u00f1os, una especie de nido y refugio en el que inician educando a los ciudadanos del ma\u00f1ana.<\/p>\n<p>El tiempo pas\u00f3 al galope: <strong>\u201cEncontr\u00e9 una gran p\u00e1gina de historia sagrada \u2013comenta Giancarlo Faletti-, encontr\u00e9 el Evangelio vivo<\/strong>. Le comunicar\u00e9 a la presidente Maria Voce el precioso tesoro que son ustedes para el barrio y la ciudad\u201d Los abrazos no terminan nunca. \u00a1Y se comprende!<\/p>\n<p>Alberto Lo Presti y Paolo L\u00f2riga<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apenas lleg\u00f3 a Colombia el copresidente de los Focolares visita el Centro Social Unidad en la localidad \u201cLos Chircales\u201d, en la periferia pobre de Bogot\u00e1.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[904],"tags":[],"class_list":["post-348372","post","type-post","status-publish","format-standard","hentry","category-focolare-worldwide-2-2"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/348372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/comments?post=348372"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/348372\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/media?parent=348372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/categories?post=348372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/tags?post=348372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}