{"id":349186,"date":"2013-02-20T08:31:27","date_gmt":"2013-02-20T07:31:27","guid":{"rendered":"https:\/\/www.focolare.org\/con-b16-hacia-la-ultima-audiencia\/"},"modified":"2024-06-06T12:32:10","modified_gmt":"2024-06-06T10:32:10","slug":"con-b16-hacia-la-ultima-audiencia","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/es\/con-b16-hacia-la-ultima-audiencia\/","title":{"rendered":"Con B16 hacia la \u00faltima audiencia"},"content":{"rendered":"<p><img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-articolo_1 wp-image-80280\" style=\"border: 0px;margin: 10px\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2013\/02\/20130216-07-250x165.jpg\" alt=\"\" width=\"250\" height=\"165\" \/>Ser\u00e1 una ocasi\u00f3n \u00fanica para manifestar una vez m\u00e1s la gratitud del Movimiento de los Focolares y rezar con el Papa por el futuro de la Iglesia, junto a miles de personas que acudir\u00e1n a San Pedro.<\/p>\n<p><em><strong>\u201cSantidad, el Movimiento de los Focolares se estrecha a su alrededor en un conmovido gran agradecimiento<\/strong> por todo el amor paterno con el que siempre se ha sentido acompa\u00f1ado y sostenido\u201d.<\/em><\/p>\n<p>En el gran abrazo planetario que rodea estos \u00faltimos d\u00edas del pontificado del papa Benedicto XVI, tambi\u00e9n los Focolares han querido \u201cestar\u201d para expresarle al Santo Padre su cercan\u00eda y oraciones. En un mensaje escrito inmediatamente despu\u00e9s del anuncia difundido el 11 de febrero por la oficina de prensa vaticana,\u00a0<a href=\"https:\/\/www.focolare.org\/es\/news\/2011\/01\/20\/maria-voce\/\" target=\"_blank\" rel=\"noopener\">Mar\u00eda Voce<\/a> a nombre de todos los focolarinos del mundo <a href=\"https:\/\/www.focolare.org\/es\/news\/2013\/02\/11\/con-benedetto-xvi\/\">escribi\u00f3<\/a> al Papa: \u201c<em>Queremos que nos sienta a su lado, en profunda y continua oraci\u00f3n por la nueva fase que ahora se abre en Su vida y en la vida de la Iglesia, con fe segura en el amor de Dios a la que estamos especialmente llamados este a\u00f1o. \u00a1Lo queremos y lo seguiremos queriendo siempre!\u00bb<\/em><\/p>\n<p>El anuncio de la dimisi\u00f3n del Papa tomo al mundo de sorpresa. Fueron inmediatas las declaraciones de apoyo y de estima por ese gesto de \u201ccoraje y humildad\u201d, como ha sido definido en varias partes. Han tomado la palabra: pol\u00edticos, diversos responsables de Iglesias cristianas, l\u00edderes de las religiones, gente com\u00fan. Son el signo, por una parte, de un gesto \u00fanico en la historia y por otra, denotan el afecto y la consideraci\u00f3n de las que goza este Papa en el mundo, a todo nivel.<\/p>\n<p>\u201cLa primera reacci\u00f3n \u2013 confiesa la Presidente del Movimiento de los Focolares- fue casi de turbaci\u00f3n y ciertamente de dolor por esa \u2018disminuci\u00f3n del vigor tanto del cuerpo como del \u00e1nimo\u2019 tan sencilla y humildemente confesadas por el Papa, tanto que nos pareci\u00f3 m\u00e1s grande precisamente en esa debilidad\u201d. Y ha sido este sentimiento el que ha empujado a los focolarinos a enviarle un \u201cmensaje de agradecimiento\u201d. Pero tambi\u00e9n a leer en esta circunstancia <strong>\u201cun llamado de Dios a una nueva y mayor medida de unidad\u201d<\/strong>. Mar\u00eda Voce explica: \u201cEn este momento m\u00e1s que nunca debemos dar testimonio de nuestro carisma, estrech\u00e1ndonos en un renovado pacto planetario, de punta a punta de la tierra, para poner a disposici\u00f3n de toda la Iglesia el tesoro de la presencia del Resucitado en medio nuestro\u201d.<\/p>\n<p>El sitio de\u00a0<a title=\"Convegno per genitori in attesa\" href=\"http:\/\/www.cittanuova.it\/\" target=\"_blank\" rel=\"noopener\">Citt\u00e0 Nuova<\/a>\u00a0 dedic\u00f3 un especial a la dimisi\u00f3n del Papa que ha recibido en estos d\u00edas muchas reacciones por parte de los lectores, incluso no italianos. \u201cMuchos hacen an\u00e1lisis, apreciaciones cr\u00edticas, intelectuales, m\u00e1s o menos ben\u00e9volas: yo quiero expresar todo mi afecto por Benedicto XVI\u201d. \u201cDespu\u00e9s de la sorpresa y un momento de desconcierto&#8230; he visto en su decisi\u00f3n una confirmaci\u00f3n de la \u2018grandeza\u2019 de su figura\u201d. Y todav\u00eda: \u201cMe impresion\u00f3 que el Papa en estos meses supo custodiar su decisi\u00f3n, lo imagino en un \u2018t\u00fa a t\u00fa\u2019 continuo con Dios. Siento que esta nueva circunstancia me cuestiona personalmente y tiene mucho que ense\u00f1arme\u201d.<\/p>\n<p><strong>Y a prop\u00f3sito de este \u2018t\u00fa a t\u00fa\u2019 tambi\u00e9n el te\u00f3logo Piero Coda,<\/strong> rector del <a href=\"http:\/\/www.iu-sophia.org\" target=\"_blank\" rel=\"noopener\">Instituto universitario Sophia<\/a>, escribe: \u201cBenedicto XVI, desde el inicio de su ministerio, nos ha sorprendido por la sencillez y radicalidad con la que ha hablado de su relaci\u00f3n con Jes\u00fas, y de la relaci\u00f3n que en Jes\u00fas estamos llamados a vivir entre nosotros, en los t\u00e9rminos m\u00e1s bellos e intensos de nuestra experiencia: la amistad. El gesto inesperado con el que hoy ha anunciado su renuncia al Ministerio de Obispo de Roma y sucesor del ap\u00f3stol Pedro, es el signo m\u00e1s alto de esta amistad que nos ha regalado. Un gesto alto, que pone un sello extraordinario a su pontificado, pero que se abre a una nueva estaci\u00f3n en la forma de entender y administrar el ministerio del papado\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tambi\u00e9n numerosos focolarinos estar\u00e1n en la Plaza  San Pedro el 27 de febrero para la \u00faltima Audiencia General del Pontificado de Benedicto XVI.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[904],"tags":[],"class_list":["post-349186","post","type-post","status-publish","format-standard","hentry","category-focolare-worldwide-2-2"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/349186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/comments?post=349186"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/349186\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/media?parent=349186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/categories?post=349186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/tags?post=349186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}