{"id":349742,"date":"2013-09-26T07:11:22","date_gmt":"2013-09-26T05:11:22","guid":{"rendered":"https:\/\/www.focolare.org\/spirituality-lived-in-caritas-jordan\/"},"modified":"2024-06-06T12:33:57","modified_gmt":"2024-06-06T10:33:57","slug":"spirituality-lived-in-caritas-jordan","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/es\/spirituality-lived-in-caritas-jordan\/","title":{"rendered":"Spirituality lived in Caritas Jordan"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"C\u00e1ritas Jordania\" src=\"https:\/\/player.vimeo.com\/video\/75470547?dnt=1&amp;app_id=122963\" width=\"720\" height=\"576\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write\"><\/iframe><\/p>\n<p><strong>\u00ab<\/strong>C\u00e1ritas Jordania es un organismo afiliado a la Iglesia Cat\u00f3lica presidida por el Patriarca de Jerusal\u00e9n. Desde hace 45 a\u00f1os est\u00e1 presente en <a href=\"https:\/\/www.focolare.org\/es\/focolare-worldwide\/asia\/giordania\/\">Jordania <\/a>y hace parte de C\u00e1ritas internacional\u00bb. Quien nos lo cuenta es el director, Wael Suleiman. Y contin\u00faa: \u00abC\u00e1ritas Jordania ha respondido a la llamada de la Iglesia para ocuparse de los refugiados sirios. Hemos registrado 1 mill\u00f3n 300 mil sirios que se han introducido en Jordania, entre ellos 130 mil inscritos en la C\u00e1ritas; les ofrecemos asistencia m\u00e9dica, servicios educativos y ayuda humanitaria. Sin duda para Jordania es dif\u00edcil acoger a este n\u00famero tan elevado de refugiados con los pocos recursos del Pa\u00eds: agua, petr\u00f3leo, y todos los problemas econ\u00f3micos. Pero Jordania no quiere cerrar las puertas. El Rey ha ordenado que las fronteras permanezcan abiertas para servir a nuestros hermanos sirios. En este momento todos tratamos de ser solidarios\u201d.<\/p>\n<p>Suhad Zarafili, es la responsable de los proyectos de C\u00e1ritas Jordania: \u201cUno de nuestros programas\u00a0 -nos cuenta- es el programa de voluntariado: tenemos cerca de 30 grupos con m\u00e1s de un millar de voluntarios, cristianos y musulmanes. Ellos son los que han comenzado a visitar los campos en busca de refugiados sirios con mayores necesidades\u201d.<\/p>\n<p>Entre los voluntarios est\u00e1 Carole<strong>.<\/strong><strong> \u201c<\/strong>Estoy muy contenta -nos dice- de que Dios me haya dado la oportunidad de trabajar en C\u00e1ritas y poder ayudar a los sirios. Yo tambi\u00e9n soy de Siria y por lo tanto puedo entender mejor lo que prueban, es un comprenderse rec\u00edproco. Sufren mucho, necesitan muchas cosas: la asociaci\u00f3n les acoge y trata de darles toda la ayuda posible, hasta que nuestro Dios resuelva la situaci\u00f3n\u201d.<\/p>\n<p>Hago parte del Movimiento de los Focolares \u2013contin\u00faa diciendo el director Wael Suleiman-<strong><em> <\/em><\/strong>y esta espiritualidad, vivida por muchos aqu\u00ed en la C\u00e1ritas, nos ayuda a salir hacia el mundo, fuera de nuestro peque\u00f1o c\u00edrculo, donde vivimos y donde trabajamos, para amar m\u00e1s a todos. Viviendo la <span style=\"text-decoration: underline\">espiritualidad de la unidad<\/span> se ha formado una \u00abc\u00e9lula\u00bb al interno de C\u00e1ritas que ha ayudado a todo este desarrollo, de modo que quien viene no s\u00f3lo experimenta la ayuda, sino tambi\u00e9n el esp\u00edritu y la vida que hay detr\u00e1s de esta ayuda\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante los dos \u00faltimos a\u00f1os, han llegado a Jordania un mill\u00f3n 300.000 pr\u00f3fugos sirios. Para acogerlos, entre las muchas organizaciones, en primera l\u00ednea est\u00e1 tambi\u00e9n C\u00e1ritas Jordania, donde trabajan muchos miembros del Movimiento de los Focolares.<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[904],"tags":[],"class_list":["post-349742","post","type-post","status-publish","format-standard","hentry","category-focolare-worldwide-2-2"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/349742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/comments?post=349742"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/posts\/349742\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/media?parent=349742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/categories?post=349742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/es\/wp-json\/wp\/v2\/tags?post=349742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}