{"id":298224,"date":"2011-06-14T04:30:30","date_gmt":"2011-06-14T02:30:30","guid":{"rendered":"https:\/\/www.focolare.org\/bruna-tomasi-en-colombie-equateur-perou\/"},"modified":"2024-05-13T21:02:39","modified_gmt":"2024-05-13T19:02:39","slug":"bruna-tomasi-en-colombie-equateur-perou","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/fr\/bruna-tomasi-en-colombie-equateur-perou\/","title":{"rendered":"Bruna Tomasi en Colombie, Equateur, P\u00e9rou"},"content":{"rendered":"<p><a href=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2011\/06\/20110614-06.jpg\"><img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-media_max wp-image-39174 alignright\" style=\"margin-left: 10px;border: 0pt none\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2011\/06\/20110614-06-520x325.jpg\" alt=\"\" width=\"312\" height=\"195\" \/><\/a>  <em>\u00ab\u00a0Je suis rest\u00e9e 5 semaines en Colombie, Equateur, P\u00e9rou. Un peuple merveilleux qui semble fait pour vivre l\u2019Id\u00e9al de Chiara\u00a0\u00bb &#8211; <\/em> nous dit Bruna \u00e0 son retour, elle qui fut un t\u00e9moin direct de la naissance des Focolari. Au terme de son voyage cette lettre est arriv\u00e9e qui exprime la joie, la reconnaissance et la gratitude des centaines de personnes qui pendant ces cinq semaines ont eu la possibilit\u00e9 d\u2019une rencontre directe avec elle\u00a0: \u00ab\u00a0<em>Comme des \u00e9toiles qui font une constellation\u00a0: Chiara et ses premi\u00e8res compagnes \u00e9taient et se sentaient ainsi. Bruna Tomasi, une d\u2019entre elles, est arriv\u00e9e jusqu\u2019ici pour partager avec nous sa divine aventure\u00a0\u00bb. <\/em>  <em> <\/em>  <img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-39163\" style=\"margin-right: 10px;border: 0pt none\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2011\/06\/20110614-09.jpg\" alt=\"\" width=\"269\" height=\"202\" \/>  <strong>En Colombie, <\/strong>du 26 avril au 10 mai les rendez-vous\u00a0se succ\u00e8dent : des salutations aux 85 pr\u00eatres en\u00a0 congr\u00e8s au Centre Mariapolis de Tocanpica, aux rencontres avec la communaut\u00e9, avec les jeunes, avec les focolarini, les religieuses, les familles\u2026 De chaque coin du pays, ils sont arriv\u00e9s nombreux et pleins d\u2019enthousiasme, malgr\u00e9 les inondations, routes ferm\u00e9es \u00e0 cause des d\u00e9bordements des fleuves dans les campagnes.  <img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-39158    alignright\" style=\"margin-left: 10px;border: 0pt none\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2011\/06\/20110614-18.jpg\" alt=\"\" width=\"215\" height=\"152\" \/>  <strong>Et<\/strong> <strong> pour Bruna qu\u2019est-ce que ces quelques jours\u00a0ont \u00e9t\u00e9 ? <\/strong>En Colombie, elle est frapp\u00e9e par la pr\u00e9sence tr\u00e8s vivante de Marita Sartori, focolarine de la premi\u00e8re heure qui a v\u00e9cu dans ce Pays de 1973 \u00e0 2002 \u00ab\u00a0<em>comme une semence tomb\u00e9e dans cette terre et qui porte du fruit\u00a0\u00bb. <\/em>Elle est aussi touch\u00e9e par la nature de ce peuple tr\u00e8s actif,\u00a0 tr\u00e8s tourn\u00e9 vers l\u2019aide \u00e0 qui en a le plus besoin. En sont un exemple le \u00ab\u00a0<strong>Centre social Unit\u00e9\u00a0\u00bb<\/strong> &#8211; action sociale de nombreux membres des Focolari qui depuis plus de 30 ans s\u2019engagent dans un quartier p\u00e9riph\u00e9rique de Bogota, avec une assistance sanitaire, des \u00e9tablissements scolaires, une \u00e9ducation artistique \u2013 et l\u2019Ecole \u00ab\u00a0<strong>Sol naciente\u00a0\u00bb <\/strong>(soleil levant), proche du\u00a0 Centre Mariapolis, dans la capitale.  &nbsp;  <img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-39162\" style=\"margin-right: 10px;border: 0pt none\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2011\/06\/20110614-10.jpg\" alt=\"\" width=\"334\" height=\"269\" \/>  Le voyage se poursuit ensuite en<strong> Equateur, <\/strong> du 10 au 23 mai. \u00ab\u00a0<em>Ce qui vient le plus en \u00e9vidence de ce pays \u2013 <\/em>c\u2019est encore Bruna qui raconte<em> \u2013 est la vari\u00e9t\u00e9 culturelle. C\u2019est aussi une acceptation r\u00e9ciproque tr\u00e8s belle. Ce qui pourrait \u00eatre un obstacle, est d\u00e9j\u00e0 d\u00e9pass\u00e9.\u00a0\u00bb <\/em>A l\u2019Universit\u00e9 Andine \u00ab\u00a0Simon Bolivar\u00a0\u00bb, les 14 et 15 mai, les membres des Focolari se sont donn\u00e9 rendez-vous,\u00a0provenant des diverses r\u00e9gions: Esmeraldas, Guayas, Imbabura, Santo Domingo de los Ts\u00e0chilas, Pinchincha. Toutes les expressions d\u2019un peuple, d\u2019un peuple riche dans la diversit\u00e9. Le chant et la danse furent pr\u00e9sents, de la c\u00f4te \u00e0 la cha\u00eene centrale des Andes, comme cadeau sp\u00e9cial et remerciements pour les visiteurs\u00a0! Expressions de la diversit\u00e9 qui devient don fut la \u2018\u2019 Messe Afro\u2019\u2019 anim\u00e9e par la communaut\u00e9 d\u2019Esmeraldas. <em>\u00ab\u00a0 Que faire pour r\u00e9pandre dans tout le Pays l\u2019Id\u00e9al de l\u2019unit\u00e9\u00a0?\u00a0\u00bb<\/em> fut \u00a0une question r\u00e9currente. <em>\u00ab\u00a0Fortifier le chemin entrepris et\u2026 raviver le \u2018\u2019feu\u2019\u2019 de l\u2019amour r\u00e9ciproque\u00a0\u00bb, <\/em> consigne de Bruna \u00e0 ce peuple, un appel afin que <strong>l\u2019Equateur vive la fraternit\u00e9 en pl\u00e9nitude et la donne comme un cadeau au monde. <\/strong>  <strong> <\/strong>  <img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-39161\" style=\"margin-left: 10px;border: 0pt none\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2011\/06\/20110614-021.jpg\" alt=\"\" width=\"274\" height=\"206\" \/>  Et finalement nous arrivons au <strong>P\u00e9rou. <\/strong>Bruna Tomasi est \u00e0 Lima du 23 mai au 3 juin. Les p\u00e9ruviens ont toujours d\u00e9sir\u00e9 une visite de Chiara Lubich, et \u00ab\u00a0<em>Dieu \u00e0 travers Bruna nous a fait ce cadeau\u00a0\u00bb,<\/em>\u00e9crivent-ils. <em>\u00ab\u00a0Le peuple p\u00e9ruvien a une dignit\u00e9 ancestrale \u2013<\/em>commente Bruna &#8211; . <em>Il semble aussi que dans la tradition religieuse des Incas on trouve des traces de la R\u00e8gle d\u2019Or\u2026\u00a0\u00bb. <\/em>Dans ce pays immense, nombreux sont aussi les rendez-vous. Tr\u00e8s belle rencontre avec la communaut\u00e9 du P\u00e9rou, avec environ 320 personnes venues de chaque partie du Pays, quelques uns ayant fait <strong>plus de 30 heures de voyage<\/strong>. <em>\u00ab\u00a0Ce fut une f\u00eate \u2013 <\/em>\u00e9crivent-ils de Lima -. <em>En 1989, au P\u00e9rou, <strong>le terrorisme <\/strong>\u00e9tait une r\u00e9alit\u00e9 et de nombreuses personnes quittaient le Pays, mais justement cette ann\u00e9e l\u00e0 est arriv\u00e9 le focolare \u00e0 Lima, soulignant de cette fa\u00e7on que notre r\u00e9volution d\u2019amour est plus forte que tout\u00a0\u00bb. <\/em> Rencontre importante avec le Nonce apostolique, Mons. Bruno Musaro, avec le Cardinal de Lima, Mons. Juan Luis Cipriani et les autres \u00e9v\u00eaques pr\u00e9sents. Ils ont tous manifest\u00e9 leur estime pour Chiara et son charisme.  &nbsp;  <em>\u00ab\u00a0L\u2019Id\u00e9al de Chiara \u2013 <\/em>conclut Bruna \u00e0 notre journaliste \u2013 <em>est fait pour le \u2018\u2019rapport\u2019\u2019 avec l\u2019autre \u00e0 n\u2019importe quel niveau, n\u2019importe quelle foi et \u00e9galement au niveau culturel. C\u2019est un d\u00e9fi, mais en vivant la charit\u00e9 on d\u00e9passe toutes les diff\u00e9rences.\u00a0\u00bb<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab Un peuple merveilleux, ouvert, avec beaucoup de vitalit\u00e9 et d\u2019initiatives \u00bb. Ainsi parle  Bruna \u2013 une  parmi les premi\u00e8res qui ont commenc\u00e9 avec Chiara l\u2019aventure focolarine \u2013 \u00e0 son retour de voyage en Am\u00e9rique Latine du 26 avril au 3 juin 2011.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[906],"tags":[],"class_list":["post-298224","post","type-post","status-publish","format-standard","hentry","category-focolare-worldwide-2-3"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts\/298224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/comments?post=298224"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts\/298224\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/media?parent=298224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/categories?post=298224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/tags?post=298224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}