{"id":312502,"date":"2017-10-31T02:10:30","date_gmt":"2017-10-31T01:10:30","guid":{"rendered":"https:\/\/www.focolare.org\/du-conflit-a-la-communion\/"},"modified":"2024-05-15T20:55:06","modified_gmt":"2024-05-15T18:55:06","slug":"du-conflit-a-la-communion","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/fr\/du-conflit-a-la-communion\/","title":{"rendered":"Du conflit \u00e0 la communion"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2017\/10\/2017-08-24-Erfurt-cella-del-monastero-di-Lutero-66.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-157685\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2017\/10\/2017-08-24-Erfurt-cella-del-monastero-di-Lutero-66.jpg\" alt=\"2017-08-24-Erfurt cella del monastero di Lutero (66)\" width=\"250\" height=\"333\" \/><\/a>31 octobre 1517. <\/strong>Il y a cinq si\u00e8cles, le moine augustinien Martin Luther, professeur de th\u00e9ologie \u00e0 l\u2019Universit\u00e9 de Wittenberg, adressait \u00e0 l\u2019archev\u00eaque de Brandebourg et puis \u00e0 un certain nombre de coll\u00e8gues th\u00e9ologien, une lettre de pr\u00e9sentation de ses 95 Th\u00e8ses, afin qu\u2019elles deviennent objet de discussion acad\u00e9mique. Il \u00e9crivait\u00a0:<em>\u00a0\u00ab\u00a0Par amour et d\u00e9sir d\u2019\u00e9lucider la v\u00e9rit\u00e9, les th\u00e8ses soussign\u00e9es <\/em>\u00a0<em>seront discut\u00e9es \u00e0 Wittenberg, sous la pr\u00e9sidence du R\u00a0.P. Martin Luther\u00a0\u00bb. <\/em>  <strong>31 octobre 2017.<\/strong> Cinq si\u00e8cles sont pass\u00e9s depuis lors. Mais aujourd\u2019hui, gr\u00e2ce au dialogue th\u00e9ologique commenc\u00e9 par le Concile Vatican II, pour les catholiques et les luth\u00e9riens, il est possible de revoir le pass\u00e9 et, de ces blessures, demander r\u00e9ciproquement pardon.  <strong>Le 31 octobre d\u2019il y a un an,<\/strong> la <a href=\"https:\/\/www.focolare.org\/fr\/news\/2016\/11\/04\/in-svezia-commemorati-i-500-anni-dalla-riforma\/\" target=\"_blank\" rel=\"noopener\">pri\u00e8re commune<\/a> prononc\u00e9e \u00e0 Lund en Su\u00e8de, avec la pr\u00e9sence du Pape Fran\u00e7ois et de l\u2019\u00c9v\u00eaque Younan, alors pr\u00e9sident de la F\u00e9d\u00e9ration mondiale luth\u00e9rienne, ouvrait l\u2019ann\u00e9e de comm\u00e9moration commune de la R\u00e9forme protestante. <em>\u00ab\u00a0Alors que nous surmontons ces<\/em> <em>\u00e9pisodes de l\u2019histoire qui p\u00e8sent sur nous <\/em>\u2013 peut-on lire dans la d\u00e9claration \u2013<em> nous nous engageons \u00e0 t\u00e9moigner ensemble la gr\u00e2ce mis\u00e9ricordieuse de Dieu et \u00e0 grandir ult\u00e9rieurement dans la communion enracin\u00e9e dans le Bapt\u00eame, en essayant d\u2019\u00e9liminer les derniers obstacles qui nous emp\u00eachent de rejoindre la pleine unit\u00e9. Christ d\u00e9sire que nous soyons un, afin que le monde croie (cfr Jn 17,2)\u00a0\u00bb.<\/em>  <strong>Il conclut avec un appel, adress\u00e9 \u00e0 tous, \u00e0 progresser dans la communion vers la pleine et visible unit\u00e9\u00a0: <em>\u00ab\u00a0<\/em><\/strong><em>Nous invitons nos compagnons de route sur le chemin \u0153cum\u00e9nique \u00e0 nous rappeler nos engagements et \u00e0 nous encourager. Nous leur demandons de continuer \u00e0 prier pour nous, de cheminer avec nous\u00a0\u00bb. <\/em>  <strong><a href=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2017\/10\/2017-08-23-Wittenberg.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-157682 alignright\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2017\/10\/2017-08-23-Wittenberg.jpg\" alt=\"2017-08-23-Wittenberg\" width=\"368\" height=\"276\" \/><\/a><\/strong>Le <a href=\"https:\/\/www.focolare.org\/fr\/chi-siamo\/\" target=\"_blank\" rel=\"noopener\">Mouvement des Focolari<\/a> ne pouvait pas ne pas sentir sien cet appel. Avec la <a href=\"https:\/\/www.focolare.org\/fr\/news\/2017\/02\/22\/nuovo-impegno-ecumenico-dei-focolari\/\" target=\"_blank\" rel=\"noopener\">D\u00e9claration de Ottmaring<\/a>, du nom de la citadelle \u0153cum\u00e9nique o\u00f9 elle a \u00e9t\u00e9 sign\u00e9e, <a href=\"https:\/\/www.focolare.org\/fr\/news\/2014\/09\/15\/maria-voce\/\" target=\"_blank\" rel=\"noopener\">Maria Voce<\/a> et <a href=\"https:\/\/www.focolare.org\/frnews\/2014\/09\/17\/jesus-moran-cepedano\/\" target=\"_blank\" rel=\"noopener\">Jes\u00fas Mor\u00e1n<\/a>, au nom du Mouvement tout entier, ont souscrit \u00e0 la pleine adh\u00e9sion \u00e0 l\u2019invitation de Lund.  <strong>Pendant toute l\u2019ann\u00e9e, <\/strong>de nombreuses rencontres, congr\u00e8s, journ\u00e9es \u0153cum\u00e9niques et moments de pri\u00e8re commune, r\u00e9alis\u00e9s en diff\u00e9rents lieux et contextes et organis\u00e9s presque toujours avec les \u00e9glises locales, ont \u00e9t\u00e9 l\u2019occasion d\u2019approfondir les tr\u00e9sors des diff\u00e9rentes traditions chr\u00e9tiennes, non seulement catholique et luth\u00e9rienne, dans une r\u00e9elle atmosph\u00e8re de famille.  <strong>Au cours du mois de mai, durant la semaine \u0153cum\u00e9nique,<\/strong><em> En <a href=\"https:\/\/www.focolare.org\/fr\/news\/2017\/05\/10\/camminando-insieme-cristiani-sulla-via-verso-lunita\/\" target=\"_blank\" rel=\"noopener\">cheminant ensemble<\/a>,<\/em> qui s\u2019est d\u00e9roul\u00e9e au Centre Mariapolis de Castel Gandolfo (Rome) avec la pr\u00e9sence de presque 700 personnes issues de 42 pays et 69 \u00e9glises diff\u00e9rentes, Maria Voce, a reconnu dans les \u2018\u2019cinq imp\u00e9ratifs\u2019\u2019 du document catholique et luth\u00e9rien\u00a0 \u2018\u2019Du conflit \u00e0 la communion\u2019\u2019, la base de tout engagement \u0153cum\u00e9nique fructueux.  <strong>Les pr\u00e9sentations de la biographie<\/strong> <em>Luther <\/em><strong>furent aussi nombreuses.<\/strong> <em>L\u2019homme de la r\u00e9volution <\/em>sign\u00e9 par Mario Dal Bello, par l\u2019\u00e9ditrice <a href=\"https:\/\/www.cittanuova.it\/lutero-luomo-della-rivoluzione\/\" target=\"_blank\" rel=\"noopener\">Citt\u00e0 Nuova<\/a>,  <strong>En Italie,<\/strong> \u00e0 Turin et Bra, la communaut\u00e9 des Focolari a organis\u00e9 deux soir\u00e9es avec les interventions d\u2019Hubertus Blaumeiser, expert catholique de Luther et du Prof. Paolo Ricca, vaudois.  <strong><a href=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2017\/10\/2017-giornata-Olanda.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-157683\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2017\/10\/2017-giornata-Olanda.jpg\" alt=\"2017-giornata Olanda\" width=\"368\" height=\"207\" \/><\/a>En Hollande, <\/strong>les leaders des principales \u00e9glises chr\u00e9tiennes ont lanc\u00e9 au mois de mars, la journ\u00e9e\u00a0:<em> L\u2019unit\u00e9 en chemin.<\/em>  <strong>Au Br\u00e9sil<\/strong>, apr\u00e8s un symposium organis\u00e9 par la commission \u0153cum\u00e9nique nationale sur le Commentaire de Luther au Magnificat, \u00e0 la Mariapolis Ginetta, une soir\u00e9e sur le th\u00e8me a \u00e9t\u00e9\u00a0 suivie via streaming, en 650 points d\u2019\u00e9coute, aussi par de nombreux jeunes.  Au Venezuela, diff\u00e9rentes rencontres et moments de pri\u00e8re ont \u00e9t\u00e9 soutenus par les Focolari.  <strong>A la Mariapolis Fiore de la Pologne,<\/strong> au cours du mois de septembre, la journ\u00e9e \u00e0 l\u2019occasion du cinqui\u00e8me centenaire a \u00e9t\u00e9 l\u2019occasion d\u2019un t\u00e9moignage particulier, celui des quinze ann\u00e9es de p\u00e8lerinage \u0153cum\u00e9nique entre le peuple polonais et allemand.  <strong>En Irlande<\/strong>, \u00e0 l\u2019initiative du Mouvement des Focolari et de l\u2019\u00c9glise luth\u00e9rienne, on a r\u00e9alis\u00e9 des \u00e9tudes, des conf\u00e9rences et une <em>Semaine \u0153cum\u00e9nique de la Bible,<\/em> qui a aussi impliqu\u00e9 les \u00e9glises anglicane et presbyt\u00e9rienne.  <strong>Des voyages <\/strong>vers des lieux significatifs de la R\u00e9forme et de la vie de Luther<strong> n\u2019ont pas manqu\u00e9. <\/strong>  Au cours du mois d\u2019ao\u00fbt, un s\u00e9minaire sur Luther \u00e0 Zwochau (Allemagne centrale), avec une cinquantaine de catholiques, luth\u00e9riens, vaudois et une copte-orthodoxe, tous originaires de diff\u00e9rents pays europ\u00e9ens, mais aussi de l\u2019\u00c9gypte et de l\u2019Argentine.\u00a0 Au programme \u00e9galement, la visite du ch\u00e2teau Wartburg et de la ville de Wittenberg, d\u2019Erfurt (o\u00f9 le jeune Luther entra au monast\u00e8re des augustiniens) et de Leipzig, dans laquelle son h\u00e9ritage s\u2019est rencontr\u00e9 avec le g\u00e9nie musical de J.S.Bach.  <strong>Un groupe italien<\/strong> s\u2019est rendu dans un autre lieu significatif, la ville d\u2019Augusta, afin de conna\u00eetre aussi la citadelle \u0153cum\u00e9nique de Ottmaring. Un p\u00e8lerinage semblable s\u2019est d\u00e9roul\u00e9 en juin, organis\u00e9 par la commission \u0153cum\u00e9nique de Hong Kong, avec l\u2019accompagnement de quelques focolarini.  <strong>En Su\u00e8de<\/strong>, la communaut\u00e9 du Focolare a sign\u00e9 solennellement \u2018\u2019les imp\u00e9ratifs\u2019\u2019 et consign\u00e9 les signatures \u00e0 l\u2019archev\u00eaque luth\u00e9rien. Le groupe musical <a href=\"http:\/\/www.genverde.it\/\" target=\"_blank\" rel=\"noopener\">Gen Verde<\/a> a aussi contribu\u00e9, avec le spectacle<em> On the other side<\/em>, \u00e0 la c\u00e9l\u00e9bration de l\u2019ann\u00e9e de comm\u00e9moration \u00e0 Stadthagen (Allemagne).  <strong>Ce sont quelques pas sur une route encore longue<\/strong>, qui s\u2019ajoutent \u00e0 beaucoup d\u2019autres mais qui indiquent d\u00e9j\u00e0 la direction du chemin vers la recherche commune de v\u00e9rit\u00e9 et de salut, avec un regard tourn\u00e9 vers toutes les \u00e9glises. D\u00e9but d\u2019une nouvelle page d\u2019histoire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd\u2019hui, le 31 octobre 2017, on c\u00e9l\u00e8bre les 500 ans de la R\u00e9forme luth\u00e9rienne. Les nombreux pas r\u00e9alis\u00e9s dans le cheminement tourment\u00e9 vers la pleine et visible unit\u00e9. La contribution du Mouvement des Focolari.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[47],"tags":[],"class_list":["post-312502","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts\/312502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/comments?post=312502"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts\/312502\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/media?parent=312502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/categories?post=312502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/tags?post=312502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}