{"id":313482,"date":"2018-11-11T01:10:29","date_gmt":"2018-11-11T00:10:29","guid":{"rendered":"https:\/\/www.focolare.org\/il-y-a-cent-ans-sachevait-la-grande-guerre\/"},"modified":"2024-05-15T20:58:05","modified_gmt":"2024-05-15T18:58:05","slug":"il-y-a-cent-ans-sachevait-la-grande-guerre","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/fr\/il-y-a-cent-ans-sachevait-la-grande-guerre\/","title":{"rendered":"Il y a cent ans s&rsquo;achevait la Grande Guerre"},"content":{"rendered":"<p><strong>Le 11 novembre on c\u00e9l\u00e8bre le centenaire de la fin de la Premi\u00e8re Guerre Mondiale<\/strong>, suivie de la Conf\u00e9rence de Paix de Paris (18 janvier 1919 \u2013 21 janvier 1920). Mais durant au moins cinq ans dans toute l\u2019Europe continueront des r\u00e9volutions violentes en tout genre: en Finlande tout comme en Anatolie, au Caucase et en Irlande, en Allemagne et en Gr\u00e8ce.  <strong>\u00a0\u00ab\u00a0Les guerres sont toujours tragiques\u00a0\u00bb, a d\u00e9clar\u00e9 le Pr\u00e9sident de la R\u00e9publique italienne Sergio Mattarella<\/strong>, le 4 novembre dernier, reprenant les propos de l\u2019\u00e9crivain<strong> Claudio Magris<\/strong>\u00a0:\u00a0<em>chaque pays pensait donner une belle petite le\u00e7on \u00e0 son ennemi le plus proche, en en retirant des avantages territoriaux ou autres. Personne n&rsquo;imaginait que cette guerre puisse \u00eatre aussi terrible, ni durer aussi longtemps<\/em>. En ces temps o\u00f9 soufflent encore une fois \u00a0des vents de guerre, que la c\u00e9l\u00e9bration de \u00a0ce centenaire nous incite \u00e0 pers\u00e9v\u00e9rer dans le processus d\u2019int\u00e9gration et d\u2019unification europ\u00e9enne, uniques garanties en vue d\u2019une paix durable\u00a0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 11 novembre on c\u00e9l\u00e8bre le centenaire de la fin de la Premi\u00e8re Guerre Mondiale, suivie de la Conf\u00e9rence de Paix de Paris (18 janvier 1919 \u2013 21 janvier 1920). Mais durant au moins cinq ans dans toute l\u2019Europe continueront des r\u00e9volutions violentes en tout genre: en Finlande tout comme en Anatolie, au Caucase et [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[47],"tags":[],"class_list":["post-313482","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts\/313482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/comments?post=313482"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts\/313482\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/media?parent=313482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/categories?post=313482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/tags?post=313482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}