{"id":330008,"date":"2014-11-19T04:00:29","date_gmt":"2014-11-19T03:00:29","guid":{"rendered":"https:\/\/www.focolare.org\/coree-le-mystere-de-la-vie\/"},"modified":"2024-05-16T15:10:19","modified_gmt":"2024-05-16T13:10:19","slug":"coree-le-mystere-de-la-vie","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/fr\/coree-le-mystere-de-la-vie\/","title":{"rendered":"Cor\u00e9e, le myst\u00e8re de la vie"},"content":{"rendered":"<p><p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-114564\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2014\/11\/geriatric_nursing.jpg\" alt=\"geriatric_nursing\" width=\"320\" height=\"213\" \/>Cielo Lee Young-Hee travaille comme infirmi\u00e8re \u00e0 domicile <\/strong>pour un h\u00f4pital \u00e0 S\u00e9oul. En <a href=\"https:\/\/www.focolare.org\/fr\/focolare-worldwide\/asia\/corea-del-sud\/\">Cor\u00e9e<\/a>, le pourcentage de suicide des personnes \u00e2g\u00e9es de plus de 80\u00a0ans est le plus \u00e9lev\u00e9 au monde. \u00ab\u00a0Apr\u00e8s avoir lu certaines donn\u00e9es, j\u2019ai commenc\u00e9 \u00e0 travailler avec un grand engagement pour la pr\u00e9vention, puisque 50% de mes patients ont justement plus de 80\u00a0ans.\u00a0\u00bb Apr\u00e8s une exp\u00e9rience n\u00e9gative avec une patiente fortement d\u00e9prim\u00e9e, Cielo Lee d\u00e9cide d\u2019organiser un cours sur la pr\u00e9vention du suicide pour 100\u00a0professionnels en g\u00e9riatrie et 30\u00a0b\u00e9n\u00e9voles qui aident dans les paroisses. \u00ab\u00a0En visitant chaque semaine environ 40\u00a0patients \u00e0 haut risque, avec un autre coll\u00e8gue nous avons \u00e9valu\u00e9 leur \u00e9tat d\u2019\u00e2me selon des param\u00e8tres de sant\u00e9. Sur la base des r\u00e9sultats, nous avons d\u00e9cid\u00e9 de rendre visite deux fois par semaine aux dix personnes \u00e0 plus haut risque.\u00a0\u00bb<\/p>\n<p><strong>Le projet \u00ab\u00a0Gate-keeper\u00a0\u00bb <\/strong>\u2013 litt\u00e9ralement \u00ab\u00a0gardien\u00a0\u00bb, mais aussi une sorte de \u00ab\u00a0garde du corps\u00a0\u00bb \u2013 est un des services publics promu par le gouvernement de S\u00e9oul. Il est offert dans chaque quartier de la capitale pour pr\u00e9venir les suicides, en collaboration \u00e9troite avec les structures de sant\u00e9 locales. \u00ab\u00a0Dans ce projet \u2013 explique Cielo Lee \u2013 nous formons aussi des personnes \u00e2g\u00e9es comme <em>gate-keeper.<\/em> Avec les infirmiers, ces contemporains vont rendre visite aux patients en donnant des conseils de sant\u00e9 utiles.\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0<strong>Avec le d\u00e9sir de prot\u00e9ger la vie m\u00eame d\u2019une seule personne<\/strong>, au travail j\u2019ai communiqu\u00e9 mon intention \u00e0 une S\u0153ur, infirmi\u00e8re en chef, et ensuite 60 de mes coll\u00e8gues infirmi\u00e8res ont particip\u00e9 \u00e0 ce cours de pr\u00e9vention.\u00a0\u00bb<\/p>\n<p><strong>Un des patients souffrait d\u2019une maladie grave depuis 10\u00a0ans:<\/strong> \u00ab\u00a0Avant d&rsquo;entrer chez lui \u2013 raconte-t-elle \u2013 je priais et j&rsquo;essayais ensuite de bien \u00e9couter ce qu\u2019il me disait. Depuis quelque temps, ce patient s\u2019est rapproch\u00e9 de la pri\u00e8re et r\u00e9cup\u00e8re des conditions stables.\u00a0\u00bb<\/p>\n<p><strong>Une amie souffrait d\u2019insomnie apr\u00e8s avoir perdu son fils a\u00een\u00e9.<\/strong> Elle r\u00e9ussissait \u00e0 dormir seulement avec l\u2019aide de m\u00e9dicaments. Cependant, apr\u00e8s avoir fr\u00e9quent\u00e9 le cours, elle prend soin d\u2019une dame \u00e2g\u00e9e sans famille qui vit pr\u00e8s de chez elle. Maintenant, elle peut dormir sans m\u00e9dicaments et elle est reconnaissante de pouvoir aider d&rsquo;autres personnes.<\/p>\n<p><strong>\u00ab\u00a0Un jour, le t\u00e9l\u00e9phone sonne\u00a0\u00bb <\/strong>\u2013 raconte encore Cielo Lee. \u00ab\u00a0C\u2019\u00e9tait le centre de sant\u00e9 mentale avec lequel je travaille. J\u2019ai \u00e9t\u00e9 inform\u00e9e que le maire de S\u00e9oul allait donner un prix \u00e0 une personne dans chaque quartier et j&rsquo;avais \u00e9t\u00e9 propos\u00e9e \u00e0 l&rsquo;unanimit\u00e9! Quelques jours apr\u00e8s, j\u2019ai re\u00e7u un autre prix du directeur de l\u2019h\u00f4pital.\u00a0\u00bb<\/p>\n<p>Les membres du <a href=\"https:\/\/www.focolare.org\/fr\/movimento-dei-focolari\/\">Mouvement des Focolari<\/a> \u00e0 S\u00e9oul qui ont fr\u00e9quent\u00e9 le cours ont \u00e9crit que c\u2019\u00e9tait \u00ab\u00a0une occasion pr\u00e9cieuse d\u2019approfondir la connaissance du myst\u00e8re de la vie et d&rsquo;aller vers les p\u00e9riph\u00e9ries existentielles\u00a0\u00bb.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une infirmi\u00e8re qui travaille dans le domaine g\u00e9riatrique partage ses exp\u00e9riences, surtout lorsque pour les patients, la vie perd son sens et la douleur se fait plus insupportable. Un cours de pr\u00e9vention rassemble plus de 100 professionnels de la sant\u00e9, avec le d\u00e9sir de sauver beaucoup de vies.<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[47],"tags":[],"class_list":["post-330008","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts\/330008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/comments?post=330008"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts\/330008\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/media?parent=330008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/categories?post=330008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/tags?post=330008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}