{"id":331234,"date":"2016-03-17T05:00:15","date_gmt":"2016-03-17T04:00:15","guid":{"rendered":"https:\/\/www.focolare.org\/au-milieu-des-sdf-de-la-gare-de-rome\/"},"modified":"2024-05-16T15:15:21","modified_gmt":"2024-05-16T13:15:21","slug":"au-milieu-des-sdf-de-la-gare-de-rome","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/fr\/au-milieu-des-sdf-de-la-gare-de-rome\/","title":{"rendered":"Au milieu des SDF de la gare de Rome"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2016\/03\/image2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-136263\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2016\/03\/image2.jpg\" alt=\"image2\" width=\"180\" height=\"303\" \/><\/a><\/strong><strong>\u00ab J\u2019ai commenc\u00e9 \u00e0 donner un coup de main en d\u00e9cembre 2014, raconte Annette, <\/strong><a href=\"https:\/\/www.focolare.org\/fr\/movimento-dei-focolari\/scelte-e-impegno\/focolarini\/\">focolarine <\/a><strong>allemande<\/strong>. Le froid s\u2019\u00e9tait d\u00e9j\u00e0 abattu et on avait urgemment besoin de couvertures. Je voulais en savoir plus lorsque quelqu\u2019un de l\u2019association <a href=\"http:\/\/www.romamor-onlus.com\/\" target=\"_blank\" rel=\"noopener\">RomAmoR<\/a> m\u2019a propos\u00e9 : \u00ab Plus que d\u2019apporter des couvertures on aurait besoin que tu viennes nous donner un coup de main en \u00e9tant avec eux \u00bb. La semaine suivante j\u2019\u00e9tais d\u00e9j\u00e0 \u00e0 la gare d\u2019Ostiense. Ce fut une grande \u00e9motion. Pendant que je m\u2019approchais de ces personnes, je d\u00e9couvrais que, paradoxalement, c\u2019\u00e9taient elles qui m\u2019accueillaient ! Je me rendais compte qu\u2019il ne s\u2019agissait pas d\u2019une cat\u00e9gorie de gens qui d\u00e9rangent et qu\u2019il faut \u00e9viter, mais de personnes d\u00e9sireuses de relations, capables de transmettre la chaleur humaine. Peu apr\u00e8s sont arriv\u00e9s les b\u00e9n\u00e9voles avec le d\u00eener et la gare, lieu anonyme, froid et gris, s\u2019est r\u00e9chauff\u00e9e \u00bb.  <div id=\"attachment_136262\" style=\"width: 368px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2016\/03\/20160317-01.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-136262\" class=\"wp-image-136262\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2016\/03\/20160317-01.jpg\" alt=\"20160317-01\" width=\"358\" height=\"269\" \/><\/a><p id=\"caption-attachment-136262\" class=\"wp-caption-text\">Foto \u00a9 Dino Impagliazzo<\/p><\/div>  <strong>A partir de ce lundi, la vie d\u2019Annette a chang\u00e9<\/strong>. Les premi\u00e8res nuits, elle ne r\u00e9ussissait pas \u00e0 dormir en pensant \u00e0 Giovanni, Stefane, Mohamed qui n\u2019avaient pas de toit au chaud comme le sien. Elle a commenc\u00e9 \u00e0 ouvrir son armoire, y aurait-il peut-\u00eatre quelque chose \u00e0 partager, bien qu\u2019au focolare on essaie de vivre avec le strict minimum. Mais elle a surtout continu\u00e9 \u00e0 se rendre \u00e0 la gare tous les lundis. Un soir, en fouinant dans le carnet o\u00f9 l\u2019on \u00e9crivait les n\u00e9cessit\u00e9s des SDF, elle a vu qu\u2019ils avaient besoin de chaussures d\u2019hommes. Elle n\u2019en avait pas chez elle. Elle s\u2019est rappel\u00e9 l\u2019exp\u00e9rience de Chiara Lubich pendant la guerre quand elle avait demand\u00e9 \u00e0 J\u00e9sus, pr\u00e9sent dans les pauvres, ce dont ils avaient besoin. \u00ab J\u2019ai fait pareil et dans les quinze jours qui suivirent \u2013 raconte Annette &#8211; 10 paires me sont arriv\u00e9es ! \u00bb.  <strong>Avec l\u2019arriv\u00e9e de l\u2019automne, le besoin de couvertures a doubl\u00e9<\/strong>. Deux amies de Rome ont f\u00eat\u00e9 leur anniversaire, elles ont alors pens\u00e9 demander comme cadeau: \u00ab des couvertures \u00bb. Un paquet est arriv\u00e9, mais cela ne suffisait pas. Ne pouvant pas donner celles de la maison (elles n\u2019avaient gard\u00e9 que le strict n\u00e9cessaire), Annette les a encore demand\u00e9es \u00e0 J\u00e9sus, afin que Lui puisse se chauffer dans ces pauvres. \u00ab Quelques jours plus tard \u2013 raconte-t-elle avec surprise \u2013 un centre pour \u00e9tudiants en th\u00e9ologie d\u00e9m\u00e9nageait et nous a fait parvenir quatre grands sacs contenant 30 couvertures et une dizaine de matelas pour camping. Sans compter ce qu\u2019avaient r\u00e9colt\u00e9 les autres b\u00e9n\u00e9voles \u00bb.  <strong>Le partage fait tache d\u2019huile.<\/strong> Le voisin d\u2019une coll\u00e8gue, qui avait perdu confiance en toute activit\u00e9 de solidarit\u00e9, a donn\u00e9 un tas de v\u00eatements chauds et a invit\u00e9 aussi un ami \u00e0 faire de m\u00eame. \u00ab Mais l\u2019exp\u00e9rience que nous faisons est encore plus forte que ces interventions de la Providence \u2013 confie Annette \u2013. Ces personnes n\u2019ont rien \u00e0 manger, n\u2019ont pas de toit, mais peu \u00e0 peu elles acqui\u00e8rent leur dignit\u00e9 parce qu\u2019elles sont mieux habill\u00e9es et plus propres, mais aussi parce qu\u2019ensemble, nous vivons des rapports de fraternit\u00e9. Chaque fois j\u2019essaie de vraiment accueillir l\u2019autre en me mettant dans la disposition d\u2019\u00eatre un petit instrument de l\u2019amour de Dieu. Et eux me donnent la possibilit\u00e9 de t\u00e9moigner de l\u2019\u00e9vangile \u00ab dans la rue \u00bb, en partageant avec ces personnes venues du monde entier et dont les id\u00e9es et les opinions sont des plus vari\u00e9es. Dans cette r\u00e9ciprocit\u00e9, la r\u00e9alit\u00e9 change, la ville prend un autre visage. On peut toucher l\u2019amour du doigt\u2026 m\u00eame \u00e0 travers un simple d\u00eener chaud. A No\u00ebl nous avons eu un cadeau sp\u00e9cial : deux amis de la gare sont venus f\u00eater avec nous au focolare, \u00e0 la grande joie de tout le monde \u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>800 plats chauds par semaine : lundi et mardi \u00e0 Ostiense, samedi et dimanche \u00e0 Tuscolana. Un projet de l\u2019association RomAmoR qui implique plus de 200 b\u00e9n\u00e9voles.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[906,907],"tags":[],"class_list":["post-331234","post","type-post","status-publish","format-standard","hentry","category-focolare-worldwide-2-3","category-senza-categoria-2-3"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts\/331234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/comments?post=331234"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts\/331234\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/media?parent=331234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/categories?post=331234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/tags?post=331234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}