{"id":331842,"date":"2016-11-10T04:00:18","date_gmt":"2016-11-10T03:00:18","guid":{"rendered":"https:\/\/www.focolare.org\/dialogue-parole-cle-de-ma-vie\/"},"modified":"2024-05-16T15:17:37","modified_gmt":"2024-05-16T13:17:37","slug":"dialogue-parole-cle-de-ma-vie","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/fr\/dialogue-parole-cle-de-ma-vie\/","title":{"rendered":"Dialogue : parole-cl\u00e9 de ma vie"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-144657 alignright\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2016\/11\/Machado1_FotoRaulSilva.jpg\" alt=\"Mons.Machado_FotoRaulSilva\" width=\"386\" height=\"212\" \/><\/strong>Mgr. Felix Machado est un passionn\u00e9 du dialogue interreligieux. L&rsquo;amiti\u00e9 qui le lie \u00e0 de nombreux leaders de diff\u00e9rentes religions en t\u00e9moigne dont une en particulier, la grande sp\u00e9cialiste hindoue Dr. Kala Acharya. Chacun parle de l&rsquo;autre en l&rsquo;appelant \u00a0\u00bbmon fr\u00e8re F\u00e9lix\u00a0\u00bb et \u00a0\u00bbma s\u0153ur Kala\u00a0\u00bb, confirmant ainsi le profond partage qui les a amen\u00e9s \u00e0 consid\u00e9rer la fraternit\u00e9 universelle comme un point commun.  <em>Monseigneur, comment expliquez-vous votre propension au dialogue\u00a0?<\/em>  \u00ab\u00a0J&rsquo;ai grandi dans un culture rurale et cosmopolite. Vasai, en effet, si\u00e8ge actuel de mon minist\u00e8re est aussi ma ville natale. Apr\u00e8s avoir \u00e9tudi\u00e9 la th\u00e9ologie en France et aux \u00c9tats-Unis de 1999 \u00e0 2008, j&rsquo;ai prest\u00e9 un service aupr\u00e8s du Conseil pour le Dialogue Interreligieux au Vatican. L\u00e0 j&rsquo;ai pu acqu\u00e9rir beaucoup d&rsquo;\u00e9l\u00e9ments en la mati\u00e8re et comprendre que la cl\u00e9 r\u00e9side dans le fait d&rsquo;\u00e9tablir des rapports r\u00e9els et authentiques avec les personnes qui sont diff\u00e9rentes de nous. Et donc, qu&rsquo;ils soient leaders ou sp\u00e9cialistes, paysans ou p\u00eacheurs, il est de mon devoir de chr\u00e9tien de voir chacun comme mon fr\u00e8re ou ma s\u0153ur dans le Christ. Le v\u00e9ritable dialogue peut jaillir seulement d&rsquo;une profonde \u00e9coute, du fait d&rsquo;accepter l&rsquo;autre et puis, si c&rsquo;est n\u00e9cessaire, on peut offrir les propres id\u00e9aux comme un cadeau. Voil\u00e0 pourquoi j&rsquo;appr\u00e9cie le travail interreligieux r\u00e9alis\u00e9 par le Mouvement des Focolari, ici en Inde. Il s&rsquo;agit d&rsquo;une action bas\u00e9e sur l&rsquo;authenticit\u00e9, sur la confiance et la bonne volont\u00e9 avec nos fr\u00e8res et s\u0153urs hindous\u00a0\u00bb.  <strong><em><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-144660 alignleft\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2016\/11\/Machado2_FotoRaulSilva.jpg\" alt=\"Machado2_FotoRaulSilva\" width=\"386\" height=\"212\" \/><\/em><\/strong><em>Apr\u00e8s son voyage en Inde au d\u00e9but de cette ann\u00e9e, <a href=\"https:\/\/www.focolare.org\/fr\/news\/2014\/09\/15\/maria-voce\/\" target=\"_blank\" rel=\"noopener\">Maria Voce<\/a>, pr\u00e9sidente des Focolari, a racont\u00e9 qu\u00a0&lsquo;elle avait re\u00e7u un accueil chaleureux de votre part.<\/em>  \u00ab\u00a0J&rsquo;ai \u00e9t\u00e9 heureux de lui souhaiter la bienvenue dans mon dioc\u00e8se de Vasai et de me souvenir avec elle des premiers contacts que j&rsquo;ai eus avec le Mouvement \u00e0 travers deux focolarine qui travaillaient aupr\u00e8s du Conseil Pontifical pour le Dialogue interreligieux. J&rsquo;avais \u00e9t\u00e9 impressionn\u00e9 par le grand amour qu&rsquo;elles mettaient dans les activit\u00e9s les plus simples. C&rsquo;est ainsi que je fus int\u00e9ress\u00e9 \u00e0 conna\u00eetre de plus pr\u00e8s les Focolari et j&rsquo;ai eu bien vite le privil\u00e8ge de rencontrer <a href=\"https:\/\/www.focolare.org\/fr\/chiara-lubich\/\" target=\"_blank\" rel=\"noopener\">Chiara Lubich<\/a>. Elle \u00e9tait simple, directe et croyait dans l&rsquo;unit\u00e9. Cette voie vers l&rsquo;unit\u00e9, elle l&rsquo;a offerte \u00e0 l&rsquo;humanit\u00e9 \u00e0 travers l\u2019\u00c9glise, en restant profond\u00e9ment fid\u00e8le \u00e0 celle-ci et en travaillant pour l&rsquo;unit\u00e9 de la famille humaine. Je suis heureux de voir comme en <a href=\"https:\/\/www.focolare.org\/fr\/focolare-worldwide\/asia\/india\/\" target=\"_blank\" rel=\"noopener\">Inde<\/a>, les <a href=\"https:\/\/www.focolare.org\/fr\/chi-siamo\/\" target=\"_blank\" rel=\"noopener\">Focolari<\/a> portent de l&rsquo;avant cet h\u00e9ritage par le biais du dialogue entre les religions, les cultures et les g\u00e9n\u00e9rations\u00a0\u00bb.  <em>Face aux tr\u00e8s nombreux d\u00e9fis que la famille humaine doit affronter en divers points du globe, dans quelle mesure est-ce important de poursuivre sur la voie du dialogue\u00a0?<\/em>  \u00ab\u00a0Il s&rsquo;agit d&rsquo;un processus qui demande temps et d\u00e9vouement et il arrive que le dialogue semble inutile lorsque nous nous heurtons \u00e0 des \u00e9pisodes de violence, dans la pauvret\u00e9 et la discrimination sociale. Mais ce n&rsquo;est pas comme \u00e7a. Personnellement, j&rsquo;essaie de m&rsquo;inspirer du Pape Jean XXIII, qui avait l&rsquo;habitude de s&rsquo;agenouiller en pri\u00e8re apr\u00e8s une longue et dure journ\u00e9e, en disant\u00a0: \u00a0\u00bbSeigneur, j&rsquo;ai fait de mon mieux. Voici ton \u00c9glise, maintenant c&rsquo;est toi qui diriges\u00a0\u00bb. En tant qu&rsquo;\u00eatres humains, nous avons la tendance \u00e0 \u00eatre impatients, mais Dieu ne l&rsquo;est pas. Par cons\u00e9quent, il est de notre devoir d&rsquo;\u00eatre semblables au Christ dans la fa\u00e7on d&rsquo;aimer, de pardonner et de continuer \u00e0 croire dans la fraternit\u00e9 universelle aussi et surtout lorsqu\u00a0&lsquo;elle semble inad\u00e9quate pour r\u00e9soudre les probl\u00e8mes actuels. Nous devons nous rappeler que nous ne pouvons pas imposer notre id\u00e9e du temps \u00e0 Dieu\u00a0\u00bb.  &nbsp;  Interview d&rsquo;Annabel D&rsquo;Souza<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Interview faite \u00e0 Mgr Felix Machado archev\u00eaque de Vasai (Inde). Pour lui, le dialogue interreligieux n&rsquo;est pas seulement une partie essentielle de son minist\u00e8re mais bien son style de vie personnel.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[47],"tags":[],"class_list":["post-331842","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts\/331842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/comments?post=331842"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts\/331842\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/media?parent=331842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/categories?post=331842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/tags?post=331842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}