{"id":350480,"date":"2013-12-18T04:00:47","date_gmt":"2013-12-18T03:00:47","guid":{"rendered":"https:\/\/www.focolare.org\/francais-news-belamy-francese\/"},"modified":"2024-06-06T12:36:11","modified_gmt":"2024-06-06T10:36:11","slug":"francais-news-belamy-francese","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/fr\/francais-news-belamy-francese\/","title":{"rendered":"Du Congo \u00e0 la Belgique, le voyage de Belamy"},"content":{"rendered":"<p><div id=\"attachment_98024\" style=\"width: 237px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.youtube.com\/watch?v=ymXHLfOal4U\" target=\"_blank\" rel=\"noopener\"><img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-98024\" class=\"size-full wp-image-98024 \" style=\"border: 0px none;margin: 10px\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2013\/12\/VideoBelamy.jpg\" alt=\"\" width=\"227\" height=\"170\" \/><\/a><p id=\"caption-attachment-98024\" class=\"wp-caption-text\">Video &#8211; http:\/\/www.youtube.com\/watch?v=ymXHLfOal4U<\/p><\/div>  Belamy Paluku est originaire de Goma, mais il se trouve en <a href=\"https:\/\/www.focolare.org\/fr\/focolare-worldwide\/europa\/belgio\/\">Belgique <\/a>pour trois mois. Dans son pays,\u00a0 le <a href=\"https:\/\/www.focolare.org\/fr\/focolare-worldwide\/africa\/repubblica-democratica-del-congo\/\">Congo<\/a>, il fait partie du groupe \u00ab\u00a0Gen Fuoco\u00a0\u00bb, un orchestre qui s\u2019inspire de <a href=\"https:\/\/www.focolare.org\/fr\/chiara-lubich\/spiritualita-dellunita\/\">la spiritualit\u00e9 de l\u2019Unit\u00e9<\/a>. Il est aussi responsable du \u00ab\u00a0Foyer Culturel\u00a0\u00bb, un centre culturel de sa ville.  Ses talents musicaux lui ont valu une bourse d\u2019\u00e9tudes offerte par le Centre Wallonie-Bruxelles pour travailler le chant \u00e0 Verviers <em>(Belgique)<\/em> Belamy compose des chansons qui mettent en lumi\u00e8re la paix, le dialogue, la valeur de la souffrance.  Sa chanson la plus connue, <em>\u00ab\u00a0Nos couleurs et nos saveurs\u00a0\u00bb<\/em>, est une invitation \u00e0 appr\u00e9cier la diversit\u00e9 des couleurs et des go\u00fbts des diff\u00e9rents peuples, parce que <em>\u00ab\u00a0un monde o\u00f9 il n\u2019y aurait qu\u2019une seule couleur et qu\u2019un seul type de nourriture serait tr\u00e8s pauvre\u00a0\u00bb.<\/em>  Nous proposons cette vid\u00e9o de l&rsquo;interview \u00e0 un jeune musicien congolais et \u00e0 une jeune belge.<em> <\/em>  <strong><em>Belamy, tu es de Goma au Congo, et en ce moment tu vis en Belgique dans le cadre d&rsquo;un \u00e9change pour te sp\u00e9cialiser comme musicien. Comment te sens-tu dans un monde si diff\u00e9rent?<\/em><\/strong>  Je d\u00e9couvre plusieurs personnes de diff\u00e9rentes origines, et je r\u00e9alise que tout le monde a toujours quelque chose \u00e0 offrir ou \u00e0 recevoir des autres. Et ni culture, ni langue ne peut \u00eatre un pr\u00e9texte pour ne pas cohabiter et communiquer.  <div id=\"attachment_98026\" style=\"width: 260px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/vimeo.com\/82013758\" target=\"_blank\" rel=\"noopener\"><img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-98026\" class=\"size-articolo_1 wp-image-98026    \" style=\"margin: 5px;border: 0px none\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2013\/12\/IntervistaBelamy-250x149.jpg\" alt=\"\" width=\"250\" height=\"149\" \/><\/a><p id=\"caption-attachment-98026\" class=\"wp-caption-text\">Belamy Paluku<\/p><\/div>  <em><strong>Elisabeth,<\/strong> <strong>tu es n\u00e9e en Belgique, que signifie pour toi l\u2019accueil et la pr\u00e9sence, dans ton pays, de\u00a0 nombreux ressortissants\u00a0\u00a0 provenant du monde enter?<\/strong><\/em>  C\u2019est vrai, en Europe, et \u00e0 \u00a0Bruxelles plus particuli\u00e8rement,\u00a0 \u00a0il y a une extraordinaire richesse de cultures et de nationalit\u00e9s. J\u2019ai v\u00e9cu avec des <a href=\"https:\/\/www.focolare.org\/fr\/movimento-dei-focolari\/un-popolo\/giovani-per-un-mondo-unito\/\">jeunes du Mouvement<\/a> venant de Syrie, de Slovaquie, d\u2019Italie\u2026 L\u2019art d\u2019aimer m\u2019ouvre une voie qui m\u2019aide \u00e0 surmonter la peur de ce qui est diff\u00e9rent. Vivre en paix les uns \u00e0 c\u00f4t\u00e9 des autres ne suffit pas. Nous sommes plut\u00f4t r\u00e9serv\u00e9s et le d\u00e9fi pour nous europ\u00e9ens, je le dis aussi pour moi, c\u2019est de prendre l\u2019initiative d\u2019aller \u00e0 la rencontre de celui qui est diff\u00e9rent jusqu\u2019\u00e0 nous reconna\u00eetre fr\u00e8res l\u2019un de l\u2019autre.<strong><\/strong>  <strong><em> Belamy,\u00a0 c&rsquo;est \u00e0 partir de cet \u00e9change de richesses que tu as compos\u00e9 une chanson. C&rsquo;est bien cela?<\/em><\/strong>  Venant d&rsquo;une r\u00e9gion o\u00f9 la guerre entre ethnies fait rage, cet \u00e9change m&rsquo;est apparu comme une voie vers un monde de partage et de tol\u00e9rance, et je suis parti de nos diff\u00e9rences pour crier au monde qu&rsquo;ensemble r\u00e9unis, nous saurons d\u00e9voiler le puzzle de l&rsquo;humanit\u00e9.\u00a0<em> <\/em><strong><\/strong>  Belamy Paluku sur facebook\u00a0: \u00a0<em>Belamusik <\/em>(le centre culturel de Goma)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les chansons du jeune artiste congolais Belamy Paluku sont porteuses d\u2019un message d\u2019unit\u00e9 entre peuples et cultures : les diff\u00e9rences sont une source d\u2019enrichissement r\u00e9ciproque.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3128,906,3123,3072,3125],"tags":[3148,2992,2912,2892,2812,2852,2832,3112,3127,3052,2952,3115,3032,3092,2872,2932,3132,3012,2972],"class_list":["post-350480","post","type-post","status-publish","format-standard","hentry","category-cultura-5","category-focolare-worldwide-2-3","category-focolari-nel-mondo-5","category-nuove-generazioni-5","category-spiritualita-5","tag-africa-5","tag-armonia-e-ambiente-3","tag-arte-2","tag-arte-e-spettacolo-2","tag-belamy-paluku-2","tag-belgio-2","tag-congo-2","tag-europa-5","tag-fr-3","tag-gen-7","tag-giovani-per-un-mondo-unito-3","tag-in-dialogo-5","tag-movimento-dei-focolari-5","tag-opere-ed-attivita-5","tag-repubblica-democratica-del-congo-2","tag-scelte-e-impegno-3","tag-societa-arte-spettacolo-5","tag-un-popolo-3","tag-vivere-il-carisma-2"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts\/350480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/comments?post=350480"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts\/350480\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/media?parent=350480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/categories?post=350480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/tags?post=350480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}