{"id":352588,"date":"2012-11-09T09:25:59","date_gmt":"2012-11-09T08:25:59","guid":{"rendered":"https:\/\/www.focolare.org\/suisse-journee-oecumenique\/"},"modified":"2024-06-06T12:43:39","modified_gmt":"2024-06-06T10:43:39","slug":"suisse-journee-oecumenique","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/fr\/suisse-journee-oecumenique\/","title":{"rendered":"Suisse: journ\u00e9e \u0153cum\u00e9nique"},"content":{"rendered":"<p><img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-73969\" style=\"margin-left: 10px;border: 0px none\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2012\/11\/20121109-01.jpg\" alt=\"\" width=\"314\" height=\"209\" \/><\/p>\n<p>De l\u2019\u00e9glise r\u00e9form\u00e9e et des \u00e9glises libres, m\u00e9thodistes et catholiques, personalit\u00e9s du monde \u0153cum\u00e9nique, pasteurs hommes et femmes, parroissiens, assistants pastoraux, membres de diff\u00e9rents mouvements de toutes les r\u00e9gions linguistiques de la Suisse: 250 personnes, au-del\u00e0 de toute pr\u00e9vision, se pressent dans la salle de l\u2019H\u00f4tel Kreuz \u00e0 Berne o\u00f9, le 8 novembre, a eu lieu <strong>un symposium \u0153cum\u00e9nique organis\u00e9 par le Mouvement des Focolari ayant pour titre: \u00ab\u0152cum\u00e9nisme: vers quoi se dirige-t-on?\u00bb.<\/strong><\/p>\n<p>A la table des intervenants, trois invit\u00e9s de marque: un cardinal, une femme la\u00efque, un pasteur r\u00e9form\u00e9. De Rome, en fait, sont venus <strong>le cardinal Koch,<\/strong> suisse, actuellement <strong>pr\u00e9sident du Conseil pontifical pour l\u2019unit\u00e9 des chr\u00e9tiens et la pr\u00e9sidente du Mouvement des Focolari, <a href=\"https:\/\/www.focolare.org\/it\/news\/2011\/01\/20\/maria-voce\/\">Maria Voce<\/a><\/strong>. A faire les honneurs de la maison,<strong> Gottfried Locher, pr\u00e9sident de la F\u00e9d\u00e9ration des \u00e9glises \u00e9vang\u00e9liques de la Suisse (la Fces)<\/strong> . Leurs interventions cherchent \u00e0 mettre en \u00e9vidence divers aspects de l\u2019engagement \u0153cum\u00e9nique par des approches diff\u00e9rentes et une conviction commune forte: <strong>le chemin \u0153cum\u00e9nique est irr\u00e9versible et on ne peut y renoncer<\/strong>, malgr\u00e9 les signes de fatigue qui parfois le caract\u00e9risent, le faisant alors appara\u00eetre mission impossible. <em>\u00abTant que nous luterons pour l\u2019unit\u00e9<\/em> \u2013 affirme la future pr\u00e9sidente <strong>de la Communaut\u00e9 de travail des \u00e9glises chr\u00e9tiennes en Suisse (la Clcc), Rita Famos<\/strong> \u2013 <em>nous sommes sur la voie juste, cela veut dire que nous ne rendons pas les armes. Aujourd\u2019hui nous voulons stimuler le dialogue entre ceux qui esp\u00e8rent en r\u00eavant et ceux qui lutent pour l\u2019unit\u00e9\u00bb.<\/p>\n<p><\/em>En effet, un des \u00abdangers\u00bb sur le chemin \u0153cum\u00e9nique est celui de <em>\u00abs\u2019habituer aux diff\u00e9rences en \u00a0pensant \u00eatre bien sans l\u2019autre Eglise\u00bb<\/em>, soutient Locher. Peut-\u00eatre <em>\u00abnous sommes-nous mis \u00e0 notre aise\u00bb,<\/em> nous ne trouvons plus que <em>\u00abcette division est scandaleuse\u00bb.<\/em> D\u2019o\u00f9 son invitation \u00e0 <em>\u00abconstruire plus d\u2019unit\u00e9 l\u00e0 o\u00f9 c\u2019est possible<\/em> <em>d\u00e9j\u00e0 maintenant\u00bb<\/em>, \u00e0 commencer par les \u00e9glises r\u00e9form\u00e9es cantonales souvent tr\u00e8s ind\u00e9pendantes entre elles, pour trouver davantage de communion et une voix, un message commun en tant qu\u2019\u00e9glise r\u00e9form\u00e9e suisse sur les th\u00e8mes importants. Fort a \u00e9t\u00e9 son rappel constant \u00e0 la force transformante de la Parole.<\/p>\n<p><strong><img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-73971\" style=\"margin-right: 10px;border: 0px none\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2012\/11\/20121109-03.jpg\" alt=\"\" width=\"314\" height=\"209\" \/><\/strong><\/p>\n<p><strong>Nombreux sont les protagonistes de ce parcours qui vit soit des moments d\u2019enthousiasme, soit des phases au point mort. Parmi ceux-ci les papes<\/strong>, comme le rappelle le cardinal Koch en citant la passion \u0153cum\u00e9nique qui a conduit, par exemple, Jean XXIII \u00e0 instituer en 1960 le Secr\u00e9tariat pour la promotion de \u00a0l\u2019unit\u00e9 des chr\u00e9tiens \u2013 l\u2019actuel Conseil pontifical pour la promotion de l\u2019unit\u00e9 des chr\u00e9tiens \u2013 qui a vu Paul VI tr\u00e8s proche du monde de l\u2019orthodoxie de Constantinople avec l\u2019annulation, entr\u2019autre des anath\u00e8mes r\u00e9ciproques qui ont \u00abexpuls\u00e9 le venin de l\u2019excommunication\u00bb apr\u00e8s 900 ans, et qui l\u2019ont ammen\u00e9 \u00e0 rencontrer le primat anglican Ramsey. Puis Jean-Paul II avec tous ses actes concrets pour l\u2019\u0153cum\u00e9nisme, jusqu\u2019\u00e0<strong> Beno\u00eest XVI, qui dans son premier message a affirm\u00e9 de vouloir travailler de toutes ses forces pour l\u2019unit\u00e9 des chr\u00e9tiens.<\/strong><\/p>\n<p>Il n\u2019y a pas seulement l\u2019\u0153cum\u00e9nisme promu par les responsables des Eglises, ni seulement celui port\u00e9 de l\u2019avant par les th\u00e9ologiens, mais \u2013 et <strong>c\u2019est<strong> vital \u2013 il y a un \u0153cum\u00e9nisme de la base, un \u0153cum\u00e9nisme de la vie, un <\/strong><\/strong><strong><a href=\"https:\/\/www.focolare.org\/it\/in-dialogo\/chiese-cristiane\/\"><strong>\u0153cum\u00e9nisme du<\/strong><strong> p<\/strong><strong>eu<\/strong><strong>pl<\/strong><strong>e<\/strong><\/a>. C\u2019est de celui-ci dont parle Maria Voce<\/strong> qui raconte \u2013 en citant des exp\u00e9riences concr\u00e8tes d\u2019enfants et d\u2019adultes de diff\u00e9rents pays \u2013 avec <strong>l\u2019accent mis sur la vie de la <a href=\"https:\/\/www.focolare.org\/it\/chiara-lubich\/spiritualita-dellunita\/la-parola\/\">Parole<\/a><\/strong>, la foi dans les promesses de J\u00e9sus d\u2019\u00eatre pr\u00e9sent \u00abl\u00e0 o\u00f9 deux ou trois se trouvent r\u00e9unis\u00bb en Son nom (Mt 18,20), l\u2019amour pour <a href=\"https:\/\/www.focolare.org\/it\/chiara-lubich\/spiritualita-dellunita\/gesu-abbandonato\/\"><strong>J\u00e9sus crucifi\u00e9 et abandonn\u00e9<\/strong><\/a> symbole de toute d\u00e9sunit\u00e9. Ce sont <strong>les<\/strong> <strong>points forts de la <a href=\"https:\/\/www.focolare.org\/it\/chiara-lubich\/spiritualita-dellunita\/\">spiritualit\u00e9 des Focolari<\/a><\/strong>, qui se sont r\u00e9v\u00e9l\u00e9s \u00eatre \u00ab\u0153cum\u00e9niques\u00bb \u00e0 travers la vie, dans le sens d\u2019avoir ouvert des domaines de dialogue entre chr\u00e9tiens de diff\u00e9rentes \u00e9glises (actuellement 350) qui retrouvent dans un point ou l\u2019autre, des aspects fondamentaux de leur credo. <strong>Un <em>\u00ab\u0153cum\u00e9nisme de la base <\/em><\/strong><strong><em>qui ne s\u2019<\/em><\/strong><em>oppose pas \u00e0 celui d\u2019en-haut. C\u2019est une sorte de dialogue qui <strong>peut servir d\u2019humus, sur lequel les autres peuvent fleurir et se d\u00e9velopper\u00bb,<\/strong><\/em> soutient la pr\u00e9sidente des Focolari.<\/p>\n<p><img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-73970\" style=\"margin-left: 10px;border: 0px none\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2012\/11\/20121109-02.jpg\" alt=\"\" width=\"314\" height=\"209\" \/><\/p>\n<p>Nombreux sont les dialogues existants entre les Eglises, nombreux les genres de dialogue, vari\u00e9s les niveaux atteints. Les difficult\u00e9s, qui ne manquent pas, font souvent voir le but loin de la r\u00e9alisation du testament de J\u00e9sus. Parfois on perd de vue la route \u00e0 entreprendre, on s\u2019\u00e9loigne plus qu\u2019on ne se rapproche. Dans la salle, il est rappel\u00e9 que J\u00e9sus, dans sa pri\u00e8re, n\u2019a pas command\u00e9 l\u2019unit\u00e9: il l\u2019a demand\u00e9e au P\u00e8re. Ce \u00e0 quoi, nous chr\u00e9tiens, nous sommes donc appel\u00e9s, c\u2019est de collaborer avec passion et patience; cependant <strong>l\u2019unit\u00e9 est un don de Dieu \u00e0 invoquer ensemble<\/strong>. Comme, ensemble, nous devons sentir la souffrance de la division, ensemble reconna\u00eetre la faute de la d\u00e9sunit\u00e9, ensemble travailler pour que \u00abtous soient un\u00bb. <strong>Une soci\u00e9t\u00e9 toujours plus d\u00e9christianis\u00e9e exige le t\u00e9moignage et l\u2019engagement de chr\u00e9tiens unis.<\/strong> Ceci est aussi une conviction commune.<\/p>\n<p>De notre envoy\u00e9e Aurora Nicosia (source: Citt\u00e0 Nuova online)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le cardinal  Koch, Maria Voce et Gottfried Locher \u00e0 Berne, \u00e0 la journ\u00e9e de r\u00e9flexion et de dialogue organis\u00e9e par le Mouvement des Focolari autour du th\u00e8me sur l\u2019unit\u00e9 des chr\u00e9tiens, \u00e0 50 ans du Concile Vatican II.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[906],"tags":[],"class_list":["post-352588","post","type-post","status-publish","format-standard","hentry","category-focolare-worldwide-2-3"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts\/352588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/comments?post=352588"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/posts\/352588\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/media?parent=352588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/categories?post=352588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/fr\/wp-json\/wp\/v2\/tags?post=352588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}