{"id":299958,"date":"2007-04-03T22:00:00","date_gmt":"2007-04-03T20:00:00","guid":{"rendered":"https:\/\/www.focolare.org\/artistas-qual-e-a-vocacao-para-a-nossa-epoca\/"},"modified":"2024-05-13T21:09:38","modified_gmt":"2024-05-13T19:09:38","slug":"artistas-qual-e-a-vocacao-para-a-nossa-epoca","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/pt-pt\/artistas-qual-e-a-vocacao-para-a-nossa-epoca\/","title":{"rendered":"Artistas: qual \u00e9 a voca\u00e7\u00e3o para a nossa \u00e9poca?"},"content":{"rendered":"<p><strong><strong><img decoding=\"async\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/layout\/edit\/foto\/foto2007\/070403-02.jpg\" border=\"0\" alt=\"\" hspace=\"5\" vspace=\"5\" align=\"left\" \/><\/strong>\u201cArtistas: qual \u00e9 a voca\u00e7\u00e3o para a nossa \u00e9poca?\u201d.<\/strong> Convocados por este questionamento, pintores e escultores, diretores e atores, m\u00fasicos e cultores das diferentes disciplinas art\u00edsticas, de 20 pa\u00edses, da \u00cdndia \u00e0 Argentina, da Cor\u00e9ia ao Brasil, da Finl\u00e2ndia a Portugal, se reunir\u00e3o para o segundo Congresso internacional, que acontecer\u00e1 nos dias 13 a 15 de abril, no Centro Mari\u00e1polis de Castelgandolfo (Roma).  <strong>Quem o promove:<\/strong> Clart\u00e9 evoca luz, claridade, cl\u00e1ritas. Os artistas que dele participam desejam contribuir para a realiza\u00e7\u00e3o de uma arte que seja portadora de luz na noite cultural desta \u00e9poca de profundas transforma\u00e7\u00f5es. Caracter\u00edstica peculiar de Clart\u00e9 \u2013 que se inspira na espiritualidade da unidade, de Chiara Lubich \u2013 \u00e9 o di\u00e1logo entre artistas. Tamb\u00e9m destes relacionamentos \u2013 eles afirmam \u2013 surge a inspira\u00e7\u00e3o.  <strong>Objetivo do encontro<\/strong> \u2013 Se na arte moderna e contempor\u00e2nea predomina a \u201cperda do centro\u201d, a exclus\u00e3o de qualquer ponto de refer\u00eancia, o congresso deseja promover uma arte renovada por uma experi\u00eancia humano-divina, universal. Uma arte que pode se tornar um espa\u00e7o de realiza\u00e7\u00e3o de uma vis\u00e3o humana integral, justamente por se dirigir ao homem como um todo.  <strong><strong><img decoding=\"async\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/layout\/edit\/foto\/foto2007\/070403-01.jpg\" border=\"0\" alt=\"\" hspace=\"5\" vspace=\"5\" align=\"right\" \/><\/strong>O programa<\/strong> \u2013 Como o t\u00edtulo explicita, o Congresso seguir\u00e1 quatro caminhos: inquieta\u00e7\u00e3o, esperan\u00e7a, luz, perspectivas. Entre outras coisas, est\u00e1 previsto: \u201cLi\u00e7\u00e3o magistral\u201d de Chiara Lubich sobre a arte \u2013 por ocasi\u00e3o do doutorado honoris causa em arte, que lhe foi conferido pela Universidade Cat\u00f3lica de Maracaibo (Venezuela) \u2013 na abertura do Congresso. A soci\u00f3loga brasileira Vera Ara\u00fajo falar\u00e1 sobre a contribui\u00e7\u00e3o que a arte pode oferecer \u00e0 sociedade atual. \u201cA arte, protagonista na cidade\u201d: iniciativas art\u00edsticas que suscitam a retomada dos valores e a coes\u00e3o social, em diferentes contextos culturais e sociais, em cidades com N\u00e1poles, Caracas e Jerusal\u00e9m, onde surgiu uma orquestra composta por palestinos e israelenses. Amplo espa\u00e7o dedicado ao di\u00e1logo, em sess\u00f5es plen\u00e1rias e em grupos. Momento conclusivo: \u201cDons de luz\u201d, proje\u00e7\u00e3o em v\u00eddeo do di\u00e1logo de Chiara Lubich com um grupo hindu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inquieta\u00e7\u00e3o, esperan\u00e7a, luz, perspectivas do mundo da arte, no segundo Congresso Internacional promovido por \u201cClart\u00e9\u201d, de 13 a 15 de abril, no Centro Mari\u00e1polis de Castelgandolfo (Roma)<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[129],"tags":[],"class_list":["post-299958","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/299958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=299958"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/299958\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=299958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=299958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=299958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}