{"id":315780,"date":"2017-09-14T00:10:08","date_gmt":"2017-09-13T22:10:08","guid":{"rendered":"https:\/\/www.focolare.org\/o-genfest-2018-na-asia\/"},"modified":"2024-05-15T21:04:57","modified_gmt":"2024-05-15T19:04:57","slug":"o-genfest-2018-na-asia","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/pt-pt\/o-genfest-2018-na-asia\/","title":{"rendered":"O Genfest 2018 na \u00c1sia"},"content":{"rendered":"<p><strong><a href=\"http:\/\/y4uw.org\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-155799\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2017\/09\/Genfest2018.jpg\" alt=\"Genfest2018\" width=\"368\" height=\"368\" \/><\/a><\/strong>Da convic\u00e7\u00e3o de querermos reescrever uma nova geografia em que caiam as barreiras e os muros pessoais e planet\u00e1rios, <strong>surgiu a ideia de uma marcha mundial dos <\/strong><a href=\"https:\/\/www.focolare.org\/pt\/movimento-dei-focolari\/scelte-e-impegno\/gen\/\" target=\"_blank\" rel=\"noopener\">Gen\u00a0<\/a><strong>e <\/strong><a href=\"https:\/\/www.focolare.org\/movimento-dei-focolari\/pt\/un-popolo\/giovani-per-un-mondo-unito\/\" target=\"_blank\" rel=\"noopener\">Jovens por um Mundo Unido<\/a><strong>\u00a0que culminasse na d\u00e9cima primeira edi\u00e7\u00e3o do Genfest que ter\u00e1 lugar de 6 a 8 de julho de 2018, em Manila<\/strong> (<a href=\"https:\/\/www.focolare.org\/pt\/focolare-worldwide\/asia\/filippine\/\" target=\"_blank\" rel=\"noopener\">Filipinas<\/a>).  O programa central acontecer\u00e1 no <strong>World Trade Center Metro Manila, enquanto todos os workshops se realizar\u00e3o na Universidade De La Salle <span id=\"result_box\" class=\"short_text\" lang=\"pt\"><span class=\"\">e outras universidades<\/span><\/span>. O t\u00edtulo ser\u00e1 <\/strong>\u201c<strong>BEYOND ALL BORDERS\u201d (Al\u00e9m de todas as fronteiras).<\/strong>  <strong>Ser\u00e1, portanto, a \u00c1sia, o continente do futuro e dos jovens, que receber\u00e1 esta conven\u00e7\u00e3o<\/strong>. Segundo os dados do U. S. Census Bureau, o n\u00famero de jovens com menos de 25 anos, no mundo inteiro, \u00e9 de 3 mil milh\u00f5es, dos quais 60% vive na \u00c1sia. Isso significa que quase metade da popula\u00e7\u00e3o asi\u00e1tica (que \u00e9 superior a 4 milh\u00f5es) tem idade inferior a 25 anos. \u00abPortanto, s\u00f3 podia realizar-se no nosso continente\u00bb &#8211; <strong>explica Kiara Cariaso,<\/strong> uma filipina da equipe organizadora. \u00abQueremos mostrar ao mundo a rede de projetos, campus, a\u00e7\u00f5es de solidariedade, de apoio \u00e0 legalidade, o n\u00e3o \u00e0 guerra e aos armamentos, mas tamb\u00e9m o n\u00e3o \u00e0 solid\u00e3o, ao abandono e aos relacionamentos superficiais, que milhares de jovens espalhados pelo mundo est\u00e3o j\u00e1 levando adiante\u00bb.  <strong>Alepo, Bel\u00e9m, Turinga, Mumbai: o Genfest inicia-se nas periferias do mundo<\/strong>.  \u00abTamb\u00e9m desta vez, o Genfest ser\u00e1 uma pedra miliar, imprescind\u00edvel no caminho para um mundo unido \u2013 <strong>explicam Maria Guaita e Marco De Salvo, da secretaria central GMU<\/strong> \u2013 quer para partilhar os esfor\u00e7os de paz e unidade em execu\u00e7\u00e3o, quer para nos darmos for\u00e7a e coragem uns aos outros. Muitos jovens vivem em territ\u00f3rios de guerra, de conflito e de problemas sociais. \u00c9 essa a primeira linha que muitos escolheram para dar in\u00edcio \u00e0 mudan\u00e7a do mundo\u00bb.  \u00abEstamos em muitas e diferentes frentes: estamos nas periferias, mas ocupamo-nos tamb\u00e9m de forma\u00e7\u00e3o, de esporte, se solidariedade \u2013 <strong>explica Rafael Tronquini<\/strong>, brasileiro, da equipe de marketing do Genfest, que j\u00e1 est\u00e1 em Manila h\u00e1 cinco meses. Queremos estar onde percebemos que existem necessidades ou se ouvem os gritos de socorro da nossa gente, em todas as latitudes. Poderemos resumir o logotipo do Genfest com o lema \u201cless is more\u201d (menos \u00e9 melhor): os desafios e as barreiras s\u00e3o infinitas, e o que conta \u00e9 super\u00e1-las juntos, avan\u00e7ando em dire\u00e7\u00e3o \u00e0 unidade\u00bb.  https:\/\/youtu.be\/C8NvjNYgNEc<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong><a href=\"http:\/\/y4uw.org\/it\/events\/genfest-2018\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-154777\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2017\/07\/Logo-Genfest.jpg\" alt=\"Logo Genfest\" width=\"48\" height=\"48\" \/><\/a><\/strong>Fronteiras, barreiras, muros: quantas destas coisas encontramos durante o dia? E quantas existem pelo mundo, muitas delas invis\u00edveis? Ser\u00e3o realmente insuper\u00e1veis?<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[909],"tags":[],"class_list":["post-315780","post","type-post","status-publish","format-standard","hentry","category-focolare-worldwide-2-4"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/315780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=315780"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/315780\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=315780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=315780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=315780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}