{"id":315886,"date":"2017-10-20T00:10:07","date_gmt":"2017-10-19T22:10:07","guid":{"rendered":"https:\/\/www.focolare.org\/ninguem-e-estrangeiro-para-mim\/"},"modified":"2024-05-15T21:05:19","modified_gmt":"2024-05-15T19:05:19","slug":"ninguem-e-estrangeiro-para-mim","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/pt-pt\/ninguem-e-estrangeiro-para-mim\/","title":{"rendered":"Ningu\u00e9m \u00e9 estrangeiro para mim"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2017\/10\/GenVerde_Germany_05.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-157132\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2017\/10\/GenVerde_Germany_05.jpg\" alt=\"GenVerde_Germany_05\" width=\"368\" height=\"245\" \/><\/a> Um m\u00eas empunhando a bandeira do di\u00e1logo, do encontro e da descoberta do valor do \u2018outro\u2019<\/strong>.  <strong>Num Pa\u00eds de forte conota\u00e7\u00e3o multi\u00e9tnica,<\/strong><strong> o ritmo e a m\u00fasica tiveram um poder agregador. <\/strong><strong>A 9 de setembro<\/strong><strong>, na pequena cidade de<\/strong> Stadthagen, na Baixa Sax\u00f3nia, por ocasi\u00e3o das festividades do jubileu da Reforma, o<a href=\"http:\/\/www.genverde.it\/\" target=\"_blank\" rel=\"noopener\"> Gen Verde<\/a> (22 elementos femininos, provenientes de 14 pa\u00edses diferentes) trouxe uma nota de internacionalidade, com o espet\u00e1culo On the Other Side. Uma viagem em redor de todo o planeta, atrav\u00e9s da narrativa de hist\u00f3rias pessoais ou coletivas de um povo inteiro, evidenciando a riqueza da diversidade e o potencial de quem se encontra \u201cdo outro lado\u201d.  <strong>No dia 15 de setembro<\/strong>, em Boppard, na Fazenda da Esperan\u00e7a, um comunidade local que desafia a toxicodepend\u00eancia, na perspetiva do renascimento, o concerto La vita LIV foi uma ocasi\u00e3o de encontro pessoal entre as componentes da banda e as experi\u00eancias dos jovens. Uma oportunidade para se compreender que cada um pode dar um pequeno mas grand\u00edssimo passo para mudar alguma coisa, no sentido de que todos se descubram como irm\u00e3os.  <strong><a href=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2017\/10\/GenVerde_Stadthagen.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-157133\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2017\/10\/GenVerde_Stadthagen.jpg\" alt=\"GenVerde_Stadthagen\" width=\"368\" height=\"245\" \/><\/a><\/strong><strong>Nos dias seguintes<\/strong>, a t\u00edpica carater\u00edstica art\u00edstica do Gen Verde encontrou express\u00e3o no laborat\u00f3rio Start Now: um wokshop intenso que se prolongou por cinco dias em cada uma das tr\u00eas etapas, trabalhando lado a lado com grupos de adolescentes e jovens.  <strong>Durante o processo criativo<\/strong> <strong>que se renova<\/strong><strong>, sempre de maneira nova e imprevis\u00edvel,<\/strong> os adolescentes trabalham em equipa, desenvolvendo os pr\u00f3prios talentos e compet\u00eancias, e sendo co-protagonistas duma atraente experi\u00eancia criativa, baseada na escuta rec\u00edproca e na transpar\u00eancia. Depois de dois dias de intenso trabalho, ancorados na confian\u00e7a e no respeito do grupo, os adolescentes puderam exibir-se no espet\u00e1culo final, juntamente com a banda, num crescendo de emo\u00e7\u00f5es.  <strong><a href=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2017\/10\/GenVerde_Germany_04.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-157134 alignright\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2017\/10\/GenVerde_Germany_04.jpg\" alt=\"GenVerde_Germany_04\" width=\"368\" height=\"245\" \/><\/a>Tr\u00eas etapas do laborat\u00f3rio-espet\u00e1culo<\/strong><strong>: em <em>Dortmund<\/em>, o grupo trabalhou em conjunto com 170 adolescentes; em<\/strong><em> Duderstadt<\/em>, com os estudantes de tr\u00eas escolas, entre os quais um grupo numeroso de imigrantes; por fim em <em>Mannheim<\/em>, com mulheres e homens de um enorme campo de refugiados.  <strong>Em cada cidade, durante o espet\u00e1culo final<\/strong>, repetiu-se, com carater\u00edsticas diferentes, o mesmo milagre: mudan\u00e7as de vida, atmosfera de profunda fraternidade, envolvimento de quem inicialmente se mostrava relutante. \u00ab<em>\u00c9 incr\u00edvel aquilo que se pode fazer em dois dias!<\/em>\u00bb \u2013 exclamou incr\u00e9dula uma repariga. E um jovem: \u00ab<em>Os erros n\u00e3o nos bloquearam, pelo contr\u00e1rio, sentimo-nos encorajados a ir em frente<\/em>\u00bb.  <strong>Particularmente, na etapa de Mannheim<\/strong>, o Gen Verde encontrou-se com pessoas que sofreram dores incr\u00edveis, foram v\u00edtimas de atrocidades, perderam tudo. <strong>As componentes do grupo contam<\/strong>: \u00abFomos ter com essas pessoas onde elas viviam e recebemos delas o dom das suas hist\u00f3rias. Durante o ser\u00e3o, na can\u00e7\u00e3o \u201c<em>Quem chora por ti<\/em>\u201d, muitas delas reviveram feridas de trag\u00e9dias vividas\u00bb. E as palavras \u201c<em>No one is a stranger to me<\/em><em>\u201d<\/em> (ningu\u00e9m \u00e9 estrangeiro para mim) ressoaram verdadeiras como nunca.  <a href=\"http:\/\/www.genverde.it\/contents\/mediagallery\/tears-of-joy-at-start-now-in-germany\/\" target=\"_blank\" rel=\"noopener\">Fotogallery<\/a>  <\/p>\n<hr \/>\n<p>  https:\/\/vimeo.com\/236654355<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De 9 a 25 de Setembro, uma tourn\u00e9e na Alemanha da banda internacional GEN VERDE. Um programa rico de concertos e workshops, nas seguintes cidades: Stadthagen, Boppard, Dortmund, Duderstadt e Mannheim.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[129],"tags":[],"class_list":["post-315886","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/315886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=315886"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/315886\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=315886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=315886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=315886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}