{"id":317364,"date":"2019-09-30T20:04:34","date_gmt":"2019-09-30T18:04:34","guid":{"rendered":"https:\/\/www.focolare.org\/ponto-de-partida-e-ponto-de-chegada\/"},"modified":"2024-05-15T21:09:59","modified_gmt":"2024-05-15T19:09:59","slug":"ponto-de-partida-e-ponto-de-chegada","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/pt-pt\/ponto-de-partida-e-ponto-de-chegada\/","title":{"rendered":"Ponto de partida e ponto de chegada"},"content":{"rendered":"<p><em>Em Rocca di Papa se concluiu o encontro anual dos dirigentes do Movimento dos Focolares. Dentre as prioridades que emergiram para 2020, existe um novo compromisso no campo dos direitos humanos e da justi\u00e7a, o centen\u00e1rio de Chiara Lubich e a pr\u00f3xima Assembleia Geral dos Focolares.<\/em>  <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-191568 alignleft\" title=\"Incontro delegati 2019_1\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2019\/10\/20190918_162350.jpg\" alt=\"20190918 162350\" width=\"326\" height=\"184\" \/>No final o c\u00edrculo se fechou. Uma longa comunh\u00e3o entre os participantes do encontro anual entre os delegados do Movimento dos Focolares no mundo e o Conselho Geral, realizado de 14 a 28 de setembro de 2019 em Rocca di Papa, p\u00f4s novamente em luz o princ\u00edpio que tinha \u201cdado o tom\u201d j\u00e1 desde o in\u00edcio do encontro e que ser\u00e1 princ\u00edpio-guia para todo o Movimento no pr\u00f3ximo ano: tudo o que se faz em nome do Movimento no campo eclesial, social ou cultural, como atividades para crian\u00e7as, jovens ou adultos, fam\u00edlias ou empenhados em pol\u00edtica, s\u00f3 tem sentido se \u00e9 caracterizado e guiado pela presen\u00e7a de Jesus no meio daqueles que se amam do modo como ele ensinou.  Isso n\u00e3o significa que os focolares est\u00e3o tomando um vi\u00e9s espiritual. De fato, a primeira parte do encontro foi dedicada \u00e0 colet\u00e2nea da vida do Movimento. Com a marca dos diferentes ambientes eclesiais, pol\u00edticos e culturais em que o Movimento est\u00e1 situado, se apresentaram projetos sociais e educativos, empenho por refugiados inclusive em regi\u00f5es de que pouco se ouve falar nos meios de comunica\u00e7\u00e3o, iniciativas art\u00edsticas ou ent\u00e3o em prol da dignidade humana.  <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-191569 alignright\" title=\"Incontro delegati 2019_2\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2019\/10\/20190926_110353.jpg\" alt=\"20190926 110353\" width=\"327\" height=\"184\" \/>Neste interc\u00e2mbio veio em relevo que a reforma, em andamento h\u00e1 alguns anos sob o t\u00edtulo de \u201cNova Configura\u00e7\u00e3o\u201d, est\u00e1 dando os primeiros frutos. Em muitas partes do mundo, as estruturas mais fr\u00e1geis parecem liberar novas for\u00e7as criativas. Nasceram novas formas de an\u00fancio e evangeliza\u00e7\u00e3o, sinergias entre as v\u00e1rias ramifica\u00e7\u00f5es do Movimento e com outras realidades eclesiais e leigas. E at\u00e9 o relacionamento entre o governo central e as regi\u00f5es geogr\u00e1ficas, ou seja, entre as sensibilidades globais e a a\u00e7\u00e3o local, est\u00e1 projetado em dire\u00e7\u00e3o a um novo equil\u00edbrio.  Neste equil\u00edbrio foi poss\u00edvel identificar juntos, embora no respeito das diversidades presentes inclusive dentro do Movimento, como as de culturas, confiss\u00f5es, for\u00e7as e recursos, tamb\u00e9m as prioridades a serem abordadas no pr\u00f3ximo ano 2019\/2020.  <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-191570 alignleft\" title=\"Incontro delegati 2019_3\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2019\/10\/20190924_105445.jpg\" alt=\"20190924 105445\" width=\"327\" height=\"184\" \/>Continuando um percurso proposto por jovens, o Movimento no pr\u00f3ximo ano se empenhar\u00e1 com o lema \u201cA tempo pela Paz\u201d nos campos dos direitos humanos, da paz, da legalidade e da justi\u00e7a procurando envolver tamb\u00e9m outras pessoas e institui\u00e7\u00f5es em dar passos concretos e importantes nestes campos.  Um papel especial ter\u00e1 nos pr\u00f3ximos meses o Centen\u00e1rio do nascimento de Chiara Lubich. As atividades, que come\u00e7am no dia 7 de dezembro de 2019 com o t\u00edtulo \u201cCelebrar para encontrar\u201d, querem oferecer a possibilidade de um encontro vivo com a fundadora e o seu carisma. O ano de 2020 enfim ser\u00e1 tamb\u00e9m caracterizado pela Assembleia Geral do Movimento, que se realiza a cada seis anos e oferecer\u00e1 novas perspectivas.  \u201cMas tudo o que fazemos tem um \u00fanico objetivo \u2013 reiterou Maria Voce, Presidente dos Focolares, na conclus\u00e3o deste encontro \u2013. Queremos transformar o mundo, dando visibilidade \u00e0 presen\u00e7a de Cristo nele, atrav\u00e9s do amor m\u00fatuo entre n\u00f3s\u201d. \u00c9 este \u2013 por assim dizer \u2013 o t\u00edpico \u201csoft skill\u201d dos Focolares, a sua \u201ccompet\u00eancia transversal\u201d, que n\u00e3o se produz com metodologias e programa\u00e7\u00f5es, mas que est\u00e1 na base de cada empenho seu, como ponto de partida e ponto de chegada. <\/p>\n<p style=\"text-align: right;\"><em>Joachim Schwind<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em Rocca di Papa se concluiu o encontro anual dos dirigentes do Movimento dos Focolares. Dentre as prioridades que emergiram para 2020, existe um novo compromisso no campo dos direitos humanos e da justi\u00e7a, o centen\u00e1rio de Chiara Lubich e a pr\u00f3xima Assembleia Geral dos Focolares.<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[129],"tags":[],"class_list":["post-317364","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/317364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=317364"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/317364\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=317364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=317364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=317364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}