{"id":318202,"date":"2021-06-19T01:00:39","date_gmt":"2021-06-18T23:00:39","guid":{"rendered":"https:\/\/www.focolare.org\/bolivia-nas-ruas-da-nossa-cidade\/"},"modified":"2024-05-15T21:12:31","modified_gmt":"2024-05-15T19:12:31","slug":"bolivia-nas-ruas-da-nossa-cidade","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/pt-pt\/bolivia-nas-ruas-da-nossa-cidade\/","title":{"rendered":"Bol\u00edvia: nas ruas da nossa cidade"},"content":{"rendered":"<p><strong><em>O testemunho dos volunt\u00e1rios da \u201cCasa de los Ni\u00f1os\u201d (Casa das Crian\u00e7as), de Cochabamba (Bol\u00edvia), obra inspirada na espiritualidade da unidade, empenhados incansavelmente em cuidar dos contaminados pela COVID-19 e consolar os moribundos.<\/em><\/strong>  Voltamos a percorrer as ruas da nossa cidade com um pouco de inconsci\u00eancia e muita ingenuidade. Este v\u00edrus amedronta a todos, incita a isolar-se uns dos outros. Mas somos conscientes da import\u00e2ncia e da necessidade daquilo que nos \u00e9 pedido com extrema urg\u00eancia. \u00c9 por isso que jamais recuamos, mesmo tomando as precau\u00e7\u00f5es necess\u00e1rias. Os testes que realizamos pontualmente cada semana continuam a dar resultados negativos. Talvez algu\u00e9m estenda uma m\u00e3o misericordiosa sobre a nossa ingenuidade.  <img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-242730 alignleft\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2021\/06\/Casa-de-los-Ni\u00a6os-2-453x340.jpg\" alt=\"\" width=\"340\" height=\"255\" \/>Aqui, come\u00e7ou a esta\u00e7\u00e3o do frio e as contamina\u00e7\u00f5es por Covid-19 aumentaram exponencialmente. Atingimos um n\u00famero sem precedentes, os hospitais p\u00fablicos encontram-se em colapso. As pessoas est\u00e3o morrendo nos carros, \u00e0 espera que se libere um leito de hospital\u2026 Mesmo nas cl\u00ednicas privadas muito dispendiosas, as interna\u00e7\u00f5es foram suspensas.  O oxig\u00eanio n\u00e3o est\u00e1 mais dispon\u00edvel e existem longas filas para o reabastecimento nos dois \u00fanicos lugares habilitados para este servi\u00e7o, a pagamento. Um cilindro de 6 m\u00b3 dura menos de 5 horas! Os medicamentos especializados s\u00f3 est\u00e3o dispon\u00edveis no mercado clandestino: cada ampola custa em torno de 1300 euros!  Este ano, as pessoas atingidas pelo v\u00edrus s\u00e3o muito mais jovens. N\u00f3s levamos oxig\u00eanio e rem\u00e9dios\u00a0 onde quer que sejamos chamados. Temos licen\u00e7as para viajar todos os dias e a qualquer hora do dia.  Nossa van, muito espa\u00e7osa se transformou em uma ambul\u00e2ncia e infelizmente, muitas vezes, em um carro f\u00fanebre, sem custo algum.  <img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\" wp-image-242731 alignright\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2021\/06\/Casa-de-lso-Ni\u00a6os-3-453x340.jpg\" alt=\"\" width=\"381\" height=\"286\" \/>O tempo passa rapidamente para os menos favorecidos e com dificuldade respirat\u00f3ria, por isso tamb\u00e9m n\u00f3s corremos e n\u00e3o h\u00e1 tempo para pensar em n\u00f3s mesmos.  Levamos oxig\u00eanio e medicamentos, mas para falar a verdade, nos esfor\u00e7amos, sobretudo em levar sementes de esperan\u00e7a. \u00c0s vezes acontece de conhecermos pela primeira vez aqueles que visitamos, mas imediatamente se estabelece uma esp\u00e9cie de cumplicidade que desperta a esperan\u00e7a. E, pouco a pouco, o medo se dissipa e vemos as pessoas sorrirem serenamente.  Conosco levamos tamb\u00e9m o ter\u00e7o que n\u00e3o \u00e9 um amuleto m\u00e1gico, n\u00e3o, \u00e9 a coroa, de n\u00f3s que desejamos confiar ao cora\u00e7\u00e3o de nossa M\u00e3e do C\u00e9u, as grandes afli\u00e7\u00f5es e dores deste tempo, de tantos irm\u00e3os e irm\u00e3s. Faz parte da oxigenoterapia: fornecer ar ao cora\u00e7\u00e3o de quem sofre!  <img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-242729 alignleft\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2021\/06\/Capilla-Casa-del-Ni\u00a6o-579x340.jpg\" alt=\"\" width=\"365\" height=\"214\" \/>Todas as noites nos encontramos para a ora\u00e7\u00e3o comunit\u00e1ria da nossa cidadezinha, no jardim, em frente \u00e0 linda capela que conserva as hist\u00f3rias de muitas das nossas crian\u00e7as que j\u00e1 voaram para o c\u00e9u. Rezamos diante da est\u00e1tua da \u201cVirgem Urcupina\u201d, padroeira de Cochabamba, que leva nos bra\u00e7os seu Filho.  A nossa \u00e9 uma ora\u00e7\u00e3o que sobe direta ao c\u00e9u e para fixar os nomes de muitos que visitamos durante o dia. Pedimos para cada um deles uma luz divina, necess\u00e1ria para iluminar a noite de suas dores. <\/p>\n<p style=\"text-align: right;\"><em>Os volunt\u00e1rios da \u201cCasa de los Ni\u00f1os\u201d \u2013 Cochabamba (Bol\u00edvia)<\/em><\/p>\n<p> <em>\u00a0<\/em>  &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O testemunho dos volunt\u00e1rios da \u201cCasa de los Ni\u00f1os\u201d (Casa das Crian\u00e7as), de Cochabamba (Bol\u00edvia), obra inspirada na espiritualidade da unidade, empenhados incansavelmente em cuidar dos contaminados pela COVID-19 e consolar os moribundos.<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[909],"tags":[],"class_list":["post-318202","post","type-post","status-publish","format-standard","hentry","category-focolare-worldwide-2-4"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/318202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=318202"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/318202\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=318202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=318202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=318202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}