{"id":333546,"date":"2015-04-29T04:08:19","date_gmt":"2015-04-29T02:08:19","guid":{"rendered":"https:\/\/www.focolare.org\/chiara-lubich-uma-consciencia-de-solidariedade-universal\/"},"modified":"2024-05-16T15:24:08","modified_gmt":"2024-05-16T13:24:08","slug":"chiara-lubich-uma-consciencia-de-solidariedade-universal","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/pt-pt\/chiara-lubich-uma-consciencia-de-solidariedade-universal\/","title":{"rendered":"Chiara Lubich: uma consci\u00eancia de solidariedade universal"},"content":{"rendered":"<p><a href=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2015\/04\/Chiara-Lubich-e-Nikkyo-Niwano.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-123326\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2015\/04\/Chiara-Lubich-e-Nikkyo-Niwano.jpg\" alt=\"Chiara Lubich e Nikkyo Niwano\" width=\"254\" height=\"198\" \/><\/a>\u00abAqui fala-se muito da constru\u00e7\u00e3o de uma casa europ\u00e9ia comum, mas estamos convencidos de que esta a\u00e7\u00e3o t\u00e3o necess\u00e1ria n\u00e3o ser\u00e1 completa se n\u00e3o a considerarmos um detalhe da &#8220;aldeia global&#8221;, que \u00e9 a Terra em que vivemos.  Este pensamento me foi sugerido pela preocupa\u00e7\u00e3o expressa na sua carta com as condi\u00e7\u00f5es prec\u00e1rias do nosso ambiente natural (\u2026).De fato, est\u00e3o se multiplicando as an\u00e1lises alarmantes de cientistas, pol\u00edticos, organismos internacionais sobre o nosso ecossistema. Muitos lan\u00e7am propostas para curar o nosso mundo doente.  A ecologia, no fundo, representa um desafio que se pode vencer somente mudando a mentalidade e formando as consci\u00eancias.  (\u2026)J\u00e1 foi demonstrado por muitos estudos cient\u00edficos s\u00e9rios que n\u00e3o faltam recursos t\u00e9cnicos nem econ\u00f4micos para melhor o ambiente. O que falta \u00e9 aquele suplemento espiritual, aquele novo amor pelo homem, que nos faz sentir respons\u00e1veis uns pelos outros, no esfor\u00e7o comum de administrar os recursos da Terra num modo inteligente, justo, moderado.(\u2026)  A distribui\u00e7\u00e3o dos bens no mundo, a ajuda \u00e0s popula\u00e7\u00f5es mais pobres, a solidariedade do Norte para com o Sul, dos ricos em rela\u00e7\u00e3o aos pobres \u00e9 a outra face do problema ecol\u00f3gico<strong>.<\/strong>  Se os imensos recursos econ\u00f4micos destinados \u00e0 ind\u00fastria b\u00e9lica e a uma super produ\u00e7\u00e3o, que requer o incremento de super-consumidores, sem falar no desperd\u00edcio dos bens nos Pa\u00edses ricos, se esses enormes recursos servissem pelo menos em parte para ajudar o Terceiro Mundo a encontrar um caminho digno de desenvolvimento, como o clima seria mais respir\u00e1vel, quantas florestas seriam poupadas, quantas regi\u00f5es n\u00e3o conheceriam a desertifica\u00e7\u00e3o e quantas vidas humanas seriam salvas!  (\u2026) Mesmo assim, sem uma nova consci\u00eancia de solidariedade universal nunca se dar\u00e1 um passo em frente.  (\u2026) Se o homem n\u00e3o est\u00e1 em paz com Deus nem sequer a Terra estar\u00e1 em paz. As pessoas que vivem a religi\u00e3o sentem o &#8220;sofrimento\u201d da Terra quando o homem n\u00e3o a usa segundo o plano de Deus, mas s\u00f3 por ego\u00edsmo, por um desejo insaci\u00e1vel de possuir.  Este ego\u00edsmo e desejo contaminam o ambiente ainda mais e pior do que qualquer outra polui\u00e7\u00e3o, que \u00e9 s\u00f3 uma sua consequ\u00eancia.  (\u2026). Agora, essas consequ\u00eancias desastrosas nos obrigam a encarar a realidade juntos na perspectiva de um mundo unido: se n\u00e3o enfrentarmos este problema todos juntos, ele n\u00e3o se resolver\u00e1.  (\u2026) Se descobrirmos que toda a cria\u00e7\u00e3o \u00e9 um dom de um Padre que nos ama, ser\u00e1 muito mais f\u00e1cil encontrar uma rela\u00e7\u00e3o harmoniosa com a natureza.  E se descobrirmos tamb\u00e9m que este dom \u00e9 para todos os membros da fam\u00edlia humana, e n\u00e3o s\u00f3 para alguns, estaremos mais atentos e respeitaremos melhor algo que pertence \u00e0 humanidade inteira, presente e futura\u00bb.  <a href=\"http:\/\/www.centrochiaralubich.org\/pt\/documentos\/textos\/149-autografo-pt\/748-8-de-marco-de-1990.html\" target=\"_blank\" rel=\"noopener\">Leia mais<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coincidindo com o encontro entre o Secret\u00e1rio Geral da ONU e o Papa, e a realiza\u00e7\u00e3o de uma Jornada sobre ecologia no Vaticano, publicamos alguns trechos de uma carta de Chiara Lubich de 1990, endere\u00e7ada ao l\u00edder budista Nikkyo Niwano.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[910],"tags":[],"class_list":["post-333546","post","type-post","status-publish","format-standard","hentry","category-senza-categoria-2-4"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/333546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=333546"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/333546\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=333546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=333546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=333546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}