{"id":333888,"date":"2015-10-05T04:00:26","date_gmt":"2015-10-05T02:00:26","guid":{"rendered":"https:\/\/www.focolare.org\/on-the-other-side-tour-comeca-a-turne-na-gra-bretanha\/"},"modified":"2024-05-16T15:25:26","modified_gmt":"2024-05-16T13:25:26","slug":"on-the-other-side-tour-comeca-a-turne-na-gra-bretanha","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/pt-pt\/on-the-other-side-tour-comeca-a-turne-na-gra-bretanha\/","title":{"rendered":"On the Other Side Tour: come\u00e7a a turn\u00ea na Gr\u00e3-Bretanha"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2015\/10\/20151005-01.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-129348\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2015\/10\/20151005-01.jpg\" alt=\"20151005-01\" width=\"380\" height=\"253\" \/><\/a>\u00abTrabalhamos muito.<\/strong> Durante tr\u00eas anos escutamos milhares de pessoas, especialmente jovens, que encontramos em nossa casa ou nas nossas turn\u00eas. Compusemos m\u00fasicas, escrevemos textos, mas principalmente procuramos \u201cviver\u201d, no sentido literal da palavra: entrando no jogo, arriscando, captando o belo e o feio da humanidade. N\u00e3o vemos a hora de ir para a Gr\u00e3-Bretanha, vamos para acolher e compartilhar, mas tamb\u00e9m para dar\u00bb.  <strong>Quem fala \u00e9 Sally McAllister, diretora do<\/strong> <a href=\"http:\/\/www.genverde.it\/\" target=\"_blank\" rel=\"noopener\">Gen Verde<\/a>, irlandesa de nascimento e inglesa por ado\u00e7\u00e3o: \u00abVivi em Londres por mais de 30 anos e aprendi a conhecer e amar o povo. Por isso \u00e9 com muita alegria que respondemos ao convite de voltar l\u00e1\u00bb.  <strong>Os Focolares est\u00e3o na<\/strong> <a href=\"https:\/\/www.focolare.org\/pt\/focolare-worldwide\/europa\/regno-unito\/\" target=\"_blank\" rel=\"noopener\">Gr\u00e3-Bretanha <\/a><strong>desde 1963<\/strong>, em muitas cidades do Reino Unido, e os seus membros s\u00e3o cat\u00f3licos, anglicanos, fieis das Igrejas Livres. H\u00e1 tamb\u00e9m mu\u00e7ulmanos e siks que, em seu pequeno c\u00edrculo, s\u00e3o um testemunho verdadeiro de unidade vivida, sofrida e realizada no cotidiano\u00bb.  \u00abPor que nos convidaram? \u2013 continua Sally -. <strong>Foram as comunidades dos Focolares que organizaram toda a turn\u00ea.<\/strong> Cerca de vinte grupos de jovens e adultos, fam\u00edlias, espalhados pelo Reino Unido. Juntos n\u00f3s sonhamos e organizamos tudo. Eles nos disseram que desejam abrir, mais e melhor, as m\u00e3os e o cora\u00e7\u00e3o, recompor relacionamentos, vencer o \u00f3dio e a desconfian\u00e7a, ir ao encontro das pessoas e comunicar o valor da comunh\u00e3o na diversidade\u00bb.  \u00abFoi preciso coragem, e posso dizer que isso essas pessoas t\u00eam para vender! <strong>Faremos doze apresenta\u00e7\u00f5es, com sete shows \u201c<em>Start Now<\/em>\u201d e cinco concertos ac\u00fasticos<\/strong>, ao lado de v\u00e1rios outros compromissos\u00bb.  Escutando Sally compreende-se que os shows n\u00e3o s\u00e3o nada mais do que a ponta do iceberg da turn\u00ea, se assim podemos dizer, e que a viagem musical do Gen Verde ao Reino Unido pode tocar o \u00e2mago do povo. \u00abVamos nos apresentar em cidades complexas, como <strong>Londres<\/strong>, <strong>Birmingham, Glasgow, Oxford, Liverpool, Portsmouth e Cardiff <\/strong>\u2013 explica Sally \u2013 com um tecido cultural e social que foi definido p\u00f3s-crist\u00e3o, desagregado, mas onde as dimens\u00f5es ecum\u00eanica e inter-religiosa s\u00e3o ainda fortes. Por meio da m\u00fasica, dos textos e coreografias, vamos contar sobre a vida que existe entre n\u00f3s, e em muitas partes do mundo, uma vida feita de comunh\u00e3o, fraternidade, sacrif\u00edcio e reciprocidade. Queremos que emerja o \u201calgo a mais\u201d, que existe, mas que n\u00e3o se mostra, da sociedade brit\u00e2nica, aquela que se desdobra pelos outros, mas que arrisca ficar escondida por detr\u00e1s das manchetes da m\u00eddia, que muitas vezes gritam exclus\u00e3o, defesa, medo\u00bb.  <strong>Em Londres o Gen Verde encontrar\u00e1 tamb\u00e9m os jovens do Centro Isl\u00e2mico<\/strong>, a convite do Im\u00e3 Dr. Mohammad Ali Shomali. Um encontro que n\u00e3o se pode dar por descontado, nesses tempos. \u00abN\u00f3s enfocamos os valores que nos unem, e queremos trabalhar juntos\u00bb.  Pelo entusiasmo que Sally demonstra \u00e9 evidente que os jovens ter\u00e3o um espa\u00e7o privilegiado nessa turn\u00ea. \u00abS\u00e3o o term\u00f4metro da sociedade, frequentemente vivem os seus abismos mais obscuros, e n\u00e3o \u00e9 um mist\u00e9rio que tamb\u00e9m na Gr\u00e3-Bretanha, como em outros pa\u00edses europeus, viol\u00eancia e suic\u00eddios est\u00e3o em forte ascend\u00eancia entre os under-30\u00bb.  No show que ser\u00e1 feito na Gr\u00e3-Bretanha haver\u00e1 m\u00fasicas do novo \u00e1lbum,<strong> \u201c<em>On The Other Side<\/em>\u201d<\/strong>, lan\u00e7ado recentemente. \u00ab\u00c9 dedicado justamente aos jovens e os temas s\u00e3o universais. Trata-se de uma viagem em quatro etapas: come\u00e7a-se com os desafios, os mais profundos, que fazem olhar para dentro; depois chega o questionamento: \u201c\u00e9 poss\u00edvel super\u00e1-los?\u201d, e enfim o convite a sair de si mesmos, para construir o presente e o futuro juntos, e que quisemos chamar \u201c<em>No frontiers<\/em>\u201d, <strong>sem fronteiras, porque juntos podemos fazer a diferen\u00e7a\u00bb.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De 5 de outubro a 5 de dezembro estaremos na Esc\u00f3cia, Pa\u00eds de Gales e Inglaterra. Doze apresenta\u00e7\u00f5es, dezenas de workshops, encontros com pessoas de diferentes igrejas crist\u00e3s e religi\u00f5es. O desafio? Mostrar que a diversidade n\u00e3o \u00e9 uma amea\u00e7a, mas uma riqueza que vale a pena conservar. Conversamos com Sally McAllister, diretora do grupo.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[909,910],"tags":[],"class_list":["post-333888","post","type-post","status-publish","format-standard","hentry","category-focolare-worldwide-2-4","category-senza-categoria-2-4"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/333888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=333888"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/333888\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=333888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=333888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=333888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}