{"id":334008,"date":"2015-11-13T05:00:59","date_gmt":"2015-11-13T04:00:59","guid":{"rendered":"https:\/\/www.focolare.org\/imigracao-um-sinal-de-malta\/"},"modified":"2024-05-16T15:25:51","modified_gmt":"2024-05-16T13:25:51","slug":"imigracao-um-sinal-de-malta","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/pt-pt\/imigracao-um-sinal-de-malta\/","title":{"rendered":"Imigra\u00e7\u00e3o. Um sinal de Malta"},"content":{"rendered":"<p><div id=\"attachment_131123\" style=\"width: 430px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2015\/11\/VallettaSummit.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-131123\" class=\"wp-image-131123\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2015\/11\/VallettaSummit.jpg\" alt=\"VallettaSummit\" width=\"420\" height=\"238\" \/><\/a><p id=\"caption-attachment-131123\" class=\"wp-caption-text\">Cimeira de Valeta sobre migra\u00e7\u00e3o<\/p><\/div>  <strong>Nos dias 11 e 12 de novembro passado, <a href=\"https:\/\/www.focolare.org\/pt\/focolare-worldwide\/europa\/malta\/\" target=\"_blank\" rel=\"noopener\">Malta <\/a>foi a sede do v\u00e9rtice internacional sobre a imigra\u00e7\u00e3o<\/strong>, promovido pelo Conselho Europeu, no qual 28 pa\u00edses da Uni\u00e3o Europ\u00e9ia reuniram-se com 35 pa\u00edses da \u00c1frica e os representantes da ONU. O objetivo, que se pode ler no site do Conselho, era o de \u201ctratar as profundas causas da quest\u00e3o, esfor\u00e7ando-se para contribuir \u00e0 cria\u00e7\u00e3o da paz, da estabilidade e desenvolvimento econ\u00f4mico, da melhoria do trabalho de promo\u00e7\u00e3o e organiza\u00e7\u00e3o dos tramites de migra\u00e7\u00e3o legal, refor\u00e7ar a prote\u00e7\u00e3o dos imigrantes e daqueles que requerem asilo, em especial dos grupos vulner\u00e1veis, fazer oposi\u00e7\u00e3o de modo mais eficaz \u00e0 explora\u00e7\u00e3o, ao tr\u00e1fico de imigrantes, e colaborar mais estreitamente para melhorar a coopera\u00e7\u00e3o no que diz respeito \u00e0 repatria\u00e7\u00e3o e readmiss\u00e3o\u201d  <strong>Nesse \u00ednterim, por\u00e9m, foram os malteses que, posicionando-se frente \u00e0 quest\u00e3o, come\u00e7aram a trabalhar, <\/strong>agindo concretamente tamb\u00e9m no que diz respeito tamb\u00e9m \u00e0 <strong>acolhida aos refugiados<\/strong>. Uma <a href=\"https:\/\/www.focolare.org\/pt\/movimento-dei-focolari\/scelte-e-impegno\/volontari\/\" target=\"_blank\" rel=\"noopener\">volunt\u00e1ria <\/a>do Movimento dos Focolares, Anna Caruana Colombo, relatou \u00e0 reda\u00e7\u00e3o da revista <em>New City<\/em> que, junto a outras amigas, conseguiram envolver 30 pessoas em uma atividade na qual, inicialmente, foram informadas sobre as condi\u00e7\u00f5es e necessidades dos imigrantes \u2013 gra\u00e7as \u00e0 a\u00e7\u00e3o dos Jesu\u00edtas em favor dos refugiados \u2013 e, em um segundo momento, foram visitar os centros \u201cabertos\u201d de acolhida, nos quais encontram alojamento aqueles que j\u00e1 receberam o documento de \u201crefugiado\u201d.  <strong><a href=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2015\/11\/20151113-03.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-131094\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2015\/11\/20151113-03.jpg\" alt=\"20151113-03\" width=\"300\" height=\"200\" \/><\/a>Em um desses centros ministraram cursos de ingl\u00eas<\/strong>, aulas com informa\u00e7\u00f5es pr\u00e1ticas sobre a ilha de Malta e, tamb\u00e9m dedicaram o tempo livre para fazer companhia aos imigrantes. Em outro campo, onde est\u00e3o tamb\u00e9m as fam\u00edlias, elas se ocuparam das crian\u00e7as e procuraram material de primeira necessidade para os mais pequeninos.  <strong>Mais tarde, quando conseguimos obter a devida autoriza\u00e7\u00e3o <\/strong>os volunt\u00e1rios conseguiram entrar tamb\u00e9m nos centros \u201cfechados\u201d, nos conta Anna: \u201cOs refugiados estavam em alguns quartos cheios de beliches, at\u00e9 mesmo 12 beliches em quartos que n\u00e3o comportavam esta quantidade de leitos. Nas primeiras vezes que fomos l\u00e1 eles ficaram assustados, mas, depois, compreenderam que quer\u00edamos somente ser amigos deles e superaram a desconfian\u00e7a. Assim, das aulas de ingl\u00eas passamos tamb\u00e9m \u00e0 partilha de momentos de alegria, com m\u00fasica e dan\u00e7as, a ponto que os guardas do campo admitiram que nunca os tinham visto t\u00e3o felizes\u201d.  <strong>Tamb\u00e9m os <a href=\"https:\/\/www.focolare.org\/pt\/movimento-dei-focolari\/un-popolo\/giovani-per-un-mondo-unito\/\" target=\"_blank\" rel=\"noopener\">jovens do Movimento dos Focolares<\/a> tomaram iniciativas neste campo<\/strong>, convidando os imigrantes a participar das atividades para os adolescentes como, por exemplo, <em>Run4Unity<\/em>, durante a Mari\u00e1polis \u2013 um encontro de v\u00e1rios dias, promovido pelos Focolares \u2013 para os seus amigos e simpatizantes. \u201cO nosso projeto est\u00e1, aos poucos, adquirindo visibilidade \u2013 concluiu Anna \u2013 tanto que fomos convidados pela diocese a compartilhar a nossa experi\u00eancia de vida com outros Movimentos eclesiais\u201d.  &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na pequena ilha do Mediterr\u00e2neo os v\u00e9rtices internacionais discutem, enquanto os malteses arrega\u00e7am as mangas para acolher os imigrantes.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[909,910],"tags":[],"class_list":["post-334008","post","type-post","status-publish","format-standard","hentry","category-focolare-worldwide-2-4","category-senza-categoria-2-4"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/334008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=334008"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/334008\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=334008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=334008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=334008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}