{"id":334668,"date":"2016-07-11T04:00:57","date_gmt":"2016-07-11T02:00:57","guid":{"rendered":"https:\/\/www.focolare.org\/ucraina-a-guerra-esquecida\/"},"modified":"2024-05-16T15:28:22","modified_gmt":"2024-05-16T13:28:22","slug":"ucraina-a-guerra-esquecida","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/pt-pt\/ucraina-a-guerra-esquecida\/","title":{"rendered":"Ucraina: a guerra esquecida"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-140367 size-full\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2016\/07\/kyjev_05_2016-024-e1467896700929.jpg\" alt=\"kyjev_05_2016 024\" width=\"384\" height=\"496\" \/><strong>Desde quando come\u00e7aram as desordens em Kiev, no final de 2013<\/strong>, que desembocaram, em abril de 2014, na revolta da Ucr\u00e2nia Oriental, tudo permanece inalterado. Situa\u00e7\u00f5es que ocupavam as primeiras p\u00e1ginas dos jornais, e das quais a m\u00eddia n\u00e3o fala mais. Mas a viol\u00eancia continua a manter paralisada a popula\u00e7\u00e3o, que vive em condi\u00e7\u00f5es dram\u00e1ticas.  <strong>Na<\/strong> <a href=\"https:\/\/www.focolare.org\/pt\/focolare-worldwide\/europa\/ucraina\/\" target=\"_blank\" rel=\"noopener\">Ucr\u00e2nia<\/a> <strong>existem pequenas comunidades dos<\/strong> <a href=\"https:\/\/www.focolare.org\/pt\/chi-siamo\/\" target=\"_blank\" rel=\"noopener\">Focolares<\/a> <strong>(Mukachevo, Leopoli, Kiev)<\/strong>, que procuram responder ao mal que as circunda. Nos \u00faltimos meses foram feitas v\u00e1rias viagens e a visita de um pequeno grupo dos Focolares da Eslov\u00e1quia \u00e0 capital, Kiev, e a Kharkiv, cidade no nordeste do pa\u00eds. Elena Vladova e Martin Uher compartilham a pr\u00f3pria experi\u00eancia.  <strong>\u00abCom o \u00eaxodo da popula\u00e7\u00e3o em idade laborativa, nas fam\u00edlias ficaram os idosos<\/strong>, \u00e0s vezes um dos genitores, crian\u00e7as de v\u00e1rias idades. Essas crian\u00e7as s\u00e3o \u201c\u00f3rf\u00e3s sociais\u201d, como afirma Sua Beatitude Svjatoslav Sevcuk, arcebispo maior da Igreja Greco-cat\u00f3lica: \u201csabem o que \u00e9 fam\u00edlia s\u00f3 pela internet e no futuro n\u00e3o saber\u00e3o como criar uma fam\u00edlia verdadeira e sadia\u201d\u00bb.  <strong>Entre as entidades que corajosamente procuram realizar iniciativas humanit\u00e1rias est\u00e1 a Igreja Cat\u00f3lica<\/strong>, por meio da C\u00e1ritas e dos Institutos religiosos. Gra\u00e7as aos frequentes apelos do Papa Francisco \u2013 o mais recente no dia <a href=\"http:\/\/w2.vatican.va\/content\/francesco\/pt\/angelus\/2016\/documents\/papa-francesco_regina-coeli_20160403.html\" target=\"_blank\" rel=\"noopener\">\u00a03 de abril <\/a>\u2013 foi poss\u00edvel formar uma rede de ajudas e apoio \u00e0s faixas mais atingidas, amplamente reconhecida, com gratid\u00e3o, inclusive pelas autoridades governamentais. H\u00e1 refeit\u00f3rios para os pobres, centros de reabilita\u00e7\u00e3o, casas de acolhida para adolescentes-m\u00e3es e seus filhos nascidos da viol\u00eancia. Significativa, nesse sentido, a a\u00e7\u00e3o das irm\u00e3s de Dom Orione, que montaram uma casa para cuidar delas.  <strong>Tamb\u00e9m os Focolares procuram demonstrar a sua proximidade aos ucra\u00ednos<\/strong> com quem est\u00e3o em contato, por meio da comunidade da Eslov\u00e1quia. Recentemente um grupo da Eslov\u00e1quia foi at\u00e9 \u00e0 capital, Kiev, para encontrar as fam\u00edlias e outras pessoas. \u00abVisitar os locais onde aconteceu \u201ca revolu\u00e7\u00e3o\u201d, dois anos atr\u00e1s, \u00e9 sempre impressionante. Faz parte da cultura contempor\u00e2nea ucra\u00edna: existem muitos nomes das pessoas mortas durantes os combates na Pra\u00e7a Maydan, ou das que morreram na guerra na Ucr\u00e2nia oriental (que ainda continua). As pessoas t\u00eam orgulho deles\u00bb, escreveram. \u00abMuitas conversas pessoais, muitos sofrimentos, o medo para carregar juntos&#8230; E assim as fam\u00edlias procuram colocar em pr\u00e1tica o convite de S. B. Svjatoslav Sevcuk: \u201cPrecisamos de fam\u00edlias que sejam \u201cm\u00e9dicos\u201d para as nossas fam\u00edlias\u201d\u00bb.  <div id=\"attachment_140370\" style=\"width: 410px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.focolare.org\/news\/2016\/07\/11\/ucraina-guerra-dimenticata\/5b\/\" rel=\"attachment wp-att-140370\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-140370\" class=\"wp-image-140370\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2016\/07\/5B.jpg\" alt=\"Mons. Stanislav Szyrokoradiuk, vescovo di Kharkiv\" width=\"400\" height=\"208\" \/><\/a><p id=\"caption-attachment-140370\" class=\"wp-caption-text\">Elena Vladova e Martin Uher com D. Stanislav Szyrokoradiuk, bispo de Kharkiv<\/p><\/div>  <strong>\u00abDesde o in\u00edcio deste ano, o padre Anton Konecny<\/strong>, <strong>dos Focolares, transferiu-se<\/strong>, a pedido do bispo de Mukachevo (Ucr\u00e2nia), Antal Majnek, da sua diocese, em Kosice (Eslov\u00e1quia Oriental), para uma par\u00f3quia na Ucr\u00e2nia ocidental. A sua presen\u00e7a e o seu servi\u00e7o contribuem para o incremento dos relacionamentos, seja na par\u00f3quia, seja no \u00e2mbito ecum\u00eanico e com as autoridades civis\u00bb.  <strong>Elena e Martin fizeram ainda outra viagem, para chegar \u00e0 Ucr\u00e2nia oriental, at\u00e9 Kharkiv,<\/strong> uma bonita cidade, de dois milh\u00f5es de habitantes, que foi a capital do pa\u00eds antes da revolu\u00e7\u00e3o russa, mas que agora apresenta as marcas da situa\u00e7\u00e3o atual. Depois da visita a D. Stanislav Szyrokoradiuk, amigo dos Focolares e h\u00e1 dois anos bispo da diocese de Kharkiv, que abra\u00e7a todos os territ\u00f3rios onde at\u00e9 hoje h\u00e1 combates, eles deram-se conta \u00abda grande necessidade da popula\u00e7\u00e3o de poder contar com a solidariedade de todos. E da import\u00e2ncia, para os crist\u00e3os ucra\u00ednos, de saberem que, tamb\u00e9m fora de seu pa\u00eds, se reza e se oferece pela paz na Ucr\u00e2nia. Justamente como salientou o cardeal Parolin durante a sua recente visita \u00e0 Ucr\u00e2nia: \u201cDeus n\u00e3o os esqueceu&#8230;!\u201d\u00bb.  Maria Chiara De Lorenzo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abTalvez seja dif\u00edcil admitir, mas na Europa existe a guerra. \u00c9 dif\u00edcil acreditar, mas \u00e9 a realidade, ainda que se fale pouco ou nada dela\u00bb.  O testemunho de Elena Vladova e Martin Uher, respons\u00e1veis do Movimento dos Focolares na Eslov\u00e1quia e Ucr\u00e2nia.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[909],"tags":[],"class_list":["post-334668","post","type-post","status-publish","format-standard","hentry","category-focolare-worldwide-2-4"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/334668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=334668"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/334668\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=334668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=334668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=334668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}