{"id":335530,"date":"2017-06-24T03:00:48","date_gmt":"2017-06-24T01:00:48","guid":{"rendered":"https:\/\/www.focolare.org\/fim-do-ramada\/"},"modified":"2024-05-16T15:31:38","modified_gmt":"2024-05-16T13:31:38","slug":"fim-do-ramada","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/pt-pt\/fim-do-ramada\/","title":{"rendered":"Fim do Ramad\u00e3"},"content":{"rendered":"<p><span style=\"text-decoration: underline\"><strong>Termina hoje, 24 de junho, o jejum feito durante o Ramad\u00e3,<\/strong><\/span> per\u00edodo de 29 ou 30 dias durante o qual os fi\u00e9is mu\u00e7ulmanos recordam <em>\u201co m\u00eas em que foi revelado o Alcor\u00e3o, como orienta\u00e7\u00e3o para a humanidade e como evid\u00eancias da orienta\u00e7\u00e3o e do crit\u00e9rio de julgar\u201d<\/em> (Alcor\u00e3o, Sura II, 185).  Durante este per\u00edodo, o jejum observado do amanhecer ao p\u00f4r-do-sol constitui um dos cinco pilares do islamismo. O significado espiritual do jejum, unido \u00e0 ora\u00e7\u00e3o e \u00e0 medita\u00e7\u00e3o, da abstin\u00eancia sexual e de v\u00e1rias outras ren\u00fancias, segundo muitos te\u00f3logos, se refere \u00e0 capacidade do homem de autodisciplinar-se, de exercitar a paci\u00eancia e a humildade e de recordar o aux\u00edlio aos mais necessitados e \u00e0queles que se encontram em situa\u00e7\u00e3o dif\u00edcil. O Ramad\u00e3, portanto, \u00e9 uma maneira de exercitar a pureza contra todas as paix\u00f5es mundanas, cujos benef\u00edcios acompanham o fiel durante o ano inteiro.  &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Termina hoje, 24 de junho, o jejum feito durante o Ramad\u00e3, per\u00edodo de 29 ou 30 dias durante o qual os fi\u00e9is mu\u00e7ulmanos recordam \u201co m\u00eas em que foi revelado o Alcor\u00e3o, como orienta\u00e7\u00e3o para a humanidade e como evid\u00eancias da orienta\u00e7\u00e3o e do crit\u00e9rio de julgar\u201d (Alcor\u00e3o, Sura II, 185). Durante este per\u00edodo, o [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[129],"tags":[],"class_list":["post-335530","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/335530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=335530"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/335530\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=335530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=335530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=335530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}