{"id":335624,"date":"2017-08-09T00:10:47","date_gmt":"2017-08-08T22:10:47","guid":{"rendered":"https:\/\/www.focolare.org\/quem-sao-os-voluntarios-de-deus\/"},"modified":"2024-05-16T15:32:03","modified_gmt":"2024-05-16T13:32:03","slug":"quem-sao-os-voluntarios-de-deus","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/pt-pt\/quem-sao-os-voluntarios-de-deus\/","title":{"rendered":"Quem s\u00e3o os volunt\u00e1rios de Deus?"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-154515\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2017\/08\/Gennaro-e-Lucia-Piccolo.jpg\" alt=\"Gennaro e Lucia Piccolo\" width=\"316\" height=\"287\" \/>Quando jovem, \u00e0 noite eu gostava de ouvir a R\u00e1dio Vaticana, que transmitia notici\u00e1rios em v\u00e1rias l\u00ednguas estrangeiras.<\/strong> Naturalmente eu n\u00e3o sabia nenhuma daquelas l\u00ednguas, mas aquela escuta me fascinava, dava-me a impress\u00e3o de dilatar o cora\u00e7\u00e3o sobre a humanidade, sobre os povos e o seu dia a dia. At\u00e9 que, numa daquelas noites, me aconteceu escutar o<strong> Papa Pio XII invocar o nome de Deus por tr\u00eas vezes: \u201cDeus, Deus, Deus!\u201d<\/strong>. Aquele \u201cgrito\u201d ficou gravado na minha consci\u00eancia, ainda que, com o passar do tempo, terminou por esmorecer e perder-se na mem\u00f3ria. <strong>Era o ano de 1956.<\/strong>  <strong>Nove anos depois, em janeiro de 1963, eu estava prestando o servi\u00e7o militar em Turim.<\/strong> Um companheiro de turma me convidou para um congresso sobre o qual, estranhamente, eu n\u00e3o pedi nenhuma informa\u00e7\u00e3o. Ainda assim, ao pedir a licen\u00e7a aos meus superiores, me surpreendi afirmando que daquele congresso dependia toda a minha vida. Com a inesperada concess\u00e3o dos superiores, viajei para <strong>Ala di Stura, um lugarejo de montanha<\/strong>, cercado por uma natureza maravilhosa.  Recebido como se antes j\u00e1 me conhecessem, foi l\u00e1 que conheci <a href=\"https:\/\/www.focolare.org\/pt\/chiara-lubich\/chi-e-chiara\/\" target=\"_blank\" rel=\"noopener\">Chiara Lubich<\/a> \u2013 fundadora do Movimento dos Focolares -, e<a href=\"https:\/\/www.focolare.org\/pt\/chiara-lubich\/chi-e-chiara\/igino-giordani\/\" target=\"_blank\" rel=\"noopener\"> Igino Giordani<\/a>, cofundador. Algo forte para mim foi deparar-me, pela primeira vez, com pessoas de culturas e religi\u00f5es diferentes. Naqueles dias conheci <strong>Assunta Roncalli<\/strong> que tamb\u00e9m era h\u00f3spede dos Focolares. Ela era irm\u00e3 do Papa Jo\u00e3o XXIII, que viria a falecer naquele mesmo ano, no dia 3 de junho de 1963.  <strong>Uma manh\u00e3 Chiara falou de uma nova voca\u00e7\u00e3o que havia surgido dentro do Movimento.<\/strong> E foi quando ela narrou o ano e as circunst\u00e2ncias em que tudo havia iniciado que aquela invoca\u00e7\u00e3o de Pio XII ressurgiu com for\u00e7a da minha consci\u00eancia: \u00abDeus, Deus, Deus! Deus vos ajudar\u00e1, Deus ser\u00e1 a vossa for\u00e7a. Ecoe este nome inef\u00e1vel, fonte de todo direito, justi\u00e7a e liberdade, nos parlamentos, nas pra\u00e7as, nas casas e nas oficinas&#8230;\u00bb. Assim o Papa se exprimiu em uma mensagem na r\u00e1dio, dia 10 de novembro de 1956, durante a repress\u00e3o da revolu\u00e7\u00e3o na Hungria. E Chiara comentou: \u00abHouve, portanto, uma sociedade capaz de apagar o nome de Deus, a realidade de Deus, a Provid\u00eancia de Deus, o amor de Deus dos cora\u00e7\u00f5es dos homens. Deve haver uma sociedade capaz de recoloc\u00e1-lo em seu lugar. \u00c9 poss\u00edvel que o dem\u00f4nio tenha os seus seguidores fieis, totalit\u00e1rios, pseudo-m\u00e1rtires da sua ideia, e Deus n\u00e3o tenha um ex\u00e9rcito compacto de crist\u00e3os que deem tudo para reconquistar para Ele a terra?\u00bb Chiara respondeu \u00e0quele apelo do Papa com a intui\u00e7\u00e3o de reunir homens e mulheres, de todas as idades, nacionalidades, condi\u00e7\u00f5es, ligados por um \u00fanico v\u00ednculo, o da fraternidade universal, para que formassem um ex\u00e9rcito de volunt\u00e1rios, os <a href=\"https:\/\/www.focolare.org\/pt\/movimento-dei-focolari\/scelte-e-impegno\/volontari\/\" target=\"_blank\" rel=\"noopener\">\u201cVolunt\u00e1rios de Deus\u201d<\/a>, express\u00e3o do Movimento dos Focolares, hoje presentes em 182 na\u00e7\u00f5es do mundo.  <strong>Uma voca\u00e7\u00e3o moderna, totalit\u00e1ria, \u00e0 qual Chiara Lubich d\u00e1 mais um toque fascinante quando a descreve como a atra\u00e7\u00e3o dos tempos modernos<\/strong>: \u00abPenetrar na mais alta contempla\u00e7\u00e3o e permanecer misturados com todos, ombro a ombro&#8230; para tra\u00e7ar sobre a multid\u00e3o desenhos de luz e, ao mesmo tempo, dividir com o pr\u00f3ximo a vergonha, a fome, os ultrajes, as alegrias fugazes\u00bb. Igino Giordani a compara a uma \u00absantidade com o macac\u00e3o de oper\u00e1rio, que leva Deus aos parlamentos, \u00e0s assembleias legislativas, aos hospitais, escolas, escrit\u00f3rios, bares, em casa, nos campos de jogo, mas tamb\u00e9m no mundo da arte, da comunica\u00e7\u00e3o, da ci\u00eancia, da economia&#8230;\u00bb. Porque, ele acrescenta, \u00ablevar Deus a todos estes lugares significa transform\u00e1-los em abadias, transform\u00e1-los em lugares sagrados, aonde, todos os dias, \u00e9 celebrada uma Missa especial!\u00bb.  Passaram-se 54 anos daquele dia em que escutei o chamado a me alistar com os \u201cVolunt\u00e1rios de Deus\u201d, nascidos de um carisma que, porque aut\u00eantico, revela-se tamb\u00e9m em suas implica\u00e7\u00f5es concretas, com reflexos na cultura, na esfera social, na economia, na pol\u00edtica&#8230; a fim de que os v\u00e1rios \u00e2mbitos da vida n\u00e3o restem med\u00edocres, carentes de coragem, incapazes de unir, insens\u00edveis, mas abertos a acolher a presen\u00e7a profunda de Deus.  Gennaro Piccolo \u2013 <a href=\"http:\/\/www.iginogiordani.info\/it\/associazioni-igino-giordani\/andria.html\" target=\"_blank\" rel=\"noopener\">Centro Igino Giordani \u201cUma via per l\u2019Unit\u00e0\u201d<\/a> (Andria, It\u00e1lia)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma express\u00e3o dos Focolares no campo social descrita pela experi\u00eancia de Gennaro Piccolo, um daqueles que, com tantos outros homens e mulheres, decidiram fazer parte dela.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[909],"tags":[],"class_list":["post-335624","post","type-post","status-publish","format-standard","hentry","category-focolare-worldwide-2-4"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/335624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=335624"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/335624\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=335624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=335624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=335624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}