{"id":344800,"date":"2012-04-16T14:18:17","date_gmt":"2012-04-16T12:18:17","guid":{"rendered":"https:\/\/www.focolare.org\/parabens-santo-padre\/"},"modified":"2024-06-06T12:18:06","modified_gmt":"2024-06-06T10:18:06","slug":"parabens-santo-padre","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/pt-pt\/parabens-santo-padre\/","title":{"rendered":"Parab\u00e9ns Santo Padre!"},"content":{"rendered":"<table style=\"width: 636px;height: 319px\" border=\"0\" cellpadding=\"5\">\n<tbody>\n<tr valign=\"top\">\n<td>Chegam do mundo inteiro duplas congratula\u00e7\u00f5es ao Papa Bento XVI. Tamb\u00e9m no Movimento dos Focolares unimo-nos \u00e0s ora\u00e7\u00f5es \u2013 como pedido pelo Santo Padre \u2013 para que o Senhor conceda-lhe a for\u00e7a de cumprir a miss\u00e3o a ele confiada.  Da Argentina, onde encontra-se nestes dias em visita \u00e0s comunidades dos Focolares, a presidente Maria Voce exprime ao Santo Padre os mais calorosos aug\u00farios em nome de todo o Movimento, com os ausp\u00edcios de que a presen\u00e7a do Senhor Ressuscitado, sempre mais resplandecente na Sua Igreja, possa preench\u00ea-lo de luz e for\u00e7a.  Cheguem \u00e0 Sua Santidade os nossos votos, com afetuoso reconhecimento pelo seu testemunho corajoso, o seu magist\u00e9rio iluminado, e pelo grande sustento dado sempre a todos os movimentos, nos quais entrev\u00ea <em>\u201ca for\u00e7a do Esp\u00edrito Santo que doa novos caminhos e, de maneiras imprevistas, continua a rejuvenescer a Igreja\u201d<\/em>. S\u00e3o as palavras dirigidas em mar\u00e7o de 2012 por Bento XVI ao cardeal Cordes, autor do livro \u201c<strong>Bento XVI inspira os novos movimentos e as realidades eclesiais<\/strong>\u201d, publicado recentemente pela Livraria Editora Vaticana, e dedicado \u2013 ente outros \u2013 tamb\u00e9m a Chiara Lubich.<\/td>\n<td><img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-61382\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2012\/04\/PapaBenedettoXVI.jpg\" alt=\"\" width=\"307\" height=\"283\" \/><\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Para dirigir os pr\u00f3prios votos diretamente ao Santo Padre foi ativado o endere\u00e7o postal eletr\u00f4nico <a href=\"mailto:auguri.benedettoxvi@vatican.va\">auguri.benedettoxvi@vatican.va<\/a> acess\u00edvel tamb\u00e9m no portal da Santa S\u00e9, <a href=\"http:\/\/www.vatican.va\/\">WWW.vatican.va<\/a>.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>No 85\u00b0 anivers\u00e1rio de Bento XVI, e na proximidade do 7\u00b0 anivers\u00e1rio de sua elei\u00e7\u00e3o ao pontificado, apresentamos, em nome de todo o Movimento dos Focolares, os mais sinceros votos.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[129],"tags":[],"class_list":["post-344800","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/344800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=344800"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/344800\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=344800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=344800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=344800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}