{"id":345378,"date":"2012-12-01T05:00:52","date_gmt":"2012-12-01T04:00:52","guid":{"rendered":"https:\/\/www.focolare.org\/camaroes-honestidade-versus-corrupcao\/"},"modified":"2024-06-06T12:19:55","modified_gmt":"2024-06-06T10:19:55","slug":"camaroes-honestidade-versus-corrupcao","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/pt-pt\/camaroes-honestidade-versus-corrupcao\/","title":{"rendered":"Camar\u00f5es: honestidade versus corrup\u00e7\u00e3o"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-75223\" style=\"margin-right: 10px;border: 0px none\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2012\/12\/20121201-b.jpg\" alt=\"\" width=\"210\" height=\"136\" \/>\u00abTrabalho na administra\u00e7\u00e3o da Alf\u00e2ndega<\/strong> e estou quase no fim da minha carreira. Um longo caminho de 29 anos! Feito de alegrias e sofrimentos, mas principalmente de escolhas muitas vezes dif\u00edceis.<\/p>\n<p><strong>Desde os meus primeiros anos de trabalho<\/strong>, como mulher e ainda mais como crist\u00e3, <strong>tive problemas de consci\u00eancia<\/strong>: como escutar a voz de Deus e segui-la num ambiente com lucros f\u00e1ceis e compromissos \u00e0s vezes inevit\u00e1veis? Tive a resposta em 1984, \u00e9poca em que conheci o <a href=\"https:\/\/www.focolare.org\/pt\/movimento-dei-focolari\/\"><strong>Movimento dos Focolares<\/strong><\/a> e fiquei tocada pela vida destas pessoas simples e felizes. Eles tinham uma alegria, uma liberdade, que eu n\u00e3o sentia. Quis saber mais. <strong>O segredo era o amor a Deus e aos outros.<\/strong><\/p>\n<p><strong>Este encontro transformou a minha vida.<\/strong> Tomava consci\u00eancia que o mais importante na vida \u00e9 amar. N\u00e3o importa a profiss\u00e3o que a pessoa tem, o cargo que assumimos \u00e9 sempre uma grande ocasi\u00e3o para amar Deus e os irm\u00e3os. Isso mudava tudo! Os colegas, os clientes, n\u00e3o eram mais um obst\u00e1culo, uma barreira, mas tornavam-se parceiros com quem construir a unidade.<\/p>\n<p><strong>O constante esfor\u00e7o<\/strong> de ultrapassar os meus limites e os dos outros, <strong>para ir contracorrente<\/strong>, sempre foi acompanhado pela alegria que se experimenta ap\u00f3s cada servi\u00e7o cumprido; por um sentimento de liberdade, cada vez que fui capaz de renunciar aos meus interesses e aos ganhos f\u00e1ceis.<\/p>\n<p>Em 1999 recebi o <strong>pr\u00eamio de excel\u00eancia da Associa\u00e7\u00e3o das Mulheres Dirigentes da Alf\u00e2ndega Camaronesa<\/strong>, em colabora\u00e7\u00e3o com os usu\u00e1rios do servi\u00e7o. A Palavra de Vida daquele m\u00eas dizia: \u201c<em>Que a vossa luz resplande\u00e7a diante dos homens, para que vejam a vossas boas obras e glorifiquem o Pai que est\u00e1 nos c\u00e9us\u201d<\/em> (Mt 5,14-16).<\/p>\n<p><strong>Esse reconhecimento fez com que eu me sentisse interpelada pessoalmente<\/strong>: \u201cFique firme, n\u00e3o ceda \u00e0s d\u00favidas e \u00e0 falta de coragem, melhore a cada dia!\u201d.<\/p>\n<p>No final da minha carreira percebo que nenhuma profiss\u00e3o \u00e9 a antic\u00e2mera do inferno! Que a nossa fun\u00e7\u00e3o espec\u00edfica, como crist\u00e3os na sociedade, \u00e9 fazer tudo com um novo esp\u00edrito, com total ades\u00e3o \u00e0 vontade de Deus. Ele sempre nos acompanha com a Sua gra\u00e7a\u00bb.<\/p>\n<p>Jeanne \u2013 Rep\u00fablica dos Camar\u00f5es<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9 poss\u00edvel fazer honestamente o pr\u00f3prio trabalho em ambientes onde prevalece a corrup\u00e7\u00e3o? Onde encontrar a for\u00e7a? Jeanne, da Rep\u00fablica dos Camar\u00f5es, conta a sua experi\u00eancia.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[909],"tags":[],"class_list":["post-345378","post","type-post","status-publish","format-standard","hentry","category-focolare-worldwide-2-4"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/345378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=345378"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/345378\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=345378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=345378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=345378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}