{"id":345518,"date":"2013-02-01T05:44:16","date_gmt":"2013-02-01T04:44:16","guid":{"rendered":"https:\/\/www.focolare.org\/brasil-fraternidade-direito-e-transformacao-social\/"},"modified":"2024-06-06T12:20:22","modified_gmt":"2024-06-06T10:20:22","slug":"brasil-fraternidade-direito-e-transformacao-social","status":"publish","type":"post","link":"https:\/\/www.focolare.org\/pt-pt\/brasil-fraternidade-direito-e-transformacao-social\/","title":{"rendered":"Brasil. Fraternidade, direito e transforma\u00e7\u00e3o social"},"content":{"rendered":"<p><strong><img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-79077\" style=\"margin-left: 10px;margin-right: 10px\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2013\/02\/2013-01.27-Congresso-Diritto_Brasile_2.jpg\" alt=\"\" width=\"320\" height=\"214\" \/>Novas perspectivas para o <a href=\"https:\/\/www.focolare.org\/pt\/in-dialogo\/cultura\/diritto\/\" target=\"_blank\" rel=\"noopener\">pensamento jur\u00eddico<\/a> e pistas concretas de aplica\u00e7\u00e3o j\u00e1 experimentadas<\/strong>: foi o que ofereceram os tr\u00eas dias de Congresso, de 25 a 27 de janeiro, na Mari\u00e1polis Ginetta (Vargem Grande Paulista, S\u00e3o Paulo), que reuniu 180 advogados, ju\u00edzes, promotores p\u00fablicos, defensores p\u00fablicos, oficiais de justi\u00e7a, agentes da administra\u00e7\u00e3o p\u00fablica e professores, provenientes de todo o <a href=\"https:\/\/www.focolare.org\/pt\/focolare-worldwide\/america-sud\/brasile\/\" target=\"_blank\" rel=\"noopener\">Brasil<\/a>.<\/p>\n<p><strong>Os numerosos depoimentos<\/strong> valorizaram e confirmaram os efeitos da fraternidade e o seu potencial. O projeto de <strong>\u201cado\u00e7\u00e3o do cidad\u00e3o detento\u201d<\/strong>, realizado em Pernambuco no \u00e2mbito do direito penal, com o qual professores e estudantes sustentam as despesas legais para os presos que n\u00e3o podem pagar os advogados; o projeto para a aplica\u00e7\u00e3o de <strong>penas alternativas para crimes ambientais<\/strong> na Amaz\u00f4nia, por meio de trabalhos em favor do ambiente; o trabalho do n\u00facleo de pesquisa de \u201cDireito e Fraternidade\u201d do Centro de Ci\u00eancias Jur\u00eddicas da Universidade Federal de Santa Catarina, para a<strong> forma\u00e7\u00e3o de agentes do direito<\/strong>; a promo\u00e7\u00e3o da solu\u00e7\u00e3o pac\u00edfica de conflitos por meio do di\u00e1logo e da concilia\u00e7\u00e3o. Foram tocados ainda o tema da media\u00e7\u00e3o familiar e da aplica\u00e7\u00e3o da jurisprud\u00eancia \u00e0 prote\u00e7\u00e3o do mais fraco.<\/p>\n<p><strong><img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-79086\" style=\"margin-left: 10px;margin-right: 10px\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2013\/02\/gehilda-mensagem-Emmaus.jpg\" alt=\"\" width=\"149\" height=\"224\" \/>Durante o Congresso um amplo espa\u00e7o foi dado aos numerosos estudantes<\/strong>, que puderam exprimir preocupa\u00e7\u00f5es, quest\u00f5es e descobertas, narrar experi\u00eancias e, principalmente, manifestar as pr\u00f3prias expectativas por uma forma\u00e7\u00e3o humana e jur\u00eddica que possua horizontes de fraternidade. Na abertura, uma<a href=\"http:\/\/www.comunionediritto.org\/it\/downloads-pdf\/doc_download\/151-messaggio-di-maria-voce.html\" target=\"_blank\" rel=\"noopener\"> mensagem de Maria Voce<\/a>, presidente do Movimento dos Focolares, advogada e uma das iniciadoras de \u201c<a href=\"http:\/\/www.comunionediritto.org\" target=\"_blank\" rel=\"noopener\">Comunh\u00e3o e Direito<\/a>\u201d, grupo que exprime o di\u00e1logo dos Focolares com a cultura jur\u00eddica. Ap\u00f3s ter recordado que <em>\u00abno amor para com o outro toda lei \u00e9 respeitada, \u00e9 interpretada e aplicada segundo justi\u00e7a\u00bb<\/em>, Maria Voce prop\u00f4s \u2013 ap\u00f3s dec\u00eanios nos quais salientou-se a tutela dos direitos individuais como \u00abcaminho para a igualdade\u00bb &#8211; uma reavalia\u00e7\u00e3o dos deveres, <em>\u00abos quais, se n\u00e3o s\u00e3o respeitados, n\u00e3o existem relacionamentos justos. Os deveres nos chamam \u00e0 responsabilidade para com o outro como indiv\u00edduos e como comunidade, contribuindo assim para a manuten\u00e7\u00e3o e consolida\u00e7\u00e3o dos v\u00ednculos na sociedade\u00bb<\/em>.<\/p>\n<p>Nesta fase de mudan\u00e7as e crise, os trabalhos do Congresso demonstraram que <strong>a fraternidade, assumida como categoria jur\u00eddica<\/strong>, \u00e9 como uma lente que faz ver a atuar a \u201cnovidade\u201d. \u201cFraternidade\u201d significa \u201cinvers\u00e3o de tend\u00eancia\u201d: recorda \u00e0 justi\u00e7a o rosto de cada pessoa, leva a sair de um direito subjetivo individual, abrindo-o \u00e0 vis\u00e3o da humanidade como um \u201cn\u00f3s\u201d. Faz do direito n\u00e3o uma mera produ\u00e7\u00e3o de normas, mas <strong>um instrumento para sanar rela\u00e7\u00f5es rompidas<\/strong>. Uma proposta \u00abde grande interesse, de enorme import\u00e2ncia social, crucial para a sociedade, para a cultura e a civiliza\u00e7\u00e3o\u00bb, como afirmou o <strong>cardeal Odilo Scherer<\/strong>, arcebispo de S\u00e3o Paulo, que participou da tarde do dia 26. \u00abFoi descoberta uma mina de ouro \u2013 disse ainda o cardeal \u2013 \u00e9 preciso continuar a escavar para oferecer esse ouro a todos\u00bb<img alt=\"\" alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-79079\" style=\"margin-left: 10px;margin-right: 10px\" src=\"https:\/\/www.focolare.org\/wp-content\/uploads\/2013\/02\/2013-01.27-Congresso-Diritto_Brasile_4.jpg\" alt=\"\" width=\"360\" height=\"240\" \/>.<\/p>\n<p>Retornou-se \u00e0s cidades de proveni\u00eancia com a miss\u00e3o de multiplicar a experi\u00eancia vivida, e os compromissos assumidos o demonstram: est\u00e3o previstos pr\u00f3ximos congressos na Universidade de Santa Catarina e de Mar\u00edlia (SP), no Tribunal de Bras\u00edlia e de Sergipe, nas cidades de Curitiba, Belo Horizonte e Manaus, al\u00e9m da forma\u00e7\u00e3o de grupos para encontros peri\u00f3dicos, a fim de aprofundar os temas e realizar o interc\u00e2mbio de estudos e pr\u00e1ticas.<\/p>\n<p>Para saber mais: <a href=\"http:\/\/www.direitoefraternidade.blogspot.com.br\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.direitoefraternidade.blogspot.com.br\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concluiu-se o 2\u00ba congresso nacional de Comunh\u00e3o e Direito, rede de operadores no campo jur\u00eddico: penas alternativas contra crimes ambientais, \u2018ado\u00e7\u00e3o\u2019 do cidad\u00e3o detido sem defensoria p\u00fablica, foram alguns dos projetos apresentados.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[909],"tags":[],"class_list":["post-345518","post","type-post","status-publish","format-standard","hentry","category-focolare-worldwide-2-4"],"_links":{"self":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/345518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=345518"}],"version-history":[{"count":0,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/posts\/345518\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=345518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=345518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.focolare.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=345518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}